{"id":186580,"date":"2016-08-18T09:00:58","date_gmt":"2016-08-18T09:00:58","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/"},"modified":"2016-08-18T09:00:58","modified_gmt":"2016-08-18T09:00:58","slug":"wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/","title":{"rendered":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Der Blogging-Bereich ist viel \u00fcberf\u00fcllter als noch vor acht Jahren, als Bluehost-Kunde Joshua Becker <\/span><a href=\"http:\/\/www.becomingminimalist.com\"><span style=\"font-weight: 400;\">mit BecomingMinimalist.com<\/span><\/a><span style=\"font-weight: 400;\">. Aber einige Prinzipien f\u00fcr den Erfolg haben sich nicht ge\u00e4ndert. Am wichtigsten ist, dass die Ver\u00f6ffentlichung hochwertiger Inhalte nicht gut genug ist \u2013 Sie m\u00fcssen auch eine florierende Community aufbauen. Hier gibt Becker f\u00fcnf Erkenntnisse zum Community-Building:  <\/span><\/p>\n<h4>1. Verbreiten Sie Ihre Botschaft.<\/h4>\n<p><span style=\"font-weight: 400;\">&#8222;Wenn du deinen Lebensunterhalt durch Bloggen oder Schreiben bestreiten willst, brauchst du eine Community von Leuten, die bereit sind, dich zu unterst\u00fctzen und deine Sachen zu kaufen&#8220;, sagt Becker. &#8222;Man kann nur mit einer bestimmten Anzahl von Menschen an einem Tag sprechen, aber wenn es 1.000 Leute gibt, die auch ihren Freunden von dir erz\u00e4hlen, dann w\u00e4chst man viel schneller.&#8220; <\/span><\/p>\n<h4>2. Bewirken Sie einen echten Eindruck.<\/h4>\n<p><span style=\"font-weight: 400;\">&#8222;Ich denke, die beste Gelegenheit, etwas zu bewirken oder das Leben zu ver\u00e4ndern, findet in der Gemeinschaft statt, wo dir jemand vertraut und offen f\u00fcr deine Gedanken zu einem Thema ist&#8220;, sagt Becker.<\/span><\/p>\n<h4>3. Gehen Sie \u00fcber das Bloggen hinaus.<\/h4>\n<p><span style=\"font-weight: 400;\">Das Bloggen half Becker, seine Ideen und seine Schreibstimme zu verfeinern, w\u00e4hrend er an mehreren B\u00fcchern arbeitete, und schuf ein Publikum, das begierig darauf war, mehr zu erfahren. Es f\u00fchrte auch direkt zur Ver\u00f6ffentlichung seines neuesten Bestsellers, <\/span><a href=\"https:\/\/www.amazon.com\/More-Less-Finding-Under-Everything\/dp\/1601427964\/ref=sr_1_1?ie=UTF8&amp;qid=1468890475&amp;sr=8-1&amp;keywords=the+more+of+less+joshua+becker\"> <i><span style=\"font-weight: 400;\">Das Mehr von Weniger<\/span><\/i><\/a><span style=\"font-weight: 400;\">. Er konnte sich mit einem Agenten in Verbindung setzen und neun Angebote f\u00fcr das Buch an Land ziehen, alles wegen seiner Blog-Community.  <\/span><\/p>\n<h4>4. Dienen Sie den Lesern.<\/h4>\n<p><span style=\"font-weight: 400;\">&#8222;Die erfolgreichsten Blogger sind diejenigen, die sehr leserorientiert sind und versuchen, den Menschen mit dem zu helfen, was sie schreiben&#8220;, sagt Becker.<\/span> <span style=\"font-weight: 400;\">Obwohl eine Community zum eigenen Erfolg beitr\u00e4gt, betont Becker die Bedeutung einer serviceorientierten Denkweise: &#8222;Wenn du nur versuchst, Leute zu benutzen, um Geld zu verdienen, merken die Leute das und vertrauen dir nicht und wollen nicht Teil dessen sein, was du aufbaust. Aber wenn du konsequent beweist, dass du dich mehr um die anderen Menschen k\u00fcmmerst als um dich selbst, f\u00fchlen sich die Leute davon angezogen.&#8220;<\/span><\/p>\n<h4>5. Mach es einfach.<\/h4>\n<p><span style=\"font-weight: 400;\">Wenn Sie sich nicht sicher sind, ob Sie bloggen sollen oder nicht, schl\u00e4gt Becker vor, es einfach auszuprobieren. &#8222;Ich bin froh, dass ich gerade erst angefangen habe&#8220;, sagt er. &#8222;Ich hatte nicht das Gef\u00fchl, dass ich alle meine Fragen beantwortet bekommen musste, aber ich habe auf dem Weg dorthin Antworten gefunden.&#8220;  <\/span><br \/>\n<span style=\"font-weight: 400;\">Lesen Sie hier mehr \u00fcber <a href=\"https:\/\/www.bluehost.com\/de-de\/blog\/customer-spotlight-lernen-sie-joshua-becker-von-becoming-minimalist-kennen\/\">Beckers Weg vom Vorstadtvater zum Experten f\u00fcr alles, was minimalistisch ist<\/a> .<\/span><br \/>\n<i>Holly Munson ist eine freiberufliche Autorin, Redakteurin und Content-Strategin mit Sitz in Philadelphia. Sie berichtet seit sieben Jahren \u00fcber Wirtschaftstrends und hat auch im Marketing, in Zeitschriften und Museen gearbeitet. <\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Blogging-Bereich ist viel \u00fcberf\u00fcllter als noch vor acht Jahren, als Bluehost-Kunde Joshua Becker mit BecomingMinimalist.com. Aber einige Prinzipien f\u00fcr den Erfolg haben sich nicht ge\u00e4ndert. Am wichtigsten ist, dass die Ver\u00f6ffentlichung hochwertiger Inhalte nicht gut genug ist \u2013 Sie m\u00fcssen auch eine florierende Community aufbauen. Hier gibt Becker f\u00fcnf Erkenntnisse zum Community-Building: 1. Verbreiten [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":186582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)","_yoast_wpseo_metadesc":"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).","inline_featured_image":false,"footnotes":""},"categories":[3142,3143],"tags":[3618,3624,3639,3628],"ppma_author":[615],"class_list":["post-186580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kundengeschichten","category-kundenmeinungen","tag-branding-de","tag-inhalt","tag-kleines-unternehmen","tag-schopfer-und-beeinflusser"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)<\/title>\n<meta name=\"description\" content=\"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/posts\/186580\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)\" \/>\n<meta property=\"og:description\" content=\"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-18T09:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Holly Munson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bluehost\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Holly Munson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\"},\"author\":{\"name\":\"Holly Munson\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/0c113399ab81614fc08afda260b6a9d6\"},\"headline\":\"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)\",\"datePublished\":\"2016-08-18T09:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg\",\"keywords\":[\"Branding\",\"Inhalt\",\"Kleines Unternehmen\",\"Sch\u00f6pfer und Beeinflusser\"],\"articleSection\":[\"Kundengeschichten\",\"Kundenmeinungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\",\"name\":\"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg\",\"datePublished\":\"2016-08-18T09:00:58+00:00\",\"description\":\"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/de-de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kunden im Rampenlicht\",\"item\":\"https:\/\/www.bluehost.com\/blog\/de\/category\/kunden-im-rampenlicht\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/de\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/0c113399ab81614fc08afda260b6a9d6\",\"name\":\"Holly Munson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/image\/4a6ebb97f7c68eeba808072a5c58bbfc\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0be30032eb110cdf559c7f296b51626615a66cf9b8b511134ca03cae4b61b706?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0be30032eb110cdf559c7f296b51626615a66cf9b8b511134ca03cae4b61b706?s=96&d=mm&r=g\",\"caption\":\"Holly Munson\"},\"url\":\"https:\/\/www.bluehost.com\/blog\/de\/author\/holly\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)","description":"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/posts\/186580\/","og_locale":"de_DE","og_type":"article","og_title":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)","og_description":"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).","og_url":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2016-08-18T09:00:58+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg","type":"image\/jpeg"}],"author":"Holly Munson","twitter_card":"summary_large_image","twitter_creator":"@bluehost","twitter_site":"@bluehost","twitter_misc":{"Verfasst von":"Holly Munson","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/"},"author":{"name":"Holly Munson","@id":"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/0c113399ab81614fc08afda260b6a9d6"},"headline":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)","datePublished":"2016-08-18T09:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/"},"wordCount":450,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg","keywords":["Branding","Inhalt","Kleines Unternehmen","Sch\u00f6pfer und Beeinflusser"],"articleSection":["Kundengeschichten","Kundenmeinungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/","url":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/","name":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg","datePublished":"2016-08-18T09:00:58+00:00","description":"Der Bluehost-Blog erkl\u00e4rt, wie dieser Bluehost-Kunde eine florierende Blog-Community aufgebaut (und einen Buchvertrag an Land gezogen hat).","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2016\/08\/Josh-Becker-feature-2-1.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/de\/wie-dieser-bluehost-kunde-eine-florierende-blog-community-aufbaute-und-einen-buchvertrag-an-land-zog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/de-de\/blog\/"},{"@type":"ListItem","position":2,"name":"Kunden im Rampenlicht","item":"https:\/\/www.bluehost.com\/blog\/de\/category\/kunden-im-rampenlicht\/"},{"@type":"ListItem","position":3,"name":"Wie dieser Bluehost-Kunde eine florierende Blog-Community aufbaute (und einen Buchvertrag an Land zog)"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/de\/#website","url":"https:\/\/www.bluehost.com\/blog\/de\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/de\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/0c113399ab81614fc08afda260b6a9d6","name":"Holly Munson","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bluehost.com\/blog\/de\/#\/schema\/person\/image\/4a6ebb97f7c68eeba808072a5c58bbfc","url":"https:\/\/secure.gravatar.com\/avatar\/0be30032eb110cdf559c7f296b51626615a66cf9b8b511134ca03cae4b61b706?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0be30032eb110cdf559c7f296b51626615a66cf9b8b511134ca03cae4b61b706?s=96&d=mm&r=g","caption":"Holly Munson"},"url":"https:\/\/www.bluehost.com\/blog\/de\/author\/holly\/"}]}},"authors":[{"term_id":615,"user_id":19,"is_guest":0,"slug":"holly","display_name":"Holly Munson","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/0be30032eb110cdf559c7f296b51626615a66cf9b8b511134ca03cae4b61b706?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/posts\/186580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=186580"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/posts\/186580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/media\/186582"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=186580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=186580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=186580"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/de\/wp-json\/wp\/v2\/ppma_author?post=186580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}