{"id":117639,"date":"2024-11-20T06:20:52","date_gmt":"2024-11-20T06:20:52","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/"},"modified":"2025-04-29T12:37:16","modified_gmt":"2025-04-29T12:37:16","slug":"actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/","title":{"rendered":"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad"},"content":{"rendered":"\n<p>La actualizaci\u00f3n de octubre de 2024 acerca a WordPress a ser una plataforma segura, vers\u00e1til y altamente personalizable, que aborda las crecientes necesidades de flexibilidad y protecci\u00f3n en todo su ecosistema. La \u00faltima actualizaci\u00f3n destaca el compromiso de la plataforma con la seguridad del usuario a trav\u00e9s de la autenticaci\u00f3n de dos factores (2FA) obligatoria para los desarrolladores, introduce un nuevo tema predeterminado altamente flexible y perfecciona el editor de bloques de Gutenberg. Estos cambios est\u00e1n dise\u00f1ados para hacer que WordPress sea m\u00e1s potente y accesible para usuarios de todos los niveles de experiencia, desde nuevos propietarios de sitios hasta desarrolladores experimentados.    <\/p>\n\n<p>En esta publicaci\u00f3n, desglosaremos las actualizaciones m\u00e1s importantes de WordPress 6.7 y exploraremos c\u00f3mo cada mejora contribuye a una mejor experiencia de usuario. Ya sea que est\u00e9 interesado en actualizaciones de seguridad, funciones principales, desarrollos de complementos o las tendencias emergentes que dan forma a la plataforma, esta descripci\u00f3n general proporciona una visi\u00f3n completa de las versiones de octubre.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-key-security-enhancements-nbsp\">Mejoras de seguridad clave  <\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-mandatory-two-factor-authentication-2fa-nbsp\">Autenticaci\u00f3n obligatoria de dos factores (2FA)  <\/h3>\n\n<p>La seguridad es un enfoque principal en la actualizaci\u00f3n de octubre, comenzando con la 2FA obligatoria para todos los desarrolladores de complementos. A medida que evolucionan las amenazas cibern\u00e9ticas, proteger las cuentas de los desarrolladores con una capa adicional de protecci\u00f3n garantiza que los actores maliciosos no puedan explotar las vulnerabilidades dentro del ecosistema de complementos. La autenticaci\u00f3n de dos factores requiere que los desarrolladores proporcionen un segundo paso de verificaci\u00f3n, como un c\u00f3digo de un solo uso enviado a un dispositivo m\u00f3vil, adem\u00e1s de su contrase\u00f1a habitual. Esto reduce significativamente el riesgo de acceso no autorizado, salvaguardando el directorio de plugins de WordPress de posibles infracciones.     <\/p>\n\n<p>Esta actualizaci\u00f3n refleja el compromiso de WordPress de proteger no solo la plataforma, sino tambi\u00e9n la gran cantidad de sitios y empresas que dependen de sus complementos. A medida que la seguridad del sitio se convierte en una preocupaci\u00f3n m\u00e1s importante para los usuarios de todo el mundo, la 2FA representa un paso esencial para minimizar el riesgo y reforzar la responsabilidad de los desarrolladores en todo WordPress.   <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-plugin-check-tool-nbsp\">Herramienta de verificaci\u00f3n de complementos  <\/h3>\n\n<p>Junto con 2FA, se ha introducido la herramienta de verificaci\u00f3n de complementos para mejorar la seguridad de los complementos mediante la automatizaci\u00f3n de las verificaciones previas al env\u00edo para problemas comunes de cumplimiento. Esta herramienta garantiza que los plugins reci\u00e9n enviados se adhieran a los est\u00e1ndares de WordPress antes de que lleguen a los usuarios, lo que minimiza la posibilidad de que las vulnerabilidades de seguridad se escapen del proceso de revisi\u00f3n.   <\/p>\n\n<p>La herramienta de verificaci\u00f3n de complementos funciona como un sistema de auditor\u00eda automatizado, escaneando problemas conocidos, errores e inconsistencias de codificaci\u00f3n que, de otro modo, podr\u00edan provocar problemas de compatibilidad o riesgos de seguridad. Para los desarrolladores, esta herramienta no solo simplifica el proceso de env\u00edo, sino que tambi\u00e9n proporciona comentarios valiosos que pueden utilizar para mejorar la calidad y la fiabilidad de sus plugins.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-core-wordpress-and-block-editor-updates-nbsp\">Actualizaciones principales de WordPress y editor de bloques  <\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-wordpress-6-7-beta-2-and-beta-3-features-nbsp\">Caracter\u00edsticas de WordPress 6.7 Beta 2 y Beta 3  <\/h3>\n\n<p><a href=\"https:\/\/wordpress.org\/news\/2024\/10\/wordpress-6-7-beta-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress 6.7 Beta 2<\/a> y Beta 3 han introducido nuevas y emocionantes caracter\u00edsticas para que los desarrolladores y usuarios las prueben, muchas de las cuales se espera que lleguen a la versi\u00f3n final. Las actualizaciones incluyen soporte mejorado para PHP 8.x, mejorando el rendimiento y la compatibilidad con los \u00faltimos entornos de servidor. WordPress tambi\u00e9n admite formatos de imagen HEIC, com\u00fanmente utilizados por los dispositivos Apple e introduce funciones de carga diferida para optimizar los tiempos de carga de im\u00e1genes. Estos cambios garantizan una experiencia de usuario m\u00e1s r\u00e1pida y fluida, especialmente en sitios con muchos medios.     <\/p>\n\n<p>La versi\u00f3n beta tambi\u00e9n incluye actualizaciones significativas para el bloque Query Loop, lo que permite a los usuarios crear visualizaciones de publicaciones personalizadas m\u00e1s f\u00e1cilmente. Los usuarios ahora pueden ajustar las opciones de filtrado, seleccionar configuraciones espec\u00edficas del contexto y realizar otras mejoras que mejoran tanto la visualizaci\u00f3n como la navegaci\u00f3n de las publicaciones. Todav\u00eda en pruebas, estas actualizaciones destacan los esfuerzos de WordPress para proporcionar una experiencia de edici\u00f3n fluida mientras prepara a los usuarios para futuras mejoras.    <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-gutenberg-enhancements-nbsp\">Mejoras de Gutenberg  <\/h3>\n\n<p>El <a href=\"https:\/\/gutenbergtimes.com\/roadmap-wordpress-6-7-design-systems-data-views-and-more-weekend-edition-303\/\" target=\"_blank\" rel=\"noreferrer noopener\">editor de bloques Gutenberg edici\u00f3n de fin de semana 303<\/a> se mantiene a la vanguardia de las capacidades de personalizaci\u00f3n de WordPress, y la actualizaci\u00f3n de octubre trae varias mejoras. El bloque de navegaci\u00f3n se ha refinado para ofrecer m\u00e1s control sobre el dise\u00f1o del sitio web, con herramientas actualizadas para dise\u00f1ar y organizar los elementos del men\u00fa. Esto facilita a los usuarios la creaci\u00f3n de una navegaci\u00f3n visualmente atractiva y accesible sin necesidad de amplios conocimientos de codificaci\u00f3n.    <\/p>\n\n<p>Adem\u00e1s, WordPress ha eliminado la etiqueta experimental de la configuraci\u00f3n de tipograf\u00eda, marcando estas herramientas como opciones estables y confiables para la personalizaci\u00f3n del texto. Esto es particularmente \u00fatil para los usuarios que buscan crear dise\u00f1os cohesivos directamente dentro del editor de bloques, aprovechando las herramientas para el estilo de texto, los ajustes de dise\u00f1o y las mejoras de dise\u00f1o receptivo.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-plugin-ecosystem-developments-nbsp\">Desarrollos del ecosistema de plugins  <\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-acf-fork-to-secure-custom-fields-nbsp\">Bifurcaci\u00f3n ACF para proteger campos personalizados  <\/h3>\n\n<p>Uno de los cambios m\u00e1s notables en el ecosistema de plugins es la bifurcaci\u00f3n del <a href=\"https:\/\/wptavern.com\/acf-plugin-forked-to-secure-custom-fields-plugin\" target=\"_blank\" rel=\"noreferrer noopener\">plugin Advanced Custom Fields (ACF),<\/a> que ha dado lugar a la creaci\u00f3n de Secure Custom Fields. Esta bifurcaci\u00f3n garantiza que los usuarios que conf\u00edan en ACF para la administraci\u00f3n de campos personalizados puedan seguir haci\u00e9ndolo con una versi\u00f3n que prioriza la seguridad y la estabilidad. Dada la popularidad de ACF dentro de la comunidad de WordPress, esta bifurcaci\u00f3n ha sido un desarrollo significativo tanto para los usuarios como para los desarrolladores.    <\/p>\n\n<p>La bifurcaci\u00f3n de un complemento permite a la comunidad mantener su funcionalidad de forma independiente, especialmente cuando surgen preocupaciones sobre la direcci\u00f3n del complemento original. En este caso, la bifurcaci\u00f3n de Secure Custom Fields conserva las caracter\u00edsticas del plugin original al tiempo que mejora su integridad, lo que garantiza que los usuarios puedan confiar en los campos personalizados sin interrupciones.   <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-rollback-for-plugin-updates-nbsp\">Reversi\u00f3n de actualizaciones de plugins  <\/h3>\n\n<p>Otra caracter\u00edstica muy solicitada introducida este mes es la reversi\u00f3n de la actualizaci\u00f3n del complemento. Con esta funci\u00f3n, los usuarios pueden revertir un plugin a su versi\u00f3n anterior si una actualizaci\u00f3n causa problemas en su sitio. Esta opci\u00f3n de reversi\u00f3n proporciona una capa de control y seguridad, lo que permite a los usuarios probar las actualizaciones con menos riesgo de tiempo de inactividad o errores del sitio.    <\/p>\n\n<p>La funci\u00f3n de reversi\u00f3n es especialmente valiosa para los sitios que dependen en gran medida de m\u00faltiples complementos para funcionar correctamente. Al permitir a los usuarios deshacer una actualizaci\u00f3n f\u00e1cilmente, WordPress reduce la probabilidad de problemas de compatibilidad, lo que hace que el mantenimiento del sitio sea m\u00e1s manejable y flexible.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-new-default-theme-twenty-twenty-five-nbsp\">Nuevo tema predeterminado: Twenty Twenty-Five  <\/h2>\n\n<p>El tema Twenty Twenty-Five es el \u00faltimo tema predeterminado para WordPress, introducido para mostrar las capacidades de personalizaci\u00f3n en expansi\u00f3n de la plataforma. Este tema est\u00e1 construido con flexibilidad, lo que permite a los usuarios aprovechar las herramientas de dise\u00f1o basadas en bloques para una experiencia totalmente personalizable. Cuenta con fuentes de alta calidad que admiten varios idiomas, una gama de paletas de colores y una amplia colecci\u00f3n de patrones predise\u00f1ados.    <\/p>\n\n<p>Dise\u00f1ado pensando en blogs personales, sitios con muchas fotos y dise\u00f1os ricos en contenido, Twenty Twenty-Five es compatible con el Editor del sitio, lo que ofrece a los usuarios una forma perfecta de ajustar y refinar la apariencia de su sitio. El tema encarna el compromiso de WordPress de capacitar a los usuarios para crear sitios web profesionales y visualmente atractivos sin necesidad de habilidades avanzadas de codificaci\u00f3n.   <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five.jpeg\" alt=\"Tema veinticinco\" class=\"wp-image-111387\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five.jpeg 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five-300x188.jpeg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five-768x480.jpeg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five-24x15.jpeg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five-36x23.jpeg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/twenty-twenty-five-48x30.jpeg 48w\" sizes=\"100vw\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-emerging-wordpress-trends-nbsp\">Tendencias emergentes de WordPress  <\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-ai-integration-nbsp\">Integraci\u00f3n de IA  <\/h3>\n\n<p>WordPress est\u00e1 explorando funciones impulsadas por IA para mejorar la experiencia del usuario. Las primeras pruebas incluyen sugerencias de contenido y dise\u00f1o. Estas herramientas de IA tienen como objetivo agilizar el dise\u00f1o y la creaci\u00f3n de contenidos. Ofrecen informaci\u00f3n automatizada, recomendaciones de contenido personalizadas y ajustes de dise\u00f1o eficientes. Esto permite a los usuarios centrarse m\u00e1s en la estrategia y la creatividad.    <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-accessibility-and-multilingual-support-nbsp\">Accesibilidad y soporte multiling\u00fce  <\/h3>\n\n<p>Con la accesibilidad y la inclusi\u00f3n como principios rectores, WordPress est\u00e1 mejorando su soporte para el dise\u00f1o multiling\u00fce y accesible. Esta actualizaci\u00f3n presenta herramientas para hacer que el contenido sea m\u00e1s accesible para los usuarios con discapacidades. Tambi\u00e9n agrega soporte para m\u00e1s idiomas. Estas caracter\u00edsticas son esenciales para las empresas y los creadores de contenido con una audiencia global. Ayudan a llegar a una base de usuarios diversa de manera m\u00e1s efectiva.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-practical-tips-for-wordpress-users-post-update-nbsp\">Consejos pr\u00e1cticos para los usuarios de WordPress despu\u00e9s de la actualizaci\u00f3n  <\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Actualizaciones peri\u00f3dicas<\/strong>: Para garantizar una seguridad y un rendimiento \u00f3ptimos, los usuarios deben actualizar regularmente sus plugins y el software principal de WordPress. Esta simple pr\u00e1ctica puede reducir significativamente las vulnerabilidades y mantener el sitio funcionando sin problemas. <\/li>\n\n\n\n<li><strong>Habilitar 2FA: Siguiendo<\/strong> los nuevos requisitos de 2FA de WordPress para desarrolladores, los usuarios tambi\u00e9n deben considerar habilitar la autenticaci\u00f3n de dos factores en sus cuentas para mayor seguridad.  <\/li>\n\n\n\n<li><strong>Probar la compatibilidad<\/strong>: Cuando WordPress 6.7 se lanza oficialmente, probar la compatibilidad de los plugins y temas puede ayudar a prevenir problemas de funcionalidad inesperados.  <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-final-thoughts-nbsp\">Reflexiones finales  <\/h2>\n\n<p>La actualizaci\u00f3n de octubre de 2024 marca un gran paso adelante para WordPress en t\u00e9rminos de seguridad, personalizaci\u00f3n y facilidad de uso. Al introducir 2FA, comprobaciones automatizadas de plugins y una funci\u00f3n de reversi\u00f3n, WordPress est\u00e1 priorizando tanto la integridad de la plataforma como la flexibilidad del usuario. El nuevo tema Twenty Twenty-Five destaca el poder del dise\u00f1o basado en bloques en WordPress. Hace que la creaci\u00f3n de sitios diversos y visualmente atractivos sea m\u00e1s f\u00e1cil que nunca. Las herramientas impulsadas por IA tambi\u00e9n est\u00e1n en camino, junto con funciones de accesibilidad mejoradas. WordPress sigue evolucionando para satisfacer las necesidades de los usuarios modernos. Al mismo tiempo, sigue comprometida con su misi\u00f3n de democratizar la creaci\u00f3n de contenidos.        <\/p>\n\n<p>Si a\u00fan no has explorado la versi\u00f3n actualizada de WordPress, ahora es el momento perfecto para probarla y experimentar sus funciones mejoradas. Para una experiencia a\u00fan m\u00e1s fluida, considere alojar su sitio con Bluehost. Como proveedor de <a href=\"https:\/\/www.bluehost.com\/wordpress\/wordpress-hosting\">alojamiento<\/a> de confianza, Bluehost es totalmente compatible con las \u00faltimas actualizaciones de WordPress, lo que garantiza un rendimiento \u00f3ptimo y una experiencia de usuario perfecta.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-faqs-nbsp\">Preguntas frecuentes  <\/h2>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1732082644715\"><strong class=\"schema-faq-question\"><strong>\u00bfQu\u00e9 es 2FA y por qu\u00e9 es necesario para los desarrolladores de plugins?<\/strong> <\/strong> <p class=\"schema-faq-answer\">La autenticaci\u00f3n de dos factores (2FA) es una medida de seguridad que a\u00f1ade una capa adicional de protecci\u00f3n. Requiere que los usuarios verifiquen su identidad mediante un segundo m\u00e9todo, como un c\u00f3digo de un solo uso enviado a su dispositivo m\u00f3vil, junto con su contrase\u00f1a. Para los desarrolladores de plugins, 2FA ahora es obligatorio. Esto evita el acceso no autorizado a las cuentas de desarrollador. Tambi\u00e9n ayuda a proteger el repositorio de plugins de WordPress de posibles amenazas de seguridad.    <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1732082669557\"><strong class=\"schema-faq-question\"><strong>\u00bfC\u00f3mo puedo comprobar si mis plugins son compatibles con WordPress 6.7?<\/strong> <\/strong> <p class=\"schema-faq-answer\">Para comprobar la compatibilidad de los plugins con WordPress 6.7, primero actualiza tu sitio en un entorno de ensayo (o haz una copia de seguridad de tu sitio antes de actualizarlo). Pruebe cada complemento para asegurarse de que funcione correctamente. Muchos desarrolladores tambi\u00e9n publican informaci\u00f3n de compatibilidad en la p\u00e1gina del repositorio de plugins de WordPress de sus plugins.    <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1732082687036\"><strong class=\"schema-faq-question\"><strong>\u00bfQu\u00e9 hace la herramienta de verificaci\u00f3n de plugins para los desarrolladores?<\/strong> <\/strong> <p class=\"schema-faq-answer\">La herramienta de verificaci\u00f3n de complementos escanea los nuevos complementos en busca de problemas comunes antes de enviarlos. Automatiza el proceso de comprobaci\u00f3n de errores de codificaci\u00f3n. Tambi\u00e9n identifica vulnerabilidades de seguridad. Adem\u00e1s, garantiza el cumplimiento de los est\u00e1ndares de WordPress. Esta herramienta ayuda a agilizar el proceso de revisi\u00f3n y mejora la seguridad y la calidad general del plugin.      <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1732082707511\"><strong class=\"schema-faq-question\"><strong>\u00bfAfectar\u00e1 la bifurcaci\u00f3n de ACF a los campos personalizados existentes?<\/strong> <\/strong> <p class=\"schema-faq-answer\">No, la bifurcaci\u00f3n de los campos personalizados avanzados (ACF) a \u00abCampos personalizados seguros\u00bb tiene como objetivo mantener la funcionalidad de ACF y, al mismo tiempo, mejorar su seguridad. Los usuarios que conf\u00edan en ACF pueden seguir utilizando la nueva versi\u00f3n bifurcada sin perder los datos de campos personalizados existentes.   <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1732082727173\"><strong class=\"schema-faq-question\"><strong>\u00bfC\u00f3mo funciona la funci\u00f3n de reversi\u00f3n si una actualizaci\u00f3n del plugin causa problemas?<\/strong> <\/strong> <p class=\"schema-faq-answer\">La funci\u00f3n de reversi\u00f3n permite a los usuarios revertir un complemento a su versi\u00f3n anterior si una actualizaci\u00f3n resulta en problemas o incompatibilidades. Seleccione la opci\u00f3n de reversi\u00f3n en la configuraci\u00f3n del complemento, que restablece la \u00faltima versi\u00f3n estable sin afectar otras funciones del sitio.   <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1732082746873\"><strong class=\"schema-faq-question\"><strong>\u00bfC\u00f3mo puedo participar en las pruebas beta de WordPress 6.7?<\/strong> <\/strong> <p class=\"schema-faq-answer\">Para participar en las pruebas de WordPress 6.7 Beta, instala el plugin WordPress Beta Tester desde el repositorio de plugins de WordPress. Seleccione el canal \u00abBleeding edge\u00bb para las actualizaciones beta. Puedes enviar tus comentarios a trav\u00e9s de los foros de soporte de WordPress o GitHub. Esto ayuda al equipo de desarrollo a mejorar la versi\u00f3n final.     <\/p> <\/div> <\/div>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 hay de nuevo en WordPress? Un an\u00e1lisis detallado de la actualizaci\u00f3n de octubre de 2024: caracter\u00edsticas, seguridad y mejoras. <\/p>\n","protected":false},"author":137,"featured_media":117640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Actualizaci\u00f3n de WordPress de octubre de 2024: nuevas funciones y actualizaciones de seguridad","_yoast_wpseo_metadesc":"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.","inline_featured_image":false,"footnotes":""},"categories":[1365],"tags":[3659,3682],"ppma_author":[672],"class_list":["post-117639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress-en-ingles","tag-cms","tag-trucos-y-consejos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Actualizaci\u00f3n de WordPress de octubre de 2024: nuevas funciones y actualizaciones de seguridad<\/title>\n<meta name=\"description\" content=\"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/117639\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad\" \/>\n<meta property=\"og:description\" content=\"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T06:20:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T12:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Priyanka Jain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bluehost\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Priyanka Jain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\"},\"author\":{\"name\":\"Priyanka Jain\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/d1a085f70e56f0f622aa315910022cba\"},\"headline\":\"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad\",\"datePublished\":\"2024-11-20T06:20:52+00:00\",\"dateModified\":\"2025-04-29T12:37:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\"},\"wordCount\":2294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp\",\"keywords\":[\"CMS\",\"Trucos y consejos\"],\"articleSection\":[\"WordPress (en ingl\u00e9s)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#respond\"]}]},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\",\"name\":\"Actualizaci\u00f3n de WordPress de octubre de 2024: nuevas funciones y actualizaciones de seguridad\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp\",\"datePublished\":\"2024-11-20T06:20:52+00:00\",\"dateModified\":\"2025-04-29T12:37:16+00:00\",\"description\":\"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress (en ingl\u00e9s)\",\"item\":\"https:\/\/www.bluehost.com\/blog\/es\/category\/wordpress-en-ingles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/d1a085f70e56f0f622aa315910022cba\",\"name\":\"Priyanka Jain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/3238c47c6f70875a7d6840d7373f176f\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg\",\"caption\":\"Priyanka Jain\"},\"description\":\"I'm Priyanka Jain, a content writer at Bluehost with four years of experience across various topics. I am passionate about turning complex ideas into simple, engaging content. Friendly and curious, I enjoy exploring new things and connecting with others.\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/priyanka-jain\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715\",\"position\":1,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715\",\"name\":\"\u00bfQu\u00e9 es 2FA y por qu\u00e9 es necesario para los desarrolladores de plugins?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La autenticaci\u00f3n de dos factores (2FA) es una medida de seguridad que a\u00f1ade una capa adicional de protecci\u00f3n. Requiere que los usuarios verifiquen su identidad mediante un segundo m\u00e9todo, como un c\u00f3digo de un solo uso enviado a su dispositivo m\u00f3vil, junto con su contrase\u00f1a. Para los desarrolladores de plugins, 2FA ahora es obligatorio. Esto evita el acceso no autorizado a las cuentas de desarrollador. Tambi\u00e9n ayuda a proteger el repositorio de plugins de WordPress de posibles amenazas de seguridad.    \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557\",\"position\":2,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557\",\"name\":\"\u00bfC\u00f3mo puedo comprobar si mis plugins son compatibles con WordPress 6.7?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Para comprobar la compatibilidad de los plugins con WordPress 6.7, primero actualiza tu sitio en un entorno de ensayo (o haz una copia de seguridad de tu sitio antes de actualizarlo). Pruebe cada complemento para asegurarse de que funcione correctamente. Muchos desarrolladores tambi\u00e9n publican informaci\u00f3n de compatibilidad en la p\u00e1gina del repositorio de plugins de WordPress de sus plugins.    \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036\",\"position\":3,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036\",\"name\":\"\u00bfQu\u00e9 hace la herramienta de verificaci\u00f3n de plugins para los desarrolladores?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La herramienta de verificaci\u00f3n de complementos escanea los nuevos complementos en busca de problemas comunes antes de enviarlos. Automatiza el proceso de comprobaci\u00f3n de errores de codificaci\u00f3n. Tambi\u00e9n identifica vulnerabilidades de seguridad. Adem\u00e1s, garantiza el cumplimiento de los est\u00e1ndares de WordPress. Esta herramienta ayuda a agilizar el proceso de revisi\u00f3n y mejora la seguridad y la calidad general del plugin.      \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511\",\"position\":4,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511\",\"name\":\"\u00bfAfectar\u00e1 la bifurcaci\u00f3n de ACF a los campos personalizados existentes?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No, la bifurcaci\u00f3n de los campos personalizados avanzados (ACF) a \\\"Campos personalizados seguros\\\" tiene como objetivo mantener la funcionalidad de ACF y, al mismo tiempo, mejorar su seguridad. Los usuarios que conf\u00edan en ACF pueden seguir utilizando la nueva versi\u00f3n bifurcada sin perder los datos de campos personalizados existentes.   \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173\",\"position\":5,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173\",\"name\":\"\u00bfC\u00f3mo funciona la funci\u00f3n de reversi\u00f3n si una actualizaci\u00f3n del plugin causa problemas?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La funci\u00f3n de reversi\u00f3n permite a los usuarios revertir un complemento a su versi\u00f3n anterior si una actualizaci\u00f3n resulta en problemas o incompatibilidades. Seleccione la opci\u00f3n de reversi\u00f3n en la configuraci\u00f3n del complemento, que restablece la \u00faltima versi\u00f3n estable sin afectar otras funciones del sitio.   \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873\",\"position\":6,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873\",\"name\":\"\u00bfC\u00f3mo puedo participar en las pruebas beta de WordPress 6.7?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Para participar en las pruebas de WordPress 6.7 Beta, instala el plugin WordPress Beta Tester desde el repositorio de plugins de WordPress. Seleccione el canal \\\"Bleeding edge\\\" para las actualizaciones beta. Puedes enviar tus comentarios a trav\u00e9s de los foros de soporte de WordPress o GitHub. Esto ayuda al equipo de desarrollo a mejorar la versi\u00f3n final.     \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Actualizaci\u00f3n de WordPress de octubre de 2024: nuevas funciones y actualizaciones de seguridad","description":"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/117639\/","og_locale":"es_ES","og_type":"article","og_title":"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad","og_description":"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.","og_url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2024-11-20T06:20:52+00:00","article_modified_time":"2025-04-29T12:37:16+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp","type":"image\/webp"}],"author":"Priyanka Jain","twitter_card":"summary_large_image","twitter_creator":"@bluehost","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Priyanka Jain","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/"},"author":{"name":"Priyanka Jain","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/d1a085f70e56f0f622aa315910022cba"},"headline":"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad","datePublished":"2024-11-20T06:20:52+00:00","dateModified":"2025-04-29T12:37:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/"},"wordCount":2294,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp","keywords":["CMS","Trucos y consejos"],"articleSection":["WordPress (en ingl\u00e9s)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/","url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/","name":"Actualizaci\u00f3n de WordPress de octubre de 2024: nuevas funciones y actualizaciones de seguridad","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp","datePublished":"2024-11-20T06:20:52+00:00","dateModified":"2025-04-29T12:37:16+00:00","description":"Descubre la actualizaci\u00f3n de WordPress de octubre de 2024 con 2FA, reversiones y el nuevo tema Twenty Twenty-Five. Explore las mejoras en las herramientas de seguridad, personalizaci\u00f3n e inteligencia artificial.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/11\/August-2023-WordPress-Updates-1024x576.png.webp","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"WordPress (en ingl\u00e9s)","item":"https:\/\/www.bluehost.com\/blog\/es\/category\/wordpress-en-ingles\/"},{"@type":"ListItem","position":3,"name":"Actualizaci\u00f3n de WordPress de octubre de 2024: descripci\u00f3n completa de las nuevas funciones y mejoras de seguridad"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/d1a085f70e56f0f622aa315910022cba","name":"Priyanka Jain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/3238c47c6f70875a7d6840d7373f176f","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg","caption":"Priyanka Jain"},"description":"I'm Priyanka Jain, a content writer at Bluehost with four years of experience across various topics. I am passionate about turning complex ideas into simple, engaging content. Friendly and curious, I enjoy exploring new things and connecting with others.","url":"https:\/\/www.bluehost.com\/blog\/es\/author\/priyanka-jain\/"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715","position":1,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082644715","name":"\u00bfQu\u00e9 es 2FA y por qu\u00e9 es necesario para los desarrolladores de plugins?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La autenticaci\u00f3n de dos factores (2FA) es una medida de seguridad que a\u00f1ade una capa adicional de protecci\u00f3n. Requiere que los usuarios verifiquen su identidad mediante un segundo m\u00e9todo, como un c\u00f3digo de un solo uso enviado a su dispositivo m\u00f3vil, junto con su contrase\u00f1a. Para los desarrolladores de plugins, 2FA ahora es obligatorio. Esto evita el acceso no autorizado a las cuentas de desarrollador. Tambi\u00e9n ayuda a proteger el repositorio de plugins de WordPress de posibles amenazas de seguridad.    ","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557","position":2,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082669557","name":"\u00bfC\u00f3mo puedo comprobar si mis plugins son compatibles con WordPress 6.7?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Para comprobar la compatibilidad de los plugins con WordPress 6.7, primero actualiza tu sitio en un entorno de ensayo (o haz una copia de seguridad de tu sitio antes de actualizarlo). Pruebe cada complemento para asegurarse de que funcione correctamente. Muchos desarrolladores tambi\u00e9n publican informaci\u00f3n de compatibilidad en la p\u00e1gina del repositorio de plugins de WordPress de sus plugins.    ","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036","position":3,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082687036","name":"\u00bfQu\u00e9 hace la herramienta de verificaci\u00f3n de plugins para los desarrolladores?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La herramienta de verificaci\u00f3n de complementos escanea los nuevos complementos en busca de problemas comunes antes de enviarlos. Automatiza el proceso de comprobaci\u00f3n de errores de codificaci\u00f3n. Tambi\u00e9n identifica vulnerabilidades de seguridad. Adem\u00e1s, garantiza el cumplimiento de los est\u00e1ndares de WordPress. Esta herramienta ayuda a agilizar el proceso de revisi\u00f3n y mejora la seguridad y la calidad general del plugin.      ","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511","position":4,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082707511","name":"\u00bfAfectar\u00e1 la bifurcaci\u00f3n de ACF a los campos personalizados existentes?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"No, la bifurcaci\u00f3n de los campos personalizados avanzados (ACF) a \"Campos personalizados seguros\" tiene como objetivo mantener la funcionalidad de ACF y, al mismo tiempo, mejorar su seguridad. Los usuarios que conf\u00edan en ACF pueden seguir utilizando la nueva versi\u00f3n bifurcada sin perder los datos de campos personalizados existentes.   ","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173","position":5,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082727173","name":"\u00bfC\u00f3mo funciona la funci\u00f3n de reversi\u00f3n si una actualizaci\u00f3n del plugin causa problemas?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La funci\u00f3n de reversi\u00f3n permite a los usuarios revertir un complemento a su versi\u00f3n anterior si una actualizaci\u00f3n resulta en problemas o incompatibilidades. Seleccione la opci\u00f3n de reversi\u00f3n en la configuraci\u00f3n del complemento, que restablece la \u00faltima versi\u00f3n estable sin afectar otras funciones del sitio.   ","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873","position":6,"url":"https:\/\/www.bluehost.com\/blog\/es\/actualizacion-de-wordpress-de-octubre-de-2024-descripcion-completa-de-las-nuevas-funciones-y-mejoras-de-seguridad\/#faq-question-1732082746873","name":"\u00bfC\u00f3mo puedo participar en las pruebas beta de WordPress 6.7?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Para participar en las pruebas de WordPress 6.7 Beta, instala el plugin WordPress Beta Tester desde el repositorio de plugins de WordPress. Seleccione el canal \"Bleeding edge\" para las actualizaciones beta. Puedes enviar tus comentarios a trav\u00e9s de los foros de soporte de WordPress o GitHub. Esto ayuda al equipo de desarrollo a mejorar la versi\u00f3n final.     ","inLanguage":"es"},"inLanguage":"es"}]}},"authors":[{"term_id":672,"user_id":137,"is_guest":0,"slug":"priyanka-jain","display_name":"Priyanka Jain","avatar_url":{"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg","url2x":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2024\/10\/Image.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/117639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=117639"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/117639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/117640"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=117639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=117639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=117639"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=117639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}