{"id":123375,"date":"2023-12-29T11:25:25","date_gmt":"2023-12-29T11:25:25","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/"},"modified":"2025-02-24T03:09:47","modified_gmt":"2025-02-24T03:09:47","slug":"wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/","title":{"rendered":"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023"},"content":{"rendered":"\n<p>A medida que 2023 llega a su fin, tambi\u00e9n lo hace un emocionante a\u00f1o de actualizaciones de WordPress.<\/p>\n\n<p>El mayor de ellos fue el 20\u00ba aniversario de WordPress en mayo. Tambi\u00e9n se celebr\u00f3 la primera <a href=\"https:\/\/www.bluehost.com\/blog\/wordpress-news-roundup-february-2023\/\">WordCamp Asia<\/a> emblem\u00e1tica, el paso <a href=\"https:\/\/www.bluehost.com\/blog\/wordpress-updates-april-2023\/\">a la fase 3 del proyecto Gutenberg<\/a> y el lanzamiento de <a href=\"https:\/\/www.bluehost.com\/blog\/wordpress-updates\/\">WordPress Playground<\/a>. <\/p>\n\n<p>Adem\u00e1s de esto, WordPress 6.2-6.4 sali\u00f3 este a\u00f1o, y se llevaron a cabo 70 WordCamps en todo el mundo.<\/p>\n\n<p>Ahora, terminemos el a\u00f1o con WordPress 6.4.2 (la \u00faltima versi\u00f3n de 2023), Gutenberg 17.2 y el Estado de la Palabra yendo a Madrid por primera vez.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-security-release-wordpress-6-4-2\"><a id=\"_j7cd3snxrxb2\"><\/a>Versi\u00f3n de seguridad: WordPress 6.4.2<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1682\" height=\"354\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress.png\" alt=\"La &#xFA;ltima versi&#xF3;n de seguridad de WordPress es la 6.4.2.\" class=\"wp-image-49378\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress.png 1682w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-300x63.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-1024x216.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-768x162.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-1536x323.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-24x5.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-36x8.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Security-release-WordPress-48x10.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Si no mantienes activadas las actualizaciones autom\u00e1ticas, lo que definitivamente deber\u00edas, es hora de actualizar WordPress de inmediato.<\/p>\n\n<p>Un problema de seguridad potencialmente cr\u00edtico introducido en WordPress 6.4 podr\u00eda permitir la <a href=\"https:\/\/www.wordfence.com\/blog\/2023\/12\/psa-critical-pop-chain-allowing-remote-code-execution-patched-in-wordpress-6-4-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">ejecuci\u00f3n remota de c\u00f3digo<\/a> y una toma de control de todo el sitio cuando se combina con plugins inseguros. Afortunadamente, no parece que la vulnerabilidad se haya explotado significativamente, si es que se ha explotado. <\/p>\n\n<p>El lanzamiento r\u00e1pido de WordPress 6.4.2 aborda este problema. Est\u00e1s completamente seguro siempre que tu instalaci\u00f3n de WordPress est\u00e9 actualizada. <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Hoja de ruta hacia WordPress 6.5<\/h2>\n\n<p>Con WordPress 6.4 asent\u00e1ndose, es hora de esperar el pr\u00f3ximo lanzamiento: <a href=\"https:\/\/make.wordpress.org\/core\/2023\/12\/07\/roadmap-to-6-5\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress 6.5<\/a>. Esp\u00e9ralo a principios de la pr\u00f3xima primavera, el 26 de marzo de 2024. <\/p>\n\n<p>Si bien es posible que no todos estos lleguen al producto final, el equipo de WordPress est\u00e1 buscando agregar estas caracter\u00edsticas y m\u00e1s:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La funci\u00f3n de biblioteca de fuentes previamente planeada para WordPress 6.4 llegar\u00e1 a la versi\u00f3n 6.5.<\/li>\n\n\n\n<li>Los atributos de bloque y patr\u00f3n se sincronizar\u00e1n sin dejar de permitir cambios locales. Por ejemplo, puedes reutilizar el estilo de un bloque en todo tu sitio web, pero cambiar el texto dentro de \u00e9l en cada p\u00e1gina. <\/li>\n\n\n\n<li>El soporte para las herramientas de apariencia y una mejor gesti\u00f3n de patrones llegar\u00e1 a los temas cl\u00e1sicos.<\/li>\n\n\n\n<li>La funci\u00f3n Combinaciones de colores le permitir\u00e1 usar colores predefinidos dentro de los bloques de grupo.<\/li>\n\n\n\n<li>Se est\u00e1 trabajando en un nuevo redise\u00f1o rico en funciones para plantillas, partes de plantillas y p\u00e1ginas de patrones. Las revisiones tambi\u00e9n llegar\u00e1n a las plantillas y partes de plantillas. <\/li>\n\n\n\n<li>Varias API nuevas, incluida la API de interactividad, estar\u00e1n disponibles para los desarrolladores.<\/li>\n\n\n\n<li>La versi\u00f3n m\u00ednima de MySQL aumentar\u00e1 a 5.5.5, y el equipo trabajar\u00e1 para mejorar la compatibilidad con PHP 8.0+.<\/li>\n<\/ul>\n\n<p>Ser\u00e1 una actualizaci\u00f3n emocionante para los dise\u00f1adores de WordPress, que ver\u00e1n muchas mejoras y m\u00e1s opciones.<\/p>\n\n<h2 class=\"wp-block-heading\">Gutenberg 17.2: Mejoras en la experiencia de dise\u00f1o<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"1152\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2.png\" alt=\"Gutenberg 17.2 ofrece una mayor accesibilidad al editor de bloques.\" class=\"wp-image-49379\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2.png 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-300x173.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-1024x590.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-768x443.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-1536x885.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-36x21.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Gutenberg-17.2-48x28.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/make.wordpress.org\/core\/2023\/12\/06\/whats-new-in-gutenberg-17-2-6-december\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Fuente de la imagen<\/em><\/a><\/figcaption><\/figure>\n\n<p>Gutenberg 17.1 y 17.2 salieron a finales de noviembre y principios de diciembre, cada uno con algunas caracter\u00edsticas peque\u00f1as pero impactantes para mejorar su experiencia.<\/p>\n\n<p>He aqu\u00ed un punto destacado de las nuevas caracter\u00edsticas de Gutenberg 17.2 y 17.1:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>El equipo realiz\u00f3 algunas <a href=\"https:\/\/www.bluehost.com\/blog\/accessibility-for-websites\/\">mejoras en la accesibilidad y el<\/a> flujo de escritura. Esto incluye peque\u00f1os ajustes para hacer que varias caracter\u00edsticas sean coherentes con otras. <\/li>\n\n\n\n<li>El bloque Quote ahora admite el espaciado entre bloques.<\/li>\n\n\n\n<li>Puede arrastrar y soltar bloques al principio y al final de un documento mucho m\u00e1s f\u00e1cilmente.<\/li>\n\n\n\n<li>Los encabezados de tabla en conjuntos de datos grandes ahora son fijos.<\/li>\n\n\n\n<li>El modo sin distracciones ahora cuenta con una barra de herramientas de bloqueo que se desliza a la vista cuando se pasa el cursor por la parte superior de la pantalla.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Actualizaciones para desarrolladores de WordPress para diciembre de 2023<\/h2>\n\n<p>Programadores de WordPress, sintonicen las <a href=\"https:\/\/developer.wordpress.org\/news\/2023\/12\/10\/whats-new-for-developers-december-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00faltimas actualizaciones para desarrolladores de diciembre<\/a>. Hemos mencionado la hoja de ruta para la versi\u00f3n 6.5 y repasaremos el regreso de las vistas previas de los plugins, pero aqu\u00ed hay algunos otros aspectos destacados del mes: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>El Manual Tem\u00e1tico ha a\u00f1adido varios cap\u00edtulos nuevos centrados en los bloques, y la revisi\u00f3n del manual a\u00fan est\u00e1 en curso.<\/li>\n\n\n\n<li>Las bibliotecas PHPMailer y getID3 se han actualizado a sus \u00faltimas versiones.<\/li>\n\n\n\n<li>La API de interactividad en Gutenberg ahora admite una API nativa store().<\/li>\n\n\n\n<li>Gutenberg ha agregado una configuraci\u00f3n de dise\u00f1o de theme.json para desactivar los controles de tama\u00f1o de contenido personalizados.<\/li>\n\n\n\n<li>Los bloques de galer\u00eda con im\u00e1genes anidadas ahora usan una barra de desplazamiento transparente. Esto evita problemas con subt\u00edtulos largos. <\/li>\n\n\n\n<li>El componente Tabs reemplaz\u00f3 recientemente a TabsPanel en Gutenberg y ha recibido varias mejoras.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Vuelven las vistas previas de los plugins<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"594\" height=\"512\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews.png\" alt=\"Las vistas previas de complementos regresaron en diciembre.\" class=\"wp-image-49380\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews.png 594w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews-300x259.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews-24x21.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews-36x31.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Plugin-previews-48x41.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/make.wordpress.org\/meta\/2023\/11\/22\/plugin-directory-preview-button-revisited\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Fuente de la imagen<\/em><\/a><\/figcaption><\/figure>\n\n<p>Si recuerdas el lanzamiento inicial de <a href=\"https:\/\/make.wordpress.org\/meta\/2023\/11\/22\/plugin-directory-preview-button-revisited\/\" target=\"_blank\" rel=\"noreferrer noopener\">Plugin Previews<\/a>, sabr\u00e1s que r\u00e1pidamente se vio inmerso en una reacci\u00f3n violenta. La premisa, permitir que las personas prueben complementos a trav\u00e9s de la nueva funci\u00f3n de demostraci\u00f3n de WordPress Playground, era excelente en teor\u00eda. <\/p>\n\n<p>En la ejecuci\u00f3n, WordPress Playground no tuvo en cuenta ning\u00fan requisito del plugin. Simplemente no funcion\u00f3 bien con algunos complementos, lo que hizo que los usuarios vieran un complemento roto y decidieran no instalarlo. <\/p>\n\n<p>El equipo de WordPress elimin\u00f3 r\u00e1pidamente las vistas previas de los plugins. Aun as\u00ed, escucharon los comentarios y decidieron volver a implementar la funci\u00f3n de forma optativa. Adem\u00e1s, los desarrolladores pueden configurar cualquier dependencia de instalaci\u00f3n con otros complementos o temas y otros cambios \u00fatiles.  <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Las principales vulnerabilidades afectan a m\u00e1s de 15,2 millones de sitios web<\/h2>\n\n<p>Finales de noviembre y principios de diciembre han sido estresantes para los usuarios de WordPress, ya que se han descubierto m\u00faltiples vulnerabilidades importantes en los plugins e incluso en la propia plataforma. Estos son algunos de los aspectos m\u00e1s destacados: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Wordfence detect\u00f3 <a href=\"https:\/\/www.wordfence.com\/blog\/2023\/12\/over-100-wordpress-repository-plugins-affected-by-shortcode-based-stored-cross-site-scripting\/\" target=\"_blank\" rel=\"noreferrer noopener\">100+ plugins afectados<\/a> por un exploit de scripting entre sitios que utiliza c\u00f3digos cortos. Adem\u00e1s, algunos de estos plugins no han sido parcheados. En total, esto afect\u00f3 a m\u00e1s de 6 millones de sitios web.  <\/li>\n\n\n\n<li>WordPress conten\u00eda una vulnerabilidad importante que permit\u00eda la ejecuci\u00f3n remota de c\u00f3digo, que la versi\u00f3n 6.4.2 parche\u00f3.<\/li>\n\n\n\n<li>Elementor parche\u00f3 una <a href=\"https:\/\/www.wordfence.com\/blog\/2023\/12\/psa-high-severity-file-upload-vulnerability-in-elementor-patched\/\" target=\"_blank\" rel=\"noreferrer noopener\">grave vulnerabilidad de carga de archivos<\/a> que afect\u00f3 a m\u00e1s de 9 millones de usuarios.<\/li>\n\n\n\n<li>Una vulnerabilidad significativa <a href=\"https:\/\/www.wordfence.com\/blog\/2023\/12\/update-asap-critical-unauthenticated-arbitrary-file-upload-in-mw-wp-form-allows-malicious-code-execution\/\" target=\"_blank\" rel=\"noreferrer noopener\">en el plugin MW WP Form<\/a>, que afectaba a 200.000 usuarios, fue parcheada r\u00e1pidamente.<\/li>\n\n\n\n<li>Backup Migration, un plugin con m\u00e1s de 90.000 usuarios, parche\u00f3 r\u00e1pidamente una <a href=\"https:\/\/www.wordfence.com\/blog\/2023\/12\/critical-unauthenticated-remote-code-execution-found-in-backup-migration-plugin\/\" target=\"_blank\" rel=\"noreferrer noopener\">vulnerabilidad cr\u00edtica que permit\u00eda la ejecuci\u00f3n remota de c\u00f3digo<\/a>.<\/li>\n\n\n\n<li>Una <a href=\"https:\/\/blog.sucuri.net\/2023\/12\/analysis-of-the-fake-wordpress-cve-2023-46182-patch-plugin-phishing-campaign.html\" target=\"_blank\" rel=\"noreferrer noopener\">estafa de phishing<\/a> de piratas inform\u00e1ticos que afirman ser parte del equipo de seguridad de WordPress ha plagado a los administradores de WordPress.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/wordpress-hosting-service-kinsta-targeted-by-google-phishing-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los anuncios de phishing alojados por Google<\/a> se dirigieron a los usuarios de Kinsta.<\/li>\n<\/ul>\n\n<p>Para mitigar posibles hackeos, mant\u00e9n tus plugins y el n\u00facleo de WordPress actualizados e instala un <a href=\"https:\/\/www.bluehost.com\/blog\/best-wordpress-security-plugins\/\">plugin de seguridad altamente valorado<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-state-of-the-word-2023-recap\">Resumen del Estado de la Palabra 2023<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word.png\" alt=\"El State of the Word 2023 celebr&#xF3; el 20&#xBA; aniversario de WordPress.\" class=\"wp-image-49381\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word.png 1280w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-300x200.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-1024x682.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-768x512.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-270x180.png 270w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-24x16.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-36x24.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/State-of-Word-48x32.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/wordpress.org\/news\/2023\/12\/state-of-the-word-2023-recap\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Fuente de la imagen<\/em><\/a><\/figcaption><\/figure>\n\n<p>El evento anual State of the Word se estren\u00f3 en diciembre, teniendo lugar por primera vez fuera de los Estados Unidos, en Madrid, Espa\u00f1a.<\/p>\n\n<p>Este a\u00f1o fue el 20\u00ba aniversario de WordPress, por lo que el evento fue una emocionante reflexi\u00f3n sobre lo lejos que ha llegado WordPress. Cientos de desarrolladores y colaboradores clave asistieron, mientras que millones lo vieron en l\u00ednea. <\/p>\n\n<p>La charla toc\u00f3 temas como el proyecto Gutenberg, sus pr\u00f3ximas fases y el futuro de la IA y WordPress.<\/p>\n\n<p>Puedes leer el <a href=\"https:\/\/wordpress.org\/news\/2023\/12\/state-of-the-word-2023-recap\/\" target=\"_blank\" rel=\"noreferrer noopener\">resumen del Estado de la Palabra 2023<\/a> y <a href=\"https:\/\/www.youtube.com\/watch?v=c7M4mBVgP3Y\" target=\"_blank\" rel=\"noreferrer noopener\">ver el evento completo en YouTube<\/a>. Los fan\u00e1ticos de WordPress lo disfrutar\u00e1n. <\/p>\n\n<h2 class=\"wp-block-heading\">Las primeras WordCamps de 2024<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1687\" height=\"863\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024.png\" alt=\"A principios de 2024 se celebrar&#xE1;n algunas WordCamps.\" class=\"wp-image-49382\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024.png 1687w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-300x153.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-1024x524.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-768x393.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-1536x786.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-36x18.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordCamp-2024-48x25.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Todas las WordCamps de 2023 han llegado a su fin. Ha sido un a\u00f1o largo y emocionante, con 70 WordCamps en todo el mundo. Ahora, es el momento de esperar con ansias los eventos de WordPress del pr\u00f3ximo a\u00f1o.  <\/p>\n\n<p>Aunque la mayor\u00eda de ellas siguen en proceso, se han previsto algunas WordCamps para los primeros meses de 2024.<\/p>\n\n<p>Este enero, espere con ansias los eventos de WordPress en Calcuta, India; Pokhara, Nepal; Zaragoza, Espa\u00f1a; y Yakarta, Indonesia. Febrero tambi\u00e9n contar\u00e1 con WordCamps en Kobe, Jap\u00f3n, y Phoenix, EE.UU. <\/p>\n\n<p>Echa un vistazo a la <a href=\"https:\/\/central.wordcamp.org\/schedule\/\" target=\"_blank\" rel=\"noreferrer noopener\">programaci\u00f3n de la WordCamp<\/a> para ver qu\u00e9 eventos se acercan a ti. Adem\u00e1s, no olvides realizar la <a href=\"https:\/\/central.wordcamp.org\/news\/2023\/12\/2023-annual-meetup-survey\/\" target=\"_blank\" rel=\"noreferrer noopener\">Encuesta Anual de Meetup 2023<\/a> si quieres asistir u organizar eventos de WordPress. <\/p>\n\n<h2 class=\"wp-block-heading\">Lanzamiento oficial de Bluehost Professional Email<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1461\" height=\"509\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email.png\" alt=\"Bluehost lanz&#xF3; Professional Email.\" class=\"wp-image-49383\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email.png 1461w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-300x105.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-1024x357.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-768x268.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-24x8.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-36x13.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/Bluehost-Professional-Email-48x17.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Una vez que hayas configurado tu sitio web profesional, lo siguiente que necesitar\u00e1s es un correo electr\u00f3nico personalizado.<\/p>\n\n<p>No puedes lanzar una campa\u00f1a de marketing por correo electr\u00f3nico desde tu correo electr\u00f3nico personal, y un correo electr\u00f3nico de marca reduce la confusi\u00f3n del cliente.<\/p>\n\n<p>Es por eso que Bluehost lanz\u00f3 <a href=\"https:\/\/www.bluehost.com\/email\/professional-email\">Professional Email<\/a>, brind\u00e1ndole alojamiento de correo electr\u00f3nico asequible a partir de solo $ 1.25 \/ a\u00f1o durante el primer a\u00f1o. Pru\u00e9balo si necesitas una direcci\u00f3n de correo electr\u00f3nico de marca para tu sitio web. <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Mantente al d\u00eda<\/h2>\n\n<p>Siga a Bluehost para conocer las <a href=\"https:\/\/www.bluehost.com\/es-es\/blog\/category\/noticia\/\">\u00faltimas noticias de la comunidad de WordPress<\/a>.<\/p>\n\n<p>Si est\u00e1 buscando un host de WordPress potente, confiable y econ\u00f3mico, consulte los <a href=\"https:\/\/www.bluehost.com\/wordpress\/wordpress-hosting\">planes de alojamiento de WordPress<\/a> de Bluehost. Y no olvide suscribirse a nuestro asequible servicio de <a href=\"https:\/\/www.bluehost.com\/email\/professional-email\">correo electr\u00f3nico profesional<\/a> . <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que 2023 llega a su fin, tambi\u00e9n lo hace un emocionante a\u00f1o de actualizaciones de WordPress. El mayor de ellos fue el 20\u00ba aniversario de WordPress en mayo. Tambi\u00e9n se celebr\u00f3 la primera WordCamp Asia emblem\u00e1tica, el paso a la fase 3 del proyecto Gutenberg y el lanzamiento de WordPress Playground. Adem\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":123272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Actualizaciones de WordPress de diciembre de 2023: WordPress 6.4.2 y m\u00e1s","_yoast_wpseo_metadesc":"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.","inline_featured_image":false,"footnotes":""},"categories":[3087,1414],"tags":[3674,3659],"ppma_author":[599],"class_list":["post-123375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizaciones-de-productos","category-noticia","tag-bajo-codigo-sin-codigo","tag-cms"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Actualizaciones de WordPress de diciembre de 2023: WordPress 6.4.2 y m\u00e1s<\/title>\n<meta name=\"description\" content=\"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/123375\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023\" \/>\n<meta property=\"og:description\" content=\"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-29T11:25:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T03:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Minal Agarwal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/minalagarwal\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Minal Agarwal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\"},\"author\":{\"name\":\"Minal Agarwal\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\"},\"headline\":\"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023\",\"datePublished\":\"2023-12-29T11:25:25+00:00\",\"dateModified\":\"2025-02-24T03:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\"},\"wordCount\":1535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png\",\"keywords\":[\"Bajo c\u00f3digo \/ Sin c\u00f3digo\",\"CMS\"],\"articleSection\":[\"Actualizaciones de productos\",\"Noticia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\",\"name\":\"Actualizaciones de WordPress de diciembre de 2023: WordPress 6.4.2 y m\u00e1s\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png\",\"datePublished\":\"2023-12-29T11:25:25+00:00\",\"dateModified\":\"2025-02-24T03:09:47+00:00\",\"description\":\"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png\",\"width\":1536,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia\",\"item\":\"https:\/\/www.bluehost.com\/blog\/es\/category\/noticia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\",\"name\":\"Minal Agarwal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"caption\":\"Minal Agarwal\"},\"description\":\"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal\"],\"knowsAbout\":[\"WordPress\"],\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/minal-agarwal\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Actualizaciones de WordPress de diciembre de 2023: WordPress 6.4.2 y m\u00e1s","description":"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/123375\/","og_locale":"es_ES","og_type":"article","og_title":"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023","og_description":"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.","og_url":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2023-12-29T11:25:25+00:00","article_modified_time":"2025-02-24T03:09:47+00:00","og_image":[{"width":1536,"height":864,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2.png","type":"image\/png"}],"author":"Minal Agarwal","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/minalagarwal","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Minal Agarwal","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/"},"author":{"name":"Minal Agarwal","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3"},"headline":"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023","datePublished":"2023-12-29T11:25:25+00:00","dateModified":"2025-02-24T03:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/"},"wordCount":1535,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png","keywords":["Bajo c\u00f3digo \/ Sin c\u00f3digo","CMS"],"articleSection":["Actualizaciones de productos","Noticia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/","url":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/","name":"Actualizaciones de WordPress de diciembre de 2023: WordPress 6.4.2 y m\u00e1s","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png","datePublished":"2023-12-29T11:25:25+00:00","dateModified":"2025-02-24T03:09:47+00:00","description":"Ponte al d\u00eda con las \u00faltimas y m\u00e1s emocionantes actualizaciones de WordPress a partir de diciembre de 2023. Cubrimos WordPress 6.4.2, Gutenberg 17.2, eventos y m\u00e1s.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/12\/WordPress-6.4.2-e1741335949255.png","width":1536,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/wordpress-6-4-2-gutenberg-17-2-7-actualizaciones-mas-impresionantes-de-wordpress-para-diciembre-de-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticia","item":"https:\/\/www.bluehost.com\/blog\/es\/category\/noticia\/"},{"@type":"ListItem","position":3,"name":"WordPress 6.4.2, Gutenberg 17.2, + 7 actualizaciones m\u00e1s impresionantes de WordPress para diciembre de 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3","name":"Minal Agarwal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478","url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","caption":"Minal Agarwal"},"description":"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal"],"knowsAbout":["WordPress"],"url":"https:\/\/www.bluehost.com\/blog\/es\/author\/minal-agarwal\/"}]}},"authors":[{"term_id":599,"user_id":74,"is_guest":0,"slug":"minal-agarwal","display_name":"Minal Agarwal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/123375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=123375"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/123375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/123272"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=123375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=123375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=123375"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=123375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}