{"id":124685,"date":"2023-08-18T12:25:00","date_gmt":"2023-08-18T12:25:00","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/una-guia-para-crear-y-administrar-menus-de-wordpress\/"},"modified":"2025-02-24T04:29:36","modified_gmt":"2025-02-24T04:29:36","slug":"una-guia-para-crear-y-administrar-menus-de-wordpress","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/","title":{"rendered":"Una gu\u00eda para crear y administrar men\u00fas de WordPress"},"content":{"rendered":"\n<p>WordPress ofrece una amplia variedad de funciones para crear un sitio web de primer nivel, incluidas opciones para crear y personalizar men\u00fas de navegaci\u00f3n.<\/p>\n\n<p>Crear men\u00fas es relativamente sencillo. Y una vez que aprendas a administrar men\u00fas en WordPress, incluso puedes crear men\u00fas personalizados optimizados. <\/p>\n\n<p>Este conocimiento es invaluable, ya que la navegaci\u00f3n optimizada puede mejorar la experiencia del usuario (UX) de su sitio web e incluso ayudar con la optimizaci\u00f3n de motores de b\u00fasqueda (SEO).<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-a-wordpress-navigation-menu\">\u00bfQu\u00e9 es un men\u00fa de navegaci\u00f3n de WordPress?<\/h2>\n\n<p>Un men\u00fa de navegaci\u00f3n de WordPress es una lista de enlaces a diferentes partes de un sitio web. Por lo general, se encuentra en la parte superior de una p\u00e1gina como encabezado. Sin embargo, tambi\u00e9n puede colocar men\u00fas a lo largo del lado derecho o izquierdo o en la parte inferior de una p\u00e1gina como pie de p\u00e1gina.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-why-is-a-wordpress-navigation-menu-so-important\">\u00bfPor qu\u00e9 es tan importante un men\u00fa de navegaci\u00f3n de WordPress?<\/h3>\n\n<p>Un men\u00fa muestra la estructura de la p\u00e1gina que los visitantes ven en la interfaz de su sitio web. Ayuda a los usuarios a localizar lo que buscan, por lo que es vital para la experiencia de usuario. <\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Un men\u00fa muestra la estructura de la p\u00e1gina que los visitantes ven en la interfaz de su sitio web. Ayuda a los usuarios a localizar lo que buscan, por lo que es vital para la experiencia de usuario. <\/p><\/blockquote><\/figure>\n\n<p>Tambi\u00e9n ayuda a los motores de b\u00fasqueda <a href=\"https:\/\/www.bluehost.com\/blog\/7-tips-to-get-your-wordpress-website-indexed-by-google\/\" target=\"_blank\" rel=\"noreferrer noopener\">a rastrear e indexar su sitio web de WordPress<\/a>, por lo que es esencial para el SEO.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-set-up-menus-in-wordpress\">C\u00f3mo configurar men\u00fas en WordPress<\/h2>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"725\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-1024x725.png\" alt=\"C&#xF3;mo configurar men&#xFA;s en WordPress.\" class=\"wp-image-45952\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-1024x725.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-300x213.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-768x544.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-24x17.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-36x26.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Setup-July-2023-48x34.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\">Captura de pantalla del entorno de prueba\n<\/figcaption><\/figure>\n\n<p>Los diferentes temas de WordPress requieren enfoques distintos, as\u00ed que revisa tu panel de control para determinar qu\u00e9 m\u00e9todo usar. Si ves \u00abEditor\u00bb en la secci\u00f3n <strong>Apariencia<\/strong>, usar\u00e1s el <a href=\"https:\/\/wordpress.com\/support\/site-editor\/\" target=\"_blank\" rel=\"noreferrer noopener\">Editor del sitio<\/a>. Si no lo haces, usar\u00e1s el panel de <a href=\"https:\/\/wordpress.com\/home\" target=\"_blank\" rel=\"noreferrer noopener\">administraci\u00f3n de WP<\/a>.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-with-the-site-editor\">Con el editor del sitio<\/h3>\n\n<p>Ve a tu panel de control de WordPress y navega hasta <strong>el Editor de apariencia &gt;<\/strong> para acceder a todas las capacidades de edici\u00f3n del sitio. Haga clic en el encabezado y navegue hasta el <strong>insertador de bloques +.<\/strong> Busca el <a href=\"https:\/\/wordpress.com\/support\/wordpress-editor\/blocks\/navigation-block\/\" target=\"_blank\" rel=\"noreferrer noopener\">bloque de navegaci\u00f3n<\/a> y a\u00f1\u00e1delo a la cabecera de tu sitio web. <\/p>\n\n<p>Puede agregar nuevos elementos de men\u00fa a trav\u00e9s del <strong>insertador de bloques +.<\/strong><\/p>\n\n<p>Mientras que el bloque de navegaci\u00f3n crea instant\u00e1neamente un men\u00fa principal, usted mismo puede crear men\u00fas adicionales. Para ello, haga clic en el men\u00fa existente y vaya a <strong>Men\u00fa de configuraci\u00f3n &gt; : Crear &gt; nuevo men\u00fa.<\/strong> <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-with-the-wp-admin-dashboard\">Con el panel de administraci\u00f3n de WP<\/h3>\n\n<p>Vaya a <strong>Men\u00fas de apariencia &gt;<\/strong> desde su panel de control. Haga clic en <strong>el men\u00fa Crear<\/strong> y elija las p\u00e1ginas que desea agregar. <\/p>\n\n<p>Tambi\u00e9n puede usar el Personalizador del administrador de WP yendo a <strong>Apariencia &gt; , Personalizar &gt; men\u00fas, &gt; Crear nuevo men\u00fa.<\/strong><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-with-the-wordpress-menu-widget\">Con el widget de men\u00fa de WordPress<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"626\" height=\"185\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023.png\" alt=\"C&#xF3;mo configurar men&#xFA;s con el widget de men&#xFA; de WordPress.\" class=\"wp-image-45953\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023.png 626w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023-300x89.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023-24x7.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023-36x11.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Wordpress-Menu-Widget-Setup-July-2023-48x14.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Captura de pantalla del entorno de prueba<\/em><br\/><\/figcaption><\/figure>\n\n<p>Si tu tema utiliza el panel de administraci\u00f3n para los men\u00fas, puedes a\u00f1adir men\u00fas adicionales a las barras laterales o a los pies de p\u00e1gina como <a href=\"https:\/\/www.bluehost.com\/blog\/wordpress-widgets-and-how-to-use-them\/\">widgets<\/a> personalizados de WordPress. Un widget es un elemento del sitio web con el que los usuarios pueden interactuar en la p\u00e1gina. Algunos ejemplos son los cuadros de di\u00e1logo, las ventanas emergentes y las barras de desplazamiento.  <\/p>\n\n<p>Agregue un widget de men\u00fa navegando por <strong>Personalizaci\u00f3n de apariencia &gt;<\/strong> en su tablero. Haga clic en + y elija el widget <strong>Men\u00fa de navegaci\u00f3n<\/strong>. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-manage-menus-in-wordpress\">C\u00f3mo administrar men\u00fas en WordPress<\/h2>\n\n<p>Existen varios enfoques para gestionar los men\u00fas de WordPress que te ayudar\u00e1n a mejorar la UX, el SEO y la calidad general de tu sitio web.<\/p>\n\n<p>Estos m\u00e9todos incluyen la edici\u00f3n de men\u00fas, la reestructuraci\u00f3n de men\u00fas y la eliminaci\u00f3n de elementos de men\u00fa.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-edit-menus-in-wordpress\">C\u00f3mo editar men\u00fas en WordPress<\/h3>\n\n<p>Si es posible, utilice el <a href=\"https:\/\/wordpress.com\/support\/customizer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Personalizador<\/a> para editar los men\u00fas. Para acceder al Personalizador, vaya a <strong>Personalizar apariencia &gt;<\/strong> en el panel de control y, a continuaci\u00f3n, seleccione <strong>Men\u00fas<\/strong>. <\/p>\n\n<p>Aqu\u00ed puedes:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>A\u00f1ade enlaces personalizados y texto de enlace.<\/li>\n\n\n\n<li>Inserte una funci\u00f3n de b\u00fasqueda navegando a <strong>Widgets de apariencia&gt;<\/strong>, eligiendo el signo + y seleccionando <strong>Widget de b\u00fasqueda<\/strong>.<\/li>\n\n\n\n<li>Agregue las p\u00e1ginas, publicaciones e \u00edconos de redes sociales deseados haciendo clic en <strong>Agregar elementos de men\u00fa<\/strong>.<\/li>\n\n\n\n<li>Integra categor\u00edas desde el men\u00fa desplegable.<\/li>\n\n\n\n<li>Introduzca las descripciones de los elementos del men\u00fa yendo a <strong>Descripci\u00f3n de las opciones &gt; de pantalla<\/strong>.<\/li>\n<\/ul>\n\n<p>Con el personalizador de WordPress, tambi\u00e9n puede cambiar muchos elementos de estilo y configuraciones de men\u00fa. Piensa en fuentes, superposiciones de fondo y dimensiones. <\/p>\n\n<p>Tambi\u00e9n puede editar las opciones del men\u00fa desde el editor del sitio. Vaya al <strong>Editor de apariencia&gt;<\/strong>, seleccione <strong>Vista de lista<\/strong> y haga clic en el <strong>bloque de navegaci\u00f3n<\/strong>. Ve a la secci\u00f3n <strong>Configuraci\u00f3n<\/strong> y haz clic en <strong>Estilos<\/strong>, luego personaliza.  <\/p>\n\n<p>Con este m\u00e9todo, tambi\u00e9n puede administrar ubicaciones. Cambie la ubicaci\u00f3n del men\u00fa haciendo clic en <strong>Vista de lista<\/strong> y, a continuaci\u00f3n, arrastre y suelte el <strong>bloque de navegaci\u00f3n<\/strong> en la p\u00e1gina de inicio. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-restructure-menus\">C\u00f3mo reestructurar los men\u00fas<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-1024x608.png\" alt=\"C&#xF3;mo reestructurar men&#xFA;s.\" class=\"wp-image-45951\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-1024x608.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-300x178.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-768x456.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-36x21.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Restructure-Wordpress-Menu-July-2023-48x28.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\">Captura de pantalla del entorno de prueba\n<\/figcaption><\/figure>\n\n<p>Una estructura de men\u00fa optimizada es clave para optimizar el rendimiento de su sitio web.<\/p>\n\n<p>Si has a\u00f1adido categor\u00edas a tus men\u00fas, tu estructura ya ser\u00e1 m\u00e1s f\u00e1cil de navegar. Pero para mejorarlo a\u00fan m\u00e1s, piense desde la perspectiva del usuario para determinar qu\u00e9 marco es el ideal. <\/p>\n\n<p>A continuaci\u00f3n, puedes implementar un <strong>men\u00fa de anidamiento<\/strong> : un men\u00fa desplegable de WordPress que proporciona una estructura optimizada.<\/p>\n\n<p>Si tu men\u00fa no tiene autom\u00e1ticamente un dise\u00f1o desplegable:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Utilice el editor del sitio:<\/strong> Vaya a <strong>Editor de apariencia &gt;<\/strong> y seleccione <strong>Vista de lista<\/strong>. Haga clic en el <strong>bloque de navegaci\u00f3n <\/strong>y coloque el cursor sobre los elementos del men\u00fa. Seleccione los tres puntos y haga clic en <strong>Agregar submen\u00fa<\/strong>.  <\/li>\n\n\n\n<li><strong>Usa el editor de men\u00fas de administraci\u00f3n<\/strong>: Ve a <strong>Men\u00fas de apariencia &gt;<\/strong> y agrega submen\u00fas a tu men\u00fa principal. Para ello, arrastre los elementos debajo de otros en el lado derecho de la lista. Se convertir\u00e1n autom\u00e1ticamente en subelementos y formar\u00e1n submen\u00fas.  <\/li>\n\n\n\n<li><strong>Utilice el personalizador:<\/strong> Vaya a <strong>Men\u00fas personalizados &gt; de apariencia&gt;<\/strong>, seleccione <strong>Reordenar<\/strong> y haga clic en la flecha derecha junto a los elementos. Esto \u00abanidar\u00e1\u00bb los art\u00edculos. <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-delete-menu-items\">C\u00f3mo eliminar elementos del men\u00fa<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"982\" height=\"493\" src=\"https:\/\/www.bluehost.com\/es-es\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023.png\" alt=\"C&#xF3;mo eliminar elementos del men&#xFA;.\" class=\"wp-image-45949\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023.png 982w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023-300x151.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023-768x386.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023-36x18.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Delete-Menu-Items-on-Wordpress-July-2023-48x24.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Captura de pantalla del entorno de prueba<\/em><br\/><\/figcaption><\/figure>\n\n<p>El Instituto Baymard descubri\u00f3 que <a href=\"https:\/\/baymard.com\/blog\/ecommerce-navigation-best-practice\" target=\"_blank\" rel=\"noreferrer noopener\">la mayor\u00eda de los usuarios se sienten abrumados<\/a> cuando un men\u00fa tiene m\u00e1s de 10 subcategor\u00edas. As\u00ed que aseg\u00farate de que tu men\u00fa no tenga demasiados elementos. <\/p>\n\n<p>En primer lugar, identifique los elementos de men\u00fa innecesarios que desea eliminar. A continuaci\u00f3n, puedes: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Utilice el editor del sitio:<\/strong> Siga los mismos pasos para crear un men\u00fa desplegable, pero seleccione <strong>Eliminar<\/strong> en lugar de <strong>Agregar submen\u00fa.<\/strong><\/li>\n\n\n\n<li><strong>Utilice el editor del men\u00fa de administraci\u00f3n<\/strong>: Vaya a <strong>Men\u00fas de apariencia&gt;<\/strong>. Localice el elemento que desea eliminar, haga clic en la flecha hacia abajo correspondiente a ese elemento y seleccione Eliminar. <\/li>\n\n\n\n<li><strong>Utilice el personalizador<\/strong>: Vaya a <strong>Men\u00fas de personalizaci\u00f3n &gt; de apariencia &gt;<\/strong> y siga el mismo proceso que con el editor de men\u00fa de administraci\u00f3n.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-final-thoughts-how-to-manage-menus-in-wordpress-a-bluehost-guide\">Reflexiones finales: C\u00f3mo administrar men\u00fas en WordPress | Una gu\u00eda de Bluehost<\/h2>\n\n<p>WordPress es una plataforma f\u00e1cil de usar que ofrece muchas opciones para optimizar los men\u00fas. Al aprovechar estas opciones, puede mejorar su sitio web de WordPress. <\/p>\n\n<p>\u00bfBusca <a href=\"https:\/\/www.bluehost.com\/hosting\">servicios de alojamiento de alta calidad<\/a> que vengan con soporte 24\/7\/365? <a href=\"https:\/\/www.bluehost.com\/contact\">Contacta con nuestro equipo de Bluehost<\/a>.<\/p>\n\n<p>Ofrecemos <a href=\"https:\/\/www.bluehost.com\/wordpress\">alojamiento de WordPress a la velocidad del rayo<\/a>, <a href=\"https:\/\/www.bluehost.com\/solutions\/website-design\">servicios de dise\u00f1o web<\/a> y mucho m\u00e1s.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-faqs-about-how-to-manage-menus-in-wordpress\">Preguntas frecuentes sobre c\u00f3mo administrar men\u00fas en WordPress<\/h2>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1689485988505\"><strong class=\"schema-faq-question\">\u00bfC\u00f3mo cambio la clase de men\u00fa en WordPress?<\/strong> <p class=\"schema-faq-answer\">En el administrador de WP, vaya a <strong>Apariencia &gt; Personalizar &gt; men\u00fas<\/strong> y haga clic en el icono de configuraci\u00f3n. A continuaci\u00f3n, puede marcar la casilla <strong>de verificaci\u00f3n Clases CSS<\/strong> y escribir una clase CSS. Con el Editor del sitio, vaya a <strong>Editor de &gt; de apariencia<\/strong> y luego a la secci\u00f3n <strong>Configuraci\u00f3n avanzada<\/strong> del bloque de <strong>navegaci\u00f3n<\/strong>.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1689486023193\"><strong class=\"schema-faq-question\">\u00bfC\u00f3mo puedo crear un men\u00fa personalizado en WordPress?<\/strong> <p class=\"schema-faq-answer\">Puede crear men\u00fas personalizados con el Editor del sitio agregando un bloque de <strong>navegaci\u00f3n<\/strong> o a trav\u00e9s del administrador de WP o el Personalizador seleccionando <strong>Crear men\u00fa<\/strong>. Puedes crear m\u00e1s men\u00fas a trav\u00e9s de un widget de men\u00fa de WordPress. En algunos casos, tambi\u00e9n puede agregar uno manualmente mediante codificaci\u00f3n.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1689486158410\"><strong class=\"schema-faq-question\">\u00bfCu\u00e1l es el l\u00edmite del men\u00fa en WordPress?<\/strong> <p class=\"schema-faq-answer\">Los servidores suelen tener un l\u00edmite de 90-100 elementos de men\u00fa de WordPress. Si bien eso es m\u00e1s que suficiente para la mayor\u00eda de los sitios web, puede modificar el l\u00edmite editando la configuraci\u00f3n del cPanel o el <a href=\"https:\/\/www.geeksforgeeks.org\/what-is-the-purpose-of-php-ini-file\/\" target=\"_blank\" rel=\"noreferrer noopener\">archivo PHP.ini<\/a> a trav\u00e9s de la codificaci\u00f3n. Es posible que tu <a href=\"https:\/\/www.bluehost.com\/hosting\">proveedor de alojamiento<\/a> pueda ayudarte con esto.  <\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>WordPress ofrece una amplia variedad de funciones para crear un sitio web de primer nivel, incluidas opciones para crear y personalizar men\u00fas de navegaci\u00f3n. Crear men\u00fas es relativamente sencillo. Y una vez que aprendas a administrar men\u00fas en WordPress, incluso puedes crear men\u00fas personalizados optimizados. Este conocimiento es invaluable, ya que la navegaci\u00f3n optimizada puede [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":124690,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Administrar men\u00fas de sitios web y trabajar con widgets | Anfitri\u00f3n azul","_yoast_wpseo_metadesc":"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.","inline_featured_image":false,"footnotes":""},"categories":[3093,1365],"tags":[3659,3672,3675,3685],"ppma_author":[588],"class_list":["post-124685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno","category-wordpress-en-ingles","tag-cms","tag-guias-practicas","tag-navegacion","tag-tutoriales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Administrar men\u00fas de sitios web y trabajar con widgets | Anfitri\u00f3n azul<\/title>\n<meta name=\"description\" content=\"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/124685\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una gu\u00eda para crear y administrar men\u00fas de WordPress\" \/>\n<meta property=\"og:description\" content=\"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T12:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T04:29:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tiffani Anderson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/TiffAnddd\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiffani Anderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\"},\"author\":{\"name\":\"Tiffani Anderson\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66\"},\"headline\":\"Una gu\u00eda para crear y administrar men\u00fas de WordPress\",\"datePublished\":\"2023-08-18T12:25:00+00:00\",\"dateModified\":\"2025-02-24T04:29:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\"},\"wordCount\":1581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png\",\"keywords\":[\"CMS\",\"Gu\u00edas pr\u00e1cticas\",\"Navegaci\u00f3n\",\"Tutoriales\"],\"articleSection\":[\"Dise\u00f1o\",\"WordPress (en ingl\u00e9s)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#respond\"]}]},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\",\"name\":\"Administrar men\u00fas de sitios web y trabajar con widgets | Anfitri\u00f3n azul\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png\",\"datePublished\":\"2023-08-18T12:25:00+00:00\",\"dateModified\":\"2025-02-24T04:29:36+00:00\",\"description\":\"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193\"},{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sitios web\",\"item\":\"https:\/\/www.bluehost.com\/blog\/es\/category\/sitios-web\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una gu\u00eda para crear y administrar men\u00fas de WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66\",\"name\":\"Tiffani Anderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/1f8eaab88872e9aa519335532a3a886e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g\",\"caption\":\"Tiffani Anderson\"},\"description\":\"Tiffani is a Content and SEO Manager for the Bluehost brand. With over 10 years experience across all facets of content and brand marketing, she strives to combine concepts from brand marketing with engaging content through the lens of SEO.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/tiffaninanderson\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/TiffAnddd\"],\"knowsAbout\":[\"Search Engine Optimization\",\"Content Marketing\",\"Brand Marketing\"],\"knowsLanguage\":[\"English\"],\"jobTitle\":\"SEO and Content Manager\",\"worksFor\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/tiffani\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505\",\"position\":1,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505\",\"name\":\"How do I change the menu class in WordPress?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"In the WP admin, navigate to <strong>Appearance > Customize > Menus<\/strong> and click the settings icon. Then you can check the <strong>CSS Classes<\/strong> checkbox and type in a CSS class. With the Site Editor, go to <strong>Appearance > Editor<\/strong> and then the <strong>Advanced Settings<\/strong> section of the <strong>Navigation Block<\/strong>.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193\",\"position\":2,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193\",\"name\":\"How do I create a custom menu in WordPress?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"You can create custom menus with the Site Editor by adding a <strong>Navigation Block<\/strong> or through the WP admin or Customizer by selecting <strong>Create Menu<\/strong>. You can build more menus through a WordPress menu widget. In some cases, you can also add one manually by coding.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410\",\"position\":3,\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410\",\"name\":\"What is the menu limit in WordPress?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Servers usually have a limit of 90-100 WordPress menu items. While that\u2019s more than enough items for most websites, you can alter the limit by editing the cPanel settings or the <a href=\\\"https:\/\/www.geeksforgeeks.org\/what-is-the-purpose-of-php-ini-file\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">PHP.ini file<\/a> through coding. Your <a href=\\\"https:\/\/www.bluehost.com\/hosting\\\">hosting provider<\/a> may be able to help you with this.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Administrar men\u00fas de sitios web y trabajar con widgets | Anfitri\u00f3n azul","description":"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/124685\/","og_locale":"es_ES","og_type":"article","og_title":"Una gu\u00eda para crear y administrar men\u00fas de WordPress","og_description":"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.","og_url":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2023-08-18T12:25:00+00:00","article_modified_time":"2025-02-24T04:29:36+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png","type":"image\/png"}],"author":"Tiffani Anderson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/TiffAnddd","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Tiffani Anderson","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/"},"author":{"name":"Tiffani Anderson","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66"},"headline":"Una gu\u00eda para crear y administrar men\u00fas de WordPress","datePublished":"2023-08-18T12:25:00+00:00","dateModified":"2025-02-24T04:29:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/"},"wordCount":1581,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png","keywords":["CMS","Gu\u00edas pr\u00e1cticas","Navegaci\u00f3n","Tutoriales"],"articleSection":["Dise\u00f1o","WordPress (en ingl\u00e9s)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/","url":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/","name":"Administrar men\u00fas de sitios web y trabajar con widgets | Anfitri\u00f3n azul","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png","datePublished":"2023-08-18T12:25:00+00:00","dateModified":"2025-02-24T04:29:36+00:00","description":"Los men\u00fas de los sitios web parecen una caracter\u00edstica bastante simple dentro de WordPress, pero a menudo causan una confusi\u00f3n innecesaria si un usuario no los organiza.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193"},{"@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2019\/03\/Managing-Menu-in-Wordpress.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"Sitios web","item":"https:\/\/www.bluehost.com\/blog\/es\/category\/sitios-web\/"},{"@type":"ListItem","position":3,"name":"Una gu\u00eda para crear y administrar men\u00fas de WordPress"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66","name":"Tiffani Anderson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/1f8eaab88872e9aa519335532a3a886e","url":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","caption":"Tiffani Anderson"},"description":"Tiffani is a Content and SEO Manager for the Bluehost brand. With over 10 years experience across all facets of content and brand marketing, she strives to combine concepts from brand marketing with engaging content through the lens of SEO.","sameAs":["https:\/\/www.linkedin.com\/in\/tiffaninanderson\/","https:\/\/x.com\/https:\/\/twitter.com\/TiffAnddd"],"knowsAbout":["Search Engine Optimization","Content Marketing","Brand Marketing"],"knowsLanguage":["English"],"jobTitle":"SEO and Content Manager","worksFor":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/author\/tiffani\/"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505","position":1,"url":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689485988505","name":"How do I change the menu class in WordPress?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"In the WP admin, navigate to <strong>Appearance > Customize > Menus<\/strong> and click the settings icon. Then you can check the <strong>CSS Classes<\/strong> checkbox and type in a CSS class. With the Site Editor, go to <strong>Appearance > Editor<\/strong> and then the <strong>Advanced Settings<\/strong> section of the <strong>Navigation Block<\/strong>.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193","position":2,"url":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486023193","name":"How do I create a custom menu in WordPress?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"You can create custom menus with the Site Editor by adding a <strong>Navigation Block<\/strong> or through the WP admin or Customizer by selecting <strong>Create Menu<\/strong>. You can build more menus through a WordPress menu widget. In some cases, you can also add one manually by coding.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410","position":3,"url":"https:\/\/www.bluehost.com\/blog\/es\/una-guia-para-crear-y-administrar-menus-de-wordpress\/#faq-question-1689486158410","name":"What is the menu limit in WordPress?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Servers usually have a limit of 90-100 WordPress menu items. While that\u2019s more than enough items for most websites, you can alter the limit by editing the cPanel settings or the <a href=\"https:\/\/www.geeksforgeeks.org\/what-is-the-purpose-of-php-ini-file\/\" target=\"_blank\" rel=\"noreferrer noopener\">PHP.ini file<\/a> through coding. Your <a href=\"https:\/\/www.bluehost.com\/hosting\">hosting provider<\/a> may be able to help you with this.","inLanguage":"es"},"inLanguage":"es"}]}},"authors":[{"term_id":588,"user_id":50,"is_guest":0,"slug":"tiffani","display_name":"Tiffani Anderson","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/124685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=124685"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/124685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/124690"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=124685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=124685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=124685"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=124685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}