{"id":128324,"date":"2022-03-30T06:21:15","date_gmt":"2022-03-30T06:21:15","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/como-anadir-paginas-e-imagenes-en-wordpress\/"},"modified":"2025-03-03T05:48:55","modified_gmt":"2025-03-03T05:48:55","slug":"como-anadir-paginas-e-imagenes-en-wordpress","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/","title":{"rendered":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress"},"content":{"rendered":"\n<p>Quieres un sitio web para tu negocio. Elegiste un nombre de dominio, elegiste un tema de WordPress y est\u00e1s listo para crear un hermoso sitio web. Afortunadamente, WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear el sitio web de tus sue\u00f1os. Entonces, \u00bfpor d\u00f3nde empezar? En este blog, te ense\u00f1aremos c\u00f3mo agregar una p\u00e1gina y llenarla de contenido. \u00a1As\u00ed que sigue leyendo!     <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-gutenberg-block-editor\">Editor de bloques de Gutenberg<\/h2>\n\n<p>Antes de sumergirnos en el <a href=\"https:\/\/bhmultisite.com\/resources\/wordpress-dashboard-walkthrough\/\">backend de tu sitio web<\/a>, veamos con qu\u00e9 est\u00e1s trabajando. Cuando est\u00e1s trabajando en una p\u00e1gina en WordPress, est\u00e1s trabajando con el Editor de Bloques de Gutenberg. Esta es informaci\u00f3n \u00fatil, porque si alguna vez necesita buscar consejos o trucos, eso es lo que debe escribir en la barra de b\u00fasqueda.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-add-a-page-in-wordpress\">C\u00f3mo a\u00f1adir una p\u00e1gina en WordPress<\/h2>\n\n<p>Lo primero es lo primero: entra en el backend de tu sitio web. Para hacer esto, escriba la URL de su sitio web, agregue \/wp-admin en la barra de b\u00fasqueda e inicie sesi\u00f3n. Si ve la p\u00e1gina como se muestra en la imagen a continuaci\u00f3n, \u00a1est\u00e1 listo para comenzar!  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"521\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog1-1024x521.png\" alt=\"\" class=\"wp-image-38333\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog1-1024x521.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog1-300x153.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog1-768x391.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Ahora, mira la barra lateral negra de la izquierda. Ver\u00e1s la palabra &#8216;P\u00e1ginas&#8217;. Si pasas el cursor sobre &#8216;P\u00e1ginas&#8217;, obtendr\u00e1s un peque\u00f1o men\u00fa. Elija la segunda opci\u00f3n: &#8216;Agregar nuevo&#8217;.   <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"498\" height=\"552\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog2.png\" alt=\"\" class=\"wp-image-38336\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog2.png 498w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog2-271x300.png 271w\" sizes=\"100vw\" \/><\/figure><\/div>\n\n<p>\u00a1Ta-da! Has a\u00f1adido una nueva p\u00e1gina. Ahora viene la parte divertida: rellenarlo y convertirlo en una hermosa p\u00e1gina.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-title-of-your-page\">T\u00edtulo de la p\u00e1gina<\/h3>\n\n<p>Lo primero que ves cuando a\u00f1ades una nueva p\u00e1gina es el texto &#8216;A\u00f1adir t\u00edtulo&#8217;. Aqu\u00ed es donde puedes a\u00f1adir el t\u00edtulo de la p\u00e1gina. Si esta es tu p\u00e1gina \u00abAcerca de\u00bb, podr\u00edas llamarla \u00abAcerca de m\u00ed\u00bb. Te recomendamos que no hagas que los t\u00edtulos de las p\u00e1ginas sean demasiado largos. Deben ser claros y concisos. Deje que sus visitantes sepan en pocas palabras lo que pueden esperar encontrar en esta p\u00e1gina.     <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-slug-and-description-of-your-page\">Slug y descripci\u00f3n de tu p\u00e1gina<\/h3>\n\n<p>Las no solo se encuentran en el jard\u00edn. \u00a1Tambi\u00e9n son una parte esencial de los sitios web! El slug es parte de la URL. Identifica una p\u00e1gina concreta de tu sitio web. Por ejemplo, si est\u00e1 en el <a href=\"https:\/\/www.bluehost.com\/\">sitio web de Bluehost<\/a> y hace clic en el encabezado &#8216;Dominios&#8217;, la URL dir\u00e1: bluehost.com\/domains. \u00a1Lo que viene despu\u00e9s del corte, es la! Tambi\u00e9n puede ser varias palabras, como \/ideas-de-contenido-para-su-sitio web.      <\/p>\n\n<p>Te recomendamos que no hagas tu demasiado larga. Si lo deseas, puedes editar tu slug cuando est\u00e9s creando o editando una p\u00e1gina. Encontrar\u00e1s esta informaci\u00f3n a la derecha. Est\u00e1 debajo del encabezado &#8216;Enlace permanente&#8217;.   <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"517\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog3-1024x517.png\" alt=\"\" class=\"wp-image-38339\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog3-1024x517.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog3-300x152.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog3-768x388.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-make-a-page-your-homepage\">C\u00f3mo hacer que una p\u00e1gina sea tu p\u00e1gina de inicio<\/h3>\n\n<p>Una p\u00e1gina de inicio suele ser la primera p\u00e1gina que ve tu audiencia cuando visita tu sitio web. Se podr\u00eda decir que es la portada. Para configurar su p\u00e1gina de inicio, vaya a &#8216;Configuraci\u00f3n&#8217;. Lo encontrar\u00e1s en el men\u00fa de la izquierda de tu panel de control. Coloca el cursor sobre &#8216;Configuraci\u00f3n&#8217; hasta que veas el men\u00fa, luego haz clic en &#8216;Lectura&#8217;.    <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"479\" height=\"698\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog4.png\" alt=\"\" class=\"wp-image-38342\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog4.png 479w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog4-206x300.png 206w\" sizes=\"100vw\" \/><\/figure><\/div>\n\n<p>Cuando mire la p\u00e1gina Configuraci\u00f3n de lectura, ver\u00e1 &#8216;Pantallas de su p\u00e1gina de inicio&#8217;. Selecciona &#8216;Una p\u00e1gina est\u00e1tica&#8217;. <\/p>\n\n<p>Ahora es el momento de seleccionar tu p\u00e1gina de inicio. Hay un men\u00fa desplegable junto a &#8216;P\u00e1gina de inicio&#8217;. Aqu\u00ed, puede elegir qu\u00e9 p\u00e1gina le gustar\u00eda seleccionar como su p\u00e1gina de inicio.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"658\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog5-1024x658.png\" alt=\"\" class=\"wp-image-38345\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog5-1024x658.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog5-300x193.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog5-768x494.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Despu\u00e9s de seleccionar la p\u00e1gina correcta, \u00a1no olvide guardar los cambios! Ahora, esta p\u00e1gina se mostrar\u00e1 como su nueva p\u00e1gina de inicio. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-fill-a-page-on-wordpress\">Llenar una p\u00e1gina en WordPress<\/h2>\n\n<p>\u00a1Felicidades! Ahora ya sabes c\u00f3mo a\u00f1adir una p\u00e1gina y convertirla en tu p\u00e1gina de inicio. Has dado el primer paso para crear un hermoso sitio web para tu negocio. Lo siguiente: llenar tu sitio web de contenido. El editor de bloques de WordPress tiene muchas caracter\u00edsticas \u00fatiles, tambi\u00e9n conocidas como &#8216;bloques&#8217;. \u00a1Son muy f\u00e1ciles de usar! Te lo mostraremos.      <\/p>\n\n<p>Volvamos a la p\u00e1gina vac\u00eda que creaste. Hay dos formas de acceder a los bloques. Lo m\u00e1s f\u00e1cil es hacer clic en el gran signo m\u00e1s en la esquina superior izquierda de la pantalla.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"444\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog6-1-1024x444.png\" alt=\"\" class=\"wp-image-38351\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog6-1-1024x444.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog6-1-300x130.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog6-1-768x333.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Se abrir\u00e1 un men\u00fa que muestra todos los bloques disponibles que puedes usar en tu p\u00e1gina. Te recomendamos que te desplaces por las opciones y pruebes algunas. Despu\u00e9s de todo, a menos que hagas clic en &#8216;publicar&#8217;, \u00a1tu p\u00e1gina a\u00fan no est\u00e1 activa!  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"823\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog7-1024x823.png\" alt=\"\" class=\"wp-image-38354\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog7-1024x823.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog7-300x241.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog7-768x617.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>En este blog, nos centraremos en los bloques m\u00e1s utilizados.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-heading\">Encabezado<\/h3>\n\n<p>En el men\u00fa de bloques, encontrar\u00e1s \u00abEncabezado\u00bb en la categor\u00eda Texto. Los encabezados son una excelente manera de dividir tu p\u00e1gina. Introducen un nuevo (sub)tema o categor\u00eda, y hacen que su p\u00e1gina est\u00e9 m\u00e1s organizada.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog8-2-1024x730.png\" alt=\"\" class=\"wp-image-38363\"\/><\/figure>\n\n<p>Cuando haga clic en &#8216;Encabezado&#8217;, le dar\u00e1 espacio para escribir su texto. Puede poner el texto en negrita o cursiva, utilizando el peque\u00f1o men\u00fa que aparece encima del encabezado. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"845\" height=\"473\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog9-1.png\" alt=\"\" class=\"wp-image-38369\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog9-1.png 845w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog9-1-300x168.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog9-1-768x430.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Los encabezados son una excelente manera para que las personas entiendan su sitio web. Sin embargo, hay algunas buenas pr\u00e1cticas cuando se trata de encabezados, para asegurarse de que <em>todos<\/em> puedan disfrutar de su sitio web. <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-accessibility\" style=\"font-size:clamp(15.747px, 0.984rem + ((1vw - 3.2px) * 0.715), 24px);\">Accesibilidad<\/h4>\n\n<p>Hay varias opciones de encabezado. Al hacer clic en el bloque &#8216;Encabezado&#8217;, el valor predeterminado es H2. \u00a1Pero tambi\u00e9n hay H3, H4, H5 e incluso H6!  <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"845\" height=\"522\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog11.png\" alt=\"\" class=\"wp-image-38375\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog11.png 845w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog11-300x185.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog11-768x474.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Los diferentes encabezados var\u00edan en tama\u00f1o, pero eso no es todo. Tambi\u00e9n var\u00edan en importancia. El ep\u00edgrafe m\u00e1s importante es H2. Util\u00edzalo si quieres introducir un nuevo tema o categor\u00eda. H3 se utiliza para una subcategor\u00eda relacionada con H2. Si desea agregar una subcategor\u00eda dentro de H3, use H4. Y as\u00ed sucesivamente. En conclusi\u00f3n: los n\u00fameros se utilizan para indicar si se trata de un tema nuevo o de un tema relacionado.       <\/p>\n\n<p>Es importante que utilices los encabezados en el orden correcto. De lo contrario, las personas con discapacidad visual que utilizan lectores de pantalla no entender\u00e1n su sitio web. <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-change-the-size-of-your-heading\" style=\"font-size:clamp(15.747px, 0.984rem + ((1vw - 3.2px) * 0.715), 24px);\">Cambia el tama\u00f1o de tu encabezado<\/h4>\n\n<p>\u00bfQu\u00e9 pasa si quieres comenzar una nueva categor\u00eda, pero no te gusta lo grande que es H2? \u00a1No te preocupes! Puedes arreglar eso f\u00e1cilmente. A la derecha de la pantalla, tienes un peque\u00f1o men\u00fa con dos categor\u00edas: &#8216;P\u00e1gina&#8217; y &#8216;Bloquear&#8217;. Elija &#8216;Bloquear&#8217;.    <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"353\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog12-1024x353.png\" alt=\"\" class=\"wp-image-38378\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog12-1024x353.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog12-300x103.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog12-768x265.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>\u00a1Bien! Si ha seleccionado la secci\u00f3n Encabezado que desea cambiar, deber\u00eda ver lo siguiente: <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"282\" height=\"576\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog13.png\" alt=\"\" class=\"wp-image-38381\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog13.png 282w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog13-147x300.png 147w\" sizes=\"100vw\" \/><\/figure><\/div>\n\n<p>Ahora, ve a &#8216;Tipograf\u00eda&#8217;. Aqu\u00ed, puedes cambiar el tama\u00f1o de la fuente. Deber\u00eda decir &#8216;predeterminado&#8217;, \u00a1pero puede cambiarlo f\u00e1cilmente a otro tama\u00f1o! Como puede ver en la imagen de arriba, var\u00eda de peque\u00f1o (1) a grande (4).   <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-paragraph\">P\u00e1rrafo<\/h3>\n\n<p>En el editor de bloques de Gutenberg, un p\u00e1rrafo es donde escribes la mayor parte de tu contenido. Agregar un p\u00e1rrafo es realmente f\u00e1cil. Al pulsar Intro, se a\u00f1adir\u00e1 autom\u00e1ticamente otro p\u00e1rrafo a la p\u00e1gina. \u00a1Puedes empezar a escribir de inmediato!   <\/p>\n\n<p>Tan pronto como escribas la primera letra, aparecer\u00e1 un peque\u00f1o men\u00fa. Esto le permite poner en negrita, cursiva o agregar un enlace a su texto. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"614\" height=\"363\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog14.png\" alt=\"\" class=\"wp-image-38384\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog14.png 614w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog14-300x177.png 300w\" sizes=\"100vw\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"h-quote\">Citar<\/h3>\n\n<p>Agregar una cita a su p\u00e1gina puede ser una excelente manera de agregar credibilidad. Puedes citar una rese\u00f1a que otra persona haya dejado de tu servicio o producto. \u00a1A la gente le encanta leer rese\u00f1as! Pero tambi\u00e9n es una herramienta \u00fatil para resaltar algo que dijiste en tu p\u00e1gina \u00abAcerca de\u00bb. Puedes encontrar &#8216;Cita&#8217; en la categor\u00eda &#8216;Texto&#8217;.    <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-create-a-call-to-action-button\">C\u00f3mo crear un bot\u00f3n de llamada a la acci\u00f3n<\/h3>\n\n<p>Veamos algo un poco diferente: agregar un bot\u00f3n de llamada a la acci\u00f3n. En primer lugar, \u00bfqu\u00e9 es? Es un bot\u00f3n que pide a la gente que haga algo, por ejemplo, <em>\u00a1c\u00f3mpralo ahora!<\/em> Cuando las personas hagan clic en el bot\u00f3n, ser\u00e1n dirigidas a una p\u00e1gina de su elecci\u00f3n. Es muy \u00fatil para guiar a las personas a donde quieres que vayan. Adem\u00e1s, un bot\u00f3n puede facilitar que las personas encuentren r\u00e1pidamente lo que buscan.    <\/p>\n\n<p>Primero, abra el men\u00fa Bloquear. Puede usar la barra de b\u00fasqueda para buscar &#8216;Botones&#8217;, o puede desplazarse hacia abajo hasta la categor\u00eda &#8216;Dise\u00f1o&#8217; y hacer clic en la opci\u00f3n &#8216;Botones&#8217; all\u00ed. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog15-1024x668.png\" alt=\"\" class=\"wp-image-38387\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog15-1024x668.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog15-300x196.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog15-768x501.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Ahora, tienes un bot\u00f3n vac\u00edo sin texto que no lleva a la gente a ninguna parte. \u00a1Cambiemos eso! Al hacer clic en el bot\u00f3n vac\u00edo, puede escribir el texto que desea que aparezca en el bot\u00f3n.  <\/p>\n\n<p>A continuaci\u00f3n, desea darle un enlace al bot\u00f3n. Haz clic en el bot\u00f3n que acabas de a\u00f1adir. Aparecer\u00e1 un peque\u00f1o men\u00fa. Haga clic en el icono del enlace y, a continuaci\u00f3n, a\u00f1ada el enlace al que desea que lleve este bot\u00f3n. \u00a1Y voil\u00e0! El bot\u00f3n funciona.     <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"677\" height=\"381\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog16.png\" alt=\"\" class=\"wp-image-38393\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog16.png 677w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog16-300x169.png 300w\" sizes=\"100vw\" \/><\/figure>\n\n<p>\u00bfY si quieres cambiar el color? Sencillo. Haga clic en los tres puntos en el men\u00fa emergente, luego elija &#8216;Mostrar m\u00e1s configuraciones&#8217;. Ver\u00e1s un men\u00fa a la derecha con muchas opciones, incluido el color. Aqu\u00ed, puede cambiar el color del texto y el bot\u00f3n en s\u00ed (fondo).      <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog17-1024x705.png\" alt=\"\" class=\"wp-image-38396\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog17-1024x705.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog17-300x207.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog17-768x529.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-add-an-image-in-wordpress\">C\u00f3mo a\u00f1adir una imagen en WordPress<\/h2>\n\n<p>Desea que las personas permanezcan comprometidas cuando visiten su sitio web. Es por eso que es una buena idea incluir im\u00e1genes en tu p\u00e1gina. La mayor\u00eda de las personas est\u00e1n muy orientadas visualmente, por lo que agregar im\u00e1genes relevantes respaldar\u00e1 su mensaje. \u00a1Sin mencionar que es una excelente manera de mostrar sus productos!   <\/p>\n\n<p><strong>S.o<\/strong>., \u00bfc\u00f3mo se a\u00f1ade una imagen en WordPress? Haz clic en el signo m\u00e1s grande en la esquina superior izquierda de la pantalla. Despl\u00e1zate hacia abajo hasta la categor\u00eda \u00abMedios\u00bb y haz clic en \u00abImagen\u00bb.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog18-1-1024x592.png\" alt=\"\" class=\"wp-image-38402\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog18-1-1024x592.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog18-1-300x173.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog18-1-768x444.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Ver\u00e1s un gran bot\u00f3n azul con la palabra &#8216;subir&#8217;. Aqu\u00ed, puede cargar cualquier imagen que desee incluir en la p\u00e1gina. <\/p>\n\n<p>Si desea cambiar la ubicaci\u00f3n de la imagen, haga clic en el icono &#8216;Cambiar alineaci\u00f3n&#8217;.  <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"819\" height=\"461\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog19.png\" alt=\"\" class=\"wp-image-38405\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog19.png 819w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog19-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog19-768x432.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Siempre puedes hacer clic en los tres puntos y seleccionar &#8216;Mostrar m\u00e1s configuraciones&#8217;. Haga clic en las m\u00faltiples opciones y vea qu\u00e9 se ve mejor. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-alt-text\">Texto alternativo<\/h3>\n\n<p>Antes de explicar c\u00f3mo a\u00f1adir texto alternativo, es bueno saber qu\u00e9 es el texto alternativo y por qu\u00e9 es importante a\u00f1adirlo a tus im\u00e1genes. El texto alternativo explica el aspecto de una imagen. No tiene por qu\u00e9 ser largo. Por ejemplo, <em>un perro corre por un campo con un palo grande en la boca<\/em> es suficiente.   <\/p>\n\n<p>Para las personas con discapacidad visual, esta explicaci\u00f3n es realmente importante, porque los lectores de pantalla leen el texto alternativo en voz alta. Al incluir un buen texto alternativo, mejoras la accesibilidad de tu sitio web. \u00a1Ahora todo el mundo podr\u00e1 disfrutar de tu sitio web!  <\/p>\n\n<p>Pero no son solo los lectores de pantalla los que leen el texto alternativo. Los motores de b\u00fasqueda como Google tambi\u00e9n utilizan esta informaci\u00f3n para comprender el contexto de una imagen. \u00a1Lo que a su vez podr\u00eda ayudar a que su p\u00e1gina se clasifique mejor en Google!  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-add-alt-text-to-your-images-in-wordpress\">C\u00f3mo a\u00f1adir texto alternativo a tus im\u00e1genes en WordPress<\/h3>\n\n<p>Has a\u00f1adido una imagen a tu p\u00e1gina. Cuando seleccione la imagen, deber\u00eda ver un men\u00fa emergente. Haga clic en los tres puntos, luego elija &#8216;Mostrar m\u00e1s configuraciones&#8217;. Esto abrir\u00e1 un nuevo men\u00fa a la derecha.   <\/p>\n\n<p>Debajo del men\u00fa desplegable &#8216;Configuraci\u00f3n de imagen&#8217;, encontrar\u00e1s texto alternativo.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"645\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog20-1024x645.png\" alt=\"\" class=\"wp-image-38408\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog20-1024x645.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog20-300x189.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog20-768x484.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-add-an-image-with-text\">C\u00f3mo a\u00f1adir una imagen con texto<\/h3>\n\n<p>Hay dos formas de hacerlo. La primera: siga los pasos que se muestran arriba en &#8216;C\u00f3mo agregar una imagen&#8217;. Cuando agregues una imagen a tu p\u00e1gina, ver\u00e1s un peque\u00f1o texto debajo de tu imagen que dice &#8216;agregar subt\u00edtulo&#8217;. Puedes a\u00f1adir el t\u00edtulo de la imagen o los cr\u00e9ditos al fot\u00f3grafo\/ilustrador aqu\u00ed.   <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"763\" height=\"584\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog21.png\" alt=\"\" class=\"wp-image-38411\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog21.png 763w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog21-300x230.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog21-260x200.png 260w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog21-87x67.png 87w\" sizes=\"100vw\" \/><\/figure>\n\n<p>El segundo paso: usar otro bloque. Si busca a trav\u00e9s de la categor\u00eda &#8216;Medios&#8217;, ver\u00e1 la opci\u00f3n &#8216;Medios y texto&#8217;. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"654\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog22-1-1024x654.png\" alt=\"\" class=\"wp-image-38417\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog22-1-1024x654.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog22-1-300x191.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog22-1-768x490.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Cuando agregue esto, recibir\u00e1 un mensaje para cargar una imagen a la izquierda y un cuadro de texto vac\u00edo a la derecha.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"854\" height=\"433\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog23.png\" alt=\"\" class=\"wp-image-38420\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog23.png 854w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog23-300x152.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog23-768x389.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Si desea la imagen de la derecha, simplemente haga clic en el bloque y seleccione una ubicaci\u00f3n diferente en el men\u00fa emergente.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"389\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog24-1024x389.png\" alt=\"\" class=\"wp-image-38423\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog24-1024x389.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog24-300x114.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/bluehostblog24-768x291.png 768w\" sizes=\"100vw\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-endless-possibilities-in-wordpress\">Infinitas posibilidades en WordPress<\/h2>\n\n<p>\u00a1Felicidades! Has creado tu primera p\u00e1gina y has dado los primeros pasos para rellenarla. En este blog, te mostramos solo algunas posibilidades. Hay muchos m\u00e1s bloques disponibles para que los uses. Haga clic en las opciones y vea cu\u00e1l le gusta m\u00e1s. Si quieres m\u00e1s informaci\u00f3n sobre c\u00f3mo escribir contenido incre\u00edble para tu sitio web, lee nuestros <a href=\"https:\/\/www.bluehost.com\/es-es\/blog\/6-consejos-de-escritura-que-te-ayudaran-a-captar-la-atencion-de-tus-visitantes-2\/\">6 consejos de redacci\u00f3n<\/a>. \u00a1Buena suerte!      <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quieres un sitio web para tu negocio. Elegiste un nombre de dominio, elegiste un tema de WordPress y est\u00e1s listo para crear un hermoso sitio web. Afortunadamente, WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear el sitio web de tus sue\u00f1os. Entonces, \u00bfpor d\u00f3nde empezar? En este blog, te ense\u00f1aremos c\u00f3mo agregar una [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":128352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!","inline_featured_image":false,"footnotes":""},"categories":[3093,1365],"tags":[3659,3672,3685],"ppma_author":[592],"class_list":["post-128324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno","category-wordpress-en-ingles","tag-cms","tag-guias-practicas","tag-tutoriales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress - Bluehost Blog<\/title>\n<meta name=\"description\" content=\"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128324\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress\" \/>\n<meta property=\"og:description\" content=\"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T06:21:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-03T05:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bhmultisite.com\/content\/uploads\/sites\/3\/2022\/03\/Bluehost_OG_week_13.png\" \/>\n<meta name=\"author\" content=\"Devin Sears\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/DevinSears45842\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Devin Sears\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\"},\"author\":{\"name\":\"Devin Sears\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/3afe9d0188ad6b380b59aa10911f1e50\"},\"headline\":\"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress\",\"datePublished\":\"2022-03-30T06:21:15+00:00\",\"dateModified\":\"2025-03-03T05:48:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\"},\"wordCount\":2208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png\",\"keywords\":[\"CMS\",\"Gu\u00edas pr\u00e1cticas\",\"Tutoriales\"],\"articleSection\":[\"Dise\u00f1o\",\"WordPress (en ingl\u00e9s)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\",\"name\":\"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress - Bluehost Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png\",\"datePublished\":\"2022-03-30T06:21:15+00:00\",\"dateModified\":\"2025-03-03T05:48:55+00:00\",\"description\":\"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png\",\"width\":2400,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libros electr\u00f3nicos\",\"item\":\"https:\/\/www.bluehost.com\/blog\/es\/category\/libros-electronicos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/3afe9d0188ad6b380b59aa10911f1e50\",\"name\":\"Devin Sears\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/c58db4604c005b1ce37efa99465604c5\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3561264b7806b1f967a8dcbc7907681637719b76901f52ae90014c76da482d5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3561264b7806b1f967a8dcbc7907681637719b76901f52ae90014c76da482d5f?s=96&d=mm&r=g\",\"caption\":\"Devin Sears\"},\"description\":\"Devin is a Senior Event Marketing Manager for the Bluehost brand. He is our brand steward for all things Bluehost and WordPress. You'll always see him supporting Bluehost at WordCamps around the world!\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/devinsears\",\"https:\/\/x.com\/https:\/\/twitter.com\/DevinSears45842\"],\"knowsAbout\":[\"WordPress\",\"Event Marketing\",\"Field Marketing\"],\"knowsLanguage\":[\"English\"],\"jobTitle\":\"Senior Field Marketing Manager\",\"worksFor\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/devin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress - Bluehost Blog","description":"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128324\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress","og_description":"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!","og_url":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2022-03-30T06:21:15+00:00","article_modified_time":"2025-03-03T05:48:55+00:00","og_image":[{"url":"https:\/\/bhmultisite.com\/content\/uploads\/sites\/3\/2022\/03\/Bluehost_OG_week_13.png","type":"","width":"","height":""}],"author":"Devin Sears","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/DevinSears45842","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Devin Sears","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/"},"author":{"name":"Devin Sears","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/3afe9d0188ad6b380b59aa10911f1e50"},"headline":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress","datePublished":"2022-03-30T06:21:15+00:00","dateModified":"2025-03-03T05:48:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/"},"wordCount":2208,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png","keywords":["CMS","Gu\u00edas pr\u00e1cticas","Tutoriales"],"articleSection":["Dise\u00f1o","WordPress (en ingl\u00e9s)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/","url":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/","name":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress - Bluehost Blog","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png","datePublished":"2022-03-30T06:21:15+00:00","dateModified":"2025-03-03T05:48:55+00:00","description":"WordPress tiene toneladas de herramientas \u00fatiles para ayudarte a crear un hermoso sitio web. Pero, \u00bfpor d\u00f3nde empezar? \u00a1Lea este blog para obtener m\u00e1s informaci\u00f3n!","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2022\/03\/cad51e68-3792-4658-9ac4-49a6c7ce9323.png","width":2400,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/como-anadir-paginas-e-imagenes-en-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"Libros electr\u00f3nicos","item":"https:\/\/www.bluehost.com\/blog\/es\/category\/libros-electronicos\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo a\u00f1adir p\u00e1ginas e im\u00e1genes en WordPress"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/3afe9d0188ad6b380b59aa10911f1e50","name":"Devin Sears","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/c58db4604c005b1ce37efa99465604c5","url":"https:\/\/secure.gravatar.com\/avatar\/3561264b7806b1f967a8dcbc7907681637719b76901f52ae90014c76da482d5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3561264b7806b1f967a8dcbc7907681637719b76901f52ae90014c76da482d5f?s=96&d=mm&r=g","caption":"Devin Sears"},"description":"Devin is a Senior Event Marketing Manager for the Bluehost brand. He is our brand steward for all things Bluehost and WordPress. You'll always see him supporting Bluehost at WordCamps around the world!","sameAs":["https:\/\/www.linkedin.com\/in\/devinsears","https:\/\/x.com\/https:\/\/twitter.com\/DevinSears45842"],"knowsAbout":["WordPress","Event Marketing","Field Marketing"],"knowsLanguage":["English"],"jobTitle":"Senior Field Marketing Manager","worksFor":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/author\/devin\/"}]}},"authors":[{"term_id":592,"user_id":15,"is_guest":0,"slug":"devin","display_name":"Devin Sears","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/3561264b7806b1f967a8dcbc7907681637719b76901f52ae90014c76da482d5f?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=128324"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/128352"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=128324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=128324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=128324"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=128324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}