{"id":128570,"date":"2021-09-15T00:58:05","date_gmt":"2021-09-15T00:58:05","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/"},"modified":"2025-03-04T07:40:48","modified_gmt":"2025-03-04T07:40:48","slug":"impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/","title":{"rendered":"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google"},"content":{"rendered":"\n<p>En mayo de 2020, Google anunci\u00f3 que <a href=\"https:\/\/developers.google.com\/search\/blog\/2020\/05\/evaluating-page-experience\" target=\"_blank\" rel=\"noreferrer noopener\">lanzar\u00eda Page Experience<\/a>, una nueva actualizaci\u00f3n que prioriza la <a href=\"https:\/\/www.bluehost.com\/es-es\/blog\/experiencia-de-usuario-significado-importancia-y-como-el-contenido-ayuda-a-la-ux\/\">experiencia del usuario<\/a>.<\/p>\n\n<p>Google <a href=\"https:\/\/developers.google.com\/search\/blog\/2020\/11\/timing-for-page-experience\" target=\"_blank\" rel=\"noreferrer noopener\">comenz\u00f3 a implementar la actualizaci\u00f3n<\/a> en junio de 2021 y dijo que esperaba completarla en agosto de 2021. Despu\u00e9s de algunos retrasos, la actualizaci\u00f3n finalmente termin\u00f3 de implementarse el <a href=\"https:\/\/www.searchenginejournal.com\/google-page-experience-update-finished\/418506\/\" target=\"_blank\" rel=\"noreferrer noopener\">3 de septiembre de 2021<\/a>. <\/p>\n\n<p>Para una actualizaci\u00f3n significativa, el anuncio hecho a trav\u00e9s de Twitter no gener\u00f3 un gran revuelo.<\/p>\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The page experience update is now slowly rolling out (Top Stories will begin using this new signal by Thursday). It will be complete by the end of August 2021. More here: <a href=\"https:\/\/t.co\/kDwhhOYklK\">https:\/\/t.co\/kDwhhOYklK<\/a><\/p>&mdash; Google Search Central (@googlesearchc) <a href=\"https:\/\/twitter.com\/googlesearchc\/status\/1404886100087246848?ref_src=twsrc%5Etfw\">June 15, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<p>Durante su anuncio de junio de 2021, Google comparti\u00f3 que las Core Web Vitals, uno de los cuatro componentes que componen la experiencia de la p\u00e1gina, se considerar\u00edan un factor de clasificaci\u00f3n.<\/p>\n\n<p>Ahora que la actualizaci\u00f3n de la experiencia de la p\u00e1gina se ha implementado por completo, \u00bfqu\u00e9 significa para los sitios web? Sigue leyendo para aprender:<\/p>\n\n<ul class=\"wp-block-list\"><li><a href=\"#What-Are-Core-Web-Vitals\">\u00bfQu\u00e9 son las Core Web Vitals?<\/a><\/li><li><a href=\"#Importance-of-Core-Web-Vitals\">Importancia de las Core Web Vitals<\/a><\/li><li><a href=\"#Impact-of-Core-Web-Vitals-to-Websites-Built-Using-Website-Builders\">Impacto de las Core Web Vitals en los sitios web creados con Website Builder<\/a>s<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"What-Are-Core-Web-Vitals\">\u00bfQu\u00e9 son las Core Web Vitals?<\/h2>\n\n<p>Core Web Vitals es un nuevo conjunto de m\u00e9tricas en el algoritmo de experiencia de p\u00e1gina que mide c\u00f3mo interact\u00faan los usuarios con una p\u00e1gina web.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Page-Experience-metrics-featuring-Core-Web-Vitals-1.png\" alt=\"M&#xE9;tricas de experiencia de p&#xE1;gina de Google, con Core Web Vitals\" class=\"wp-image-38797\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Page-Experience-metrics-featuring-Core-Web-Vitals-1.png 960w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Page-Experience-metrics-featuring-Core-Web-Vitals-1-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Page-Experience-metrics-featuring-Core-Web-Vitals-1-768x432.png 768w\" sizes=\"100vw\" \/><figcaption><a href=\"https:\/\/developers.google.com\/search\/blog\/2020\/11\/timing-for-page-experience\" target=\"_blank\" rel=\"noreferrer noopener\">Fuente de la imagen<\/a><\/figcaption><\/figure>\n\n<p>Google ha identificado tres par\u00e1metros que crean una experiencia de navegaci\u00f3n \u00f3ptima para el usuario. Google eval\u00faa estos par\u00e1metros para dar al sitio web una puntuaci\u00f3n de experiencia de p\u00e1gina que se pueda ver en Search Console. <\/p>\n\n<p>Estas Core Web Vitals son:<\/p>\n\n<ol class=\"wp-block-list\" type=\"1\"><li><strong>La experiencia de carga <\/strong>es el tiempo que tarda en cargarse el contenido m\u00e1s relevante, que se mide a trav\u00e9s de la <strong>pintura con mayor contenido <\/strong>(LCP). Los sitios web deben aspirar a un LCP de 2,5 segundos o menos. <\/li><li><strong>La interactividad <\/strong>es el tiempo que tarda un sitio web en responder a la entrada del usuario. Se mide a trav\u00e9s del <strong>retardo de la primera entrada <\/strong>(FID). Los sitios web deben apuntar a un FID de 100 milisegundos o m\u00e1s. La puntuaci\u00f3n FID es m\u00e1s importante para las p\u00e1ginas que requieren la entrada del usuario, como la p\u00e1gina de inicio de sesi\u00f3n.   <\/li><li><strong>La estabilidad virtual <\/strong>es una puntuaci\u00f3n asignada a un sitio web para medir la estabilidad de una p\u00e1gina web despu\u00e9s de que se carga. Se mide a trav\u00e9s del <strong>Cumulative Layout Shift <\/strong>(CLS), y los sitios web deben aspirar a una puntuaci\u00f3n m\u00e1xima de CLS de 0,1. <\/li><\/ol>\n\n<p>Adem\u00e1s de las Core Web Vitals, la experiencia de la p\u00e1gina de Google tambi\u00e9n mide la compatibilidad con dispositivos m\u00f3viles, la <a href=\"https:\/\/www.bluehost.com\/es-es\/blog\/alojamiento-web-ssl-como-agregar-https-a-su-dominio-3\/\">seguridad del sitio web<\/a> y la ausencia de intersticiales.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"Importance-of-Core-Web-Vitals\">Importancia de las Core Web Vitals<\/h2>\n\n<p>Google reiter\u00f3 que la relevancia sigue siendo la principal consideraci\u00f3n para los resultados de los motores de b\u00fasqueda, pero la experiencia de la p\u00e1gina no debe tomarse a la ligera. Seg\u00fan <a href=\"https:\/\/developers.google.com\/search\/docs\/advanced\/experience\/page-experience\" target=\"_blank\" rel=\"noreferrer noopener\">Google Search Central<\/a>, para p\u00e1ginas similares en relevancia, la experiencia de la p\u00e1gina puede ser mucho m\u00e1s importante para la visibilidad en la b\u00fasqueda. <\/p>\n\n<p>Tal vez muchos usuarios crean que la actualizaci\u00f3n fue intrascendente porque la experiencia de la p\u00e1gina tambi\u00e9n considera HTTPS y la compatibilidad con dispositivos m\u00f3viles, que anteriormente se consideraban factores de clasificaci\u00f3n menores.<\/p>\n\n<p>Ahora, todos los factores de clasificaci\u00f3n de la experiencia de la p\u00e1gina se toman como un todo, un hecho confirmado por John Mueller de Google, quien dijo que Core Web Vitals es un <a href=\"https:\/\/www.searchenginejournal.com\/google-core-web-vitals-ranking-factor\/415533\/\" target=\"_blank\" rel=\"noreferrer noopener\">factor de clasificaci\u00f3n significativo en s\u00ed mismo<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"Impact-of-Core-Web-Vitals-to-Websites-Built-Using-Website-Builders\">Impacto de las Core Web Vitals en los sitios web creados con creadores de sitios web<\/h2>\n\n<p>Los sitios web que se encuentran m\u00e1s arriba en las p\u00e1ginas de resultados de los motores de b\u00fasqueda <a href=\"https:\/\/www.advancedwebranking.com\/ctrstudy\/\" target=\"_blank\" rel=\"noreferrer noopener\">reciben m\u00e1s tr\u00e1fico<\/a>. Por lo tanto, los propietarios de sitios web de todo el mundo intentar\u00e1n optimizar su sitio web para la nueva actualizaci\u00f3n de Google. <\/p>\n\n<p>Seg\u00fan el <a href=\"https:\/\/www.searchenginejournal.com\/google-page-experience-update-finished\/418506\/#close\" target=\"_blank\" rel=\"noreferrer noopener\">Search Engine Journal<\/a>, las m\u00e9tricas web principales recibieron la mayor cantidad de actualizaciones en 2021, lo que result\u00f3 en m\u00e9tricas m\u00e1s precisas y mejores puntajes para la mayor\u00eda de los sitios web.<\/p>\n\n<p>Con Core Web Vitals completamente implementado, los sitios web autoalojados pueden hacer los ajustes necesarios, pero \u00bfqu\u00e9 significa esto para los sitios web creados en creadores de sitios web? \u00bfTambi\u00e9n experimentan una mejora en las puntuaciones del sitio web? <\/p>\n\n<p>M\u00faltiples plataformas de comercio electr\u00f3nico y sitios web se basan en creadores de sitios web. Facilitan la creaci\u00f3n de sitios web porque se cuidan todos los aspectos t\u00e9cnicos. Sin embargo, los usuarios tienen menos control sobre el alojamiento y la codificaci\u00f3n, lo que significa que hay menos libertad para optimizar las Core Web Vitals.  <\/p>\n\n<p>Los datos lo respaldan. <a href=\"https:\/\/www.websitebuilderexpert.com\/website-builders\/core-web-vitals\/\" target=\"_blank\" rel=\"noreferrer noopener\">Website Builder Expert<\/a> prob\u00f3 las versiones de escritorio y m\u00f3vil de m\u00e1s de 3.000 sitios web de comercio electr\u00f3nico creados en las principales plataformas de comercio electr\u00f3nico para comprobar su rendimiento en comparaci\u00f3n con las m\u00e9tricas de experiencia de p\u00e1gina de Google.<\/p>\n\n<p>Los hallazgos mostraron una buena capacidad de respuesta m\u00f3vil y seguridad del sitio web para los creadores de sitios web. La velocidad del sitio web tiene margen de mejora, pero eso no es una sorpresa porque no puedes controlar tu alojamiento y el c\u00f3digo de tu sitio web. <\/p>\n\n<p>Pero algo que Website Builder Expert encontr\u00f3 y vale la pena se\u00f1alar es una diferencia entre el rendimiento m\u00f3vil y de escritorio cuando se trata de Core Web Vitals para creadores de sitios web de comercio electr\u00f3nico.<\/p>\n\n<p>El rendimiento m\u00f3vil fue consistentemente peor, lo cual es problem\u00e1tico teniendo en cuenta que la actualizaci\u00f3n de la experiencia de la p\u00e1gina se implement\u00f3 para sitios web m\u00f3viles y Google indexa las versiones m\u00f3viles.<\/p>\n\n<p>Si tu sitio web est\u00e1 construido sobre un creador de sitios web, puedes probar el rendimiento del sitio web utilizando la <a href=\"https:\/\/support.google.com\/webmasters\/answer\/9205520?hl=en\" target=\"_blank\" rel=\"noreferrer noopener\">herramienta Core Web Vitals<\/a> de Google Search Console.<\/p>\n\n<h2 class=\"wp-block-heading\">Reflexiones finales: las m\u00e9tricas web principales de Google influyen en los resultados de b\u00fasqueda del sitio web<\/h2>\n\n<p>La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que prioriza la experiencia del usuario ha terminado de implementarse.<\/p>\n\n<p>La actualizaci\u00f3n presenta Core Web Vitals, un nuevo conjunto de m\u00e9tricas que miden la experiencia de navegaci\u00f3n \u00f3ptima. Despu\u00e9s de implementar la actualizaci\u00f3n, m\u00e1s sitios web experimentaron mejores puntuaciones. <\/p>\n\n<p>Google menciona que, aunque la relevancia de la b\u00fasqueda sigue siendo la principal consideraci\u00f3n, la actualizaci\u00f3n para nuevos usuarios no debe tomarse a la ligera. Una prueba independiente realizada en creadores de sitios web encontr\u00f3 margen de mejora en el rendimiento m\u00f3vil y la experiencia del usuario. <\/p>\n\n<p><em>\u00bfQu\u00e9 opinas de la actualizaci\u00f3n de Core Vitals? H\u00e1znoslo saber tuiteando   <\/em><a href=\"http:\/\/twitter.com\/bluehost\" target=\"_blank\" rel=\"noreferrer noopener\"><em>@Bluehost<\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mayo de 2020, Google anunci\u00f3 que lanzar\u00eda Page Experience, una nueva actualizaci\u00f3n que prioriza la experiencia del usuario. Google comenz\u00f3 a implementar la actualizaci\u00f3n en junio de 2021 y dijo que esperaba completarla en agosto de 2021. Despu\u00e9s de algunos retrasos, la actualizaci\u00f3n finalmente termin\u00f3 de implementarse el 3 de septiembre de 2021. Para [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":128571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Las principales m\u00e9tricas web de Google influyen en los resultados de b\u00fasqueda de los sitios web","_yoast_wpseo_metadesc":"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.","inline_featured_image":false,"footnotes":""},"categories":[3094,1361],"tags":[3653,3672,3665,3677],"ppma_author":[588],"class_list":["post-128570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rendimiento","category-sitio-web","tag-analitica","tag-guias-practicas","tag-metricas-web-esenciales","tag-pequena-empresa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las principales m\u00e9tricas web de Google influyen en los resultados de b\u00fasqueda de los sitios web<\/title>\n<meta name=\"description\" content=\"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128570\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google\" \/>\n<meta property=\"og:description\" content=\"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T00:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T07:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1999\" \/>\n\t<meta property=\"og:image:height\" content=\"1237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiffani Anderson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/TiffAnddd\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiffani Anderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\"},\"author\":{\"name\":\"Tiffani Anderson\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66\"},\"headline\":\"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google\",\"datePublished\":\"2021-09-15T00:58:05+00:00\",\"dateModified\":\"2025-03-04T07:40:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\"},\"wordCount\":1168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg\",\"keywords\":[\"Anal\u00edtica\",\"Gu\u00edas pr\u00e1cticas\",\"M\u00e9tricas web esenciales\",\"Peque\u00f1a empresa\"],\"articleSection\":[\"Rendimiento\",\"Sitio web\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\",\"name\":\"Las principales m\u00e9tricas web de Google influyen en los resultados de b\u00fasqueda de los sitios web\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg\",\"datePublished\":\"2021-09-15T00:58:05+00:00\",\"dateModified\":\"2025-03-04T07:40:48+00:00\",\"description\":\"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg\",\"width\":1999,\"height\":1237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66\",\"name\":\"Tiffani Anderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/1f8eaab88872e9aa519335532a3a886e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g\",\"caption\":\"Tiffani Anderson\"},\"description\":\"Tiffani is a Content and SEO Manager for the Bluehost brand. With over 10 years experience across all facets of content and brand marketing, she strives to combine concepts from brand marketing with engaging content through the lens of SEO.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/tiffaninanderson\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/TiffAnddd\"],\"knowsAbout\":[\"Search Engine Optimization\",\"Content Marketing\",\"Brand Marketing\"],\"knowsLanguage\":[\"English\"],\"jobTitle\":\"SEO and Content Manager\",\"worksFor\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/tiffani\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las principales m\u00e9tricas web de Google influyen en los resultados de b\u00fasqueda de los sitios web","description":"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128570\/","og_locale":"es_ES","og_type":"article","og_title":"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google","og_description":"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.","og_url":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2021-09-15T00:58:05+00:00","article_modified_time":"2025-03-04T07:40:48+00:00","og_image":[{"width":1999,"height":1237,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg","type":"image\/jpeg"}],"author":"Tiffani Anderson","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/TiffAnddd","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Tiffani Anderson","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/"},"author":{"name":"Tiffani Anderson","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66"},"headline":"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google","datePublished":"2021-09-15T00:58:05+00:00","dateModified":"2025-03-04T07:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/"},"wordCount":1168,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg","keywords":["Anal\u00edtica","Gu\u00edas pr\u00e1cticas","M\u00e9tricas web esenciales","Peque\u00f1a empresa"],"articleSection":["Rendimiento","Sitio web"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/","url":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/","name":"Las principales m\u00e9tricas web de Google influyen en los resultados de b\u00fasqueda de los sitios web","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg","datePublished":"2021-09-15T00:58:05+00:00","dateModified":"2025-03-04T07:40:48+00:00","description":"La actualizaci\u00f3n de la experiencia de la p\u00e1gina de Google que introduce las Core Web Vitals ha terminado de implementarse. Aprende qu\u00e9 son las Core Web Vitals y c\u00f3mo afectan a tu sitio web.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2021\/09\/Googles-Core-Web-Vitals-Update-1.jpg","width":1999,"height":1237},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/impacto-seo-de-la-actualizacion-de-las-core-web-vitals-de-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"Impacto SEO de la actualizaci\u00f3n de las Core Web Vitals de Google"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/2fc4710c56aadc73395ff8075baedd66","name":"Tiffani Anderson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/1f8eaab88872e9aa519335532a3a886e","url":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","caption":"Tiffani Anderson"},"description":"Tiffani is a Content and SEO Manager for the Bluehost brand. With over 10 years experience across all facets of content and brand marketing, she strives to combine concepts from brand marketing with engaging content through the lens of SEO.","sameAs":["https:\/\/www.linkedin.com\/in\/tiffaninanderson\/","https:\/\/x.com\/https:\/\/twitter.com\/TiffAnddd"],"knowsAbout":["Search Engine Optimization","Content Marketing","Brand Marketing"],"knowsLanguage":["English"],"jobTitle":"SEO and Content Manager","worksFor":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/author\/tiffani\/"}]}},"authors":[{"term_id":588,"user_id":50,"is_guest":0,"slug":"tiffani","display_name":"Tiffani Anderson","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/97fc139aa4992d5aca99a9fcb43d5e6fb8e98ad03b81f748b6ab3ffa39797fe5?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=128570"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/128570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/128571"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=128570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=128570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=128570"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=128570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}