{"id":129577,"date":"2020-11-20T11:36:44","date_gmt":"2020-11-20T11:36:44","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/"},"modified":"2025-03-04T08:19:14","modified_gmt":"2025-03-04T08:19:14","slug":"noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/","title":{"rendered":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020"},"content":{"rendered":"\n<p>El equipo de Gutenberg lanz\u00f3 la versi\u00f3n 9.3.0 de Gutenberg el 4 de noviembre de 2020. Con peque\u00f1as mejoras y la introducci\u00f3n de experimentos significativos, la \u00faltima versi\u00f3n de Gutenberg es un claro paso hacia el futuro de la edici\u00f3n completa de sitios web. <\/p>\n\n<p>El proyecto Gutenberg se est\u00e1 moviendo a trav\u00e9s de la fase dos de su <a href=\"https:\/\/www.bluehost.com\/blog\/the-4-phases-of-wordpresss-gutenberg-project\/\">hoja de ruta de cuatro fases<\/a> para revolucionar WordPress. La primera fase se complet\u00f3 con el lanzamiento de WordPress 5.0. Ahora, el equipo ha cambiado su enfoque a la personalizaci\u00f3n completa del sitio web.  <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/BLdm6Uhz0kHiS7r-ldDfcU7rCaUrIJQkS6GvmxNISa03xUwY4p53kbDESjIaBRchrmm5hnCgXUd7Dk-JGvLp39appkHnoPHjCWCyekeUefaUxnM3WBbXG7wH2XW2Q678lCDCHUfH\" alt=\"\"\/><\/figure><\/div>\n\n<p>Una vez completado, el equipo seguir\u00e1 adelante para abordar la colaboraci\u00f3n y la publicaci\u00f3n multiling\u00fce de WordPress.  <\/p>\n\n<h2 class=\"wp-block-heading\">Lanzamiento de Gutenberg 9.3.0: Novedades<\/h2>\n\n<p>El <a href=\"https:\/\/wordpress.org\/gutenberg\/\">editor de bloques Gutenberg<\/a> se lanz\u00f3 a la comunidad de WordPress en 2018. A medida que se acerca 2021, el editor ahora contiene la mayor\u00eda de las funciones de personalizaci\u00f3n del sitio web planificadas. <\/p>\n\n<p>En la versi\u00f3n 9.3.0, el editor de bloques de Gutenberg recibi\u00f3 algunas mejoras menores para ayudar con la alineaci\u00f3n, los temas oscuros y el intercambio social. Sin embargo, el enfoque principal de esta versi\u00f3n parece estar en los experimentos de edici\u00f3n del sitio completo.   <\/p>\n\n<h2 class=\"wp-block-heading\">Experimentos completos de edici\u00f3n del sitio<\/h2>\n\n<p>Los equipos de WordPress y Gutenberg contin\u00faan avanzando hacia la edici\u00f3n completa del sitio. Gutenberg 9.3.0 incluye varios experimentos destinados a facilitar el cambio de la edici\u00f3n basada en widgets al editor de bloques.   <\/p>\n\n<h3 class=\"wp-block-heading\">Eliminaci\u00f3n de pantallas de personalizadores y widgets<\/h3>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/Au7UIq8BU1jEE5cR10v2xCxF-1Xf32DXjGjcyvCZVA6ywdH0x2sGQNIeHtBX-lv7xootLTD_LGVoDQl1OneF-bD3rj0Tdfj1aEG7UMAuQZdgpxsq4UkwPkWJH7IcNhyZipas9DXV\" alt=\"\"\/><\/figure><\/div>\n\n<p>Una de las principales tareas a las que se enfrenta el equipo de Gutenberg es la cuesti\u00f3n de fusionar los nuevos elementos de bloque con los elementos cl\u00e1sicos de los widgets.  <\/p>\n\n<p>El equipo est\u00e1 experimentando con <a href=\"https:\/\/github.com\/WordPress\/gutenberg\/pull\/26594\">la eliminaci\u00f3n de las opciones \u00abWidget\u00bb y \u00abPersonalizador\u00bb<\/a> en el men\u00fa Apariencia. En su lugar, han agregado una funci\u00f3n de Editor del sitio encima de la secci\u00f3n Apariencia.   <\/p>\n\n<p>El equipo de Gutenberg explica que los temas de edici\u00f3n completa del sitio (FSE) utilizar\u00e1n bloques en lugar de widgets, lo que hace que la pantalla de widgets no tenga prop\u00f3sito.  <\/p>\n\n<p>Asimismo, el nuevo editor de sitios web de Gutenberg realiza actualmente la misma funci\u00f3n que el Personalizador cl\u00e1sico. Por lo tanto, la pantalla del Personalizador se volver\u00e1 redundante. El equipo est\u00e1 trabajando para garantizar que no haya brechas de rendimiento cuando ya no se use la pantalla del personalizador.  <\/p>\n\n<p>Varias personas de la comunidad de WordPress adoptan este enfoque simplificado como un cambio bienvenido e intuitivo.  <\/p>\n\n<p>Sin embargo, sigue existiendo el problema de la migraci\u00f3n de temas basados en widgets a FSE. Los desarrolladores necesitar\u00e1n un marco para convertir widgets en elementos de bloque o alguna forma de acceder a una pantalla de widgets para temas que no sean FSE. <\/p>\n\n<p>El equipo de Gutenberg ha planteado la posibilidad de crear temas h\u00edbridos que utilicen tanto plantillas basadas en widgets como en bloques. Sin embargo, a\u00fan no se ha trabajado en temas h\u00edbridos. <\/p>\n\n<h3 class=\"wp-block-heading\">Habilitar autom\u00e1ticamente el editor de sitios web para temas FSE<\/h3>\n\n<p>A medida que WordPress avanza hacia FSE, varios desarrolladores han lanzado temas FSE que funcionan con el editor de bloques en lugar de los widgets cl\u00e1sicos.  <\/p>\n\n<p>Gutenberg 9.3.0 est\u00e1 ejecutando un experimento que <a href=\"https:\/\/github.com\/WordPress\/gutenberg\/pull\/26500\">habilitar\u00e1 autom\u00e1ticamente el editor de bloques<\/a> cuando se instale y active un tema FSE. De lo contrario, si se utiliza un tema cl\u00e1sico, WordPress mantendr\u00e1 las secciones Personalizador, Widgets y Men\u00fa de navegaci\u00f3n. <\/p>\n\n<p>En otras palabras, la experiencia del frontend de WordPress reflejar\u00e1 autom\u00e1ticamente las herramientas de edici\u00f3n relevantes para el tema activo.  <\/p>\n\n<p>Cabe se\u00f1alar que la FSE a\u00fan es experimental. Si bien hay temas de FSE disponibles, la edici\u00f3n completa del sitio a\u00fan est\u00e1 en progreso. El nuevo editor del sitio web todav\u00eda estar\u00e1 experimentando varios cambios y experimentos antes de que est\u00e9 finalizado.    <\/p>\n\n<p>Sin embargo, si est\u00e1 interesado en probar un tema FSE para su sitio web, Ari Stathopoulos ha lanzado el tema experimental FSE <a href=\"https:\/\/wordpress.org\/themes\/q\/\">Q<\/a>.  <\/p>\n\n<h2 class=\"wp-block-heading\">Mejoras menores en la interfaz de usuario de Gutenberg<\/h2>\n\n<p>Adem\u00e1s de los principales experimentos de FSE, Gutenberg 9.3.0 tambi\u00e9n incluye varias mejoras en la interfaz de usuario (UI).<\/p>\n\n<p>En su mayor parte, estas mejoras ayudan en la organizaci\u00f3n de las opciones de elementos de bloque. Por ejemplo, las opciones de alineaci\u00f3n ahora se mostrar\u00e1n en un orden coherente y las opciones de formato de publicaci\u00f3n ahora se mostrar\u00e1n alfab\u00e9ticamente.   <\/p>\n\n<p>El equipo de Gutenberg tambi\u00e9n ha mejorado la interfaz de usuario para el modo oscuro. En concreto, se ha actualizado la fuente de marcador de posici\u00f3n para subt\u00edtulos, citas y comillas extra\u00eddas para mejorar la legibilidad. <\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/eMw2HgXfwds_3xTBUK6MmFCnKlUPT48wD-BuuqnsRpP6LFLhV0OWa-Ql9EAGUmY1MPB48qOPPgjwRuM9iIM4igWh3vRoxkTinugg2e8krvCPq8M6UaWwqVaWBYcbdv6SwnS5RXqg\" alt=\"\"\/><\/figure><\/div>\n\n<p>Por \u00faltimo, el bloque de V\u00ednculos Sociales da la bienvenida a <a href=\"https:\/\/github.com\/WordPress\/gutenberg\/pull\/26118\">tres nuevas plataformas<\/a> para la familia. Los usuarios ahora pueden vincularse a cuentas de Patreon, Telegram y TikTok.   <\/p>\n\n<h2 class=\"wp-block-heading\">Mirando hacia el futuro en WordPress 5.6<\/h2>\n\n<p>Gutenberg 9.3.0 es un paso claro hacia el futuro de la edici\u00f3n completa de sitios. WordPress planea lanzar <a href=\"https:\/\/make.wordpress.org\/core\/2020\/08\/13\/wordpress-5-6-release-planning\/\">WordPress 5.6<\/a> el 8 de diciembre de 2020.   <\/p>\n\n<p>WordPress 5.6 tomar\u00e1 muchas de las actualizaciones y experimentos de Gutenberg y los har\u00e1 parte del n\u00facleo de WordPress.  <\/p>\n\n<p>El nuevo n\u00facleo de WordPress tiene como objetivo incluir bloques de navegaci\u00f3n, un tema predeterminado compatible con FSE y soporte para PHP 8.  <\/p>\n\n<p>Revolucionar la experiencia de WordPress no ser\u00e1 sencillo. Todav\u00eda hay obst\u00e1culos en el horizonte, incluida la migraci\u00f3n de una experiencia basada en widgets a un generador de bloques.   <\/p>\n\n<p>Sin embargo, los experimentos actuales que se ejecutan en Gutenberg 9.3.0 dan a la comunidad de WordPress una idea de c\u00f3mo ser\u00e1 la inevitable migraci\u00f3n a la creaci\u00f3n de sitios web basados en bloques.<\/p>\n\n<p>Para obtener m\u00e1s informaci\u00f3n sobre el alojamiento web para su sitio web de WordPress, explore <a href=\"https:\/\/www.bluehost.com\/wordpress\">los planes de Bluehost<\/a> hoy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de Gutenberg lanz\u00f3 la versi\u00f3n 9.3.0 de Gutenberg el 4 de noviembre de 2020. Con peque\u00f1as mejoras y la introducci\u00f3n de experimentos significativos, la \u00faltima versi\u00f3n de Gutenberg es un claro paso hacia el futuro de la edici\u00f3n completa de sitios web. El proyecto Gutenberg se est\u00e1 moviendo a trav\u00e9s de la fase [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":129578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020","_yoast_wpseo_metadesc":"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.","inline_featured_image":false,"footnotes":""},"categories":[3073,1365],"tags":[3674,3659,3682],"ppma_author":[602],"class_list":["post-129577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo","category-wordpress-en-ingles","tag-bajo-codigo-sin-codigo","tag-cms","tag-trucos-y-consejos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020<\/title>\n<meta name=\"description\" content=\"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/129577\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020\" \/>\n<meta property=\"og:description\" content=\"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-20T11:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T08:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Machielle Thomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/machiellethomas\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Machielle Thomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\"},\"author\":{\"name\":\"Machielle Thomas\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/5f0415b94c1232ec2b636fb579189d3c\"},\"headline\":\"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020\",\"datePublished\":\"2020-11-20T11:36:44+00:00\",\"dateModified\":\"2025-03-04T08:19:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\"},\"wordCount\":990,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png\",\"keywords\":[\"Bajo c\u00f3digo \/ Sin c\u00f3digo\",\"CMS\",\"Trucos y consejos\"],\"articleSection\":[\"Desarrollo\",\"WordPress (en ingl\u00e9s)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\",\"name\":\"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png\",\"datePublished\":\"2020-11-20T11:36:44+00:00\",\"dateModified\":\"2025-03-04T08:19:14+00:00\",\"description\":\"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.bluehost.com\/es-es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/5f0415b94c1232ec2b636fb579189d3c\",\"name\":\"Machielle Thomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/d4ddb5ba781119f57d9935f3cbd6875a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/68d6030908d825bb56c64a6db30231734458b2f95e17c82f374b2f9c1c0f3924?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/68d6030908d825bb56c64a6db30231734458b2f95e17c82f374b2f9c1c0f3924?s=96&d=mm&r=g\",\"caption\":\"Machielle Thomas\"},\"description\":\"Machielle is a content enthusiast who has a passion for bridging the gap between audiences and brands through impactful storytelling. Machielle has also spoken at dozens of WordCamps throughout the years.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/machielle-thomas-99752179\",\"https:\/\/x.com\/https:\/\/twitter.com\/machiellethomas\"],\"knowsAbout\":[\"Content Marketing\",\"Storytelling\",\"Leadership\"],\"jobTitle\":\"Course Instructor\",\"worksFor\":\"LinkedIn\",\"url\":\"https:\/\/www.bluehost.com\/blog\/es\/author\/machiellet\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020","description":"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/129577\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020","og_description":"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.","og_url":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2020-11-20T11:36:44+00:00","article_modified_time":"2025-03-04T08:19:14+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png","type":"image\/png"}],"author":"Machielle Thomas","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/machiellethomas","twitter_site":"@bluehost","twitter_misc":{"Escrito por":"Machielle Thomas","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/"},"author":{"name":"Machielle Thomas","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/5f0415b94c1232ec2b636fb579189d3c"},"headline":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020","datePublished":"2020-11-20T11:36:44+00:00","dateModified":"2025-03-04T08:19:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/"},"wordCount":990,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png","keywords":["Bajo c\u00f3digo \/ Sin c\u00f3digo","CMS","Trucos y consejos"],"articleSection":["Desarrollo","WordPress (en ingl\u00e9s)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/","url":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/","name":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png","datePublished":"2020-11-20T11:36:44+00:00","dateModified":"2025-03-04T08:19:14+00:00","description":"El equipo de WordPress lanz\u00f3 Gutenberg 9.3.0, realizando varias mejoras e incluyendo una serie de experimentos que avanzan hacia la edici\u00f3n completa del sitio.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2020\/11\/Social-Templates-2020-11-20T112747.475-1.png","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/es\/noticias-de-gutenberg-novedades-de-gutenberg-9-3-0-noviembre-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bluehost.com\/es-es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias de Gutenberg: Novedades de Gutenberg 9.3.0 | Noviembre 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/es\/#website","url":"https:\/\/www.bluehost.com\/blog\/es\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/es\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/5f0415b94c1232ec2b636fb579189d3c","name":"Machielle Thomas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bluehost.com\/blog\/es\/#\/schema\/person\/image\/d4ddb5ba781119f57d9935f3cbd6875a","url":"https:\/\/secure.gravatar.com\/avatar\/68d6030908d825bb56c64a6db30231734458b2f95e17c82f374b2f9c1c0f3924?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d6030908d825bb56c64a6db30231734458b2f95e17c82f374b2f9c1c0f3924?s=96&d=mm&r=g","caption":"Machielle Thomas"},"description":"Machielle is a content enthusiast who has a passion for bridging the gap between audiences and brands through impactful storytelling. Machielle has also spoken at dozens of WordCamps throughout the years.","sameAs":["https:\/\/www.linkedin.com\/in\/machielle-thomas-99752179","https:\/\/x.com\/https:\/\/twitter.com\/machiellethomas"],"knowsAbout":["Content Marketing","Storytelling","Leadership"],"jobTitle":"Course Instructor","worksFor":"LinkedIn","url":"https:\/\/www.bluehost.com\/blog\/es\/author\/machiellet\/"}]}},"authors":[{"term_id":602,"user_id":6,"is_guest":0,"slug":"machiellet","display_name":"Machielle Thomas","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/68d6030908d825bb56c64a6db30231734458b2f95e17c82f374b2f9c1c0f3924?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/129577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=129577"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/posts\/129577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media\/129578"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=129577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=129577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=129577"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/es\/wp-json\/wp\/v2\/ppma_author?post=129577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}