{"id":213952,"date":"2023-09-02T14:47:38","date_gmt":"2023-09-02T14:47:38","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/"},"modified":"2025-06-02T10:06:49","modified_gmt":"2025-06-02T10:06:49","slug":"wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/","title":{"rendered":"WordPress News Roundup &#8211; 6.3 Full Release + 7 More Updates | August 2023"},"content":{"rendered":"\n<p>La tant attendue WordPress 6.3 est enfin disponible, ce qui est une excellente nouvelle pour les fans de WordPress.<\/p>\n\n<p>Mais ce n&rsquo;est pas tout ce que le mois d&rsquo;ao\u00fbt nous a apport\u00e9. Gutenberg 16.5 est \u00e9galement sorti, ainsi que la feuille de route officielle de la prochaine version majeure de WordPress. <\/p>\n\n<p>Cependant, les nouvelles ne sont pas toutes bonnes. Nous avons r\u00e9cemment appris que de nombreux contributeurs de la communaut\u00e9 luttent pour rester \u00e0 la hauteur de leur charge de travail en raison d&rsquo;un manque de b\u00e9n\u00e9voles ou de financement, bien que WordPress continue de faire pression sur la version 6.4. <\/p>\n\n<p>Lisez la suite pour conna\u00eetre les principales nouveaut\u00e9s de WordPress pour le mois d&rsquo;ao\u00fbt 2023.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wordpress-6-3-lionel-is-out-now\">WordPress 6.3 \u00ab Lionel \u00bb est disponible d\u00e8s maintenant<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel.jpg\" alt=\"WordPress 6.3 est &#xE9;galement connu sous le nom de &#xAB; Lionel &#xBB;.\" class=\"wp-image-46741\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel.jpg 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-300x200.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-768x512.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-270x180.jpg 270w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-770x515.jpg 770w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-24x16.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-36x24.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.3-Lionel-48x32.jpg 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Apr\u00e8s une <a href=\"https:\/\/wordpress.org\/news\/2023\/08\/wordpress-6-3-rc3\/\" target=\"_blank\" rel=\"noreferrer noopener\">derni\u00e8re version candidate<\/a> qui a corrig\u00e9 les derniers bugs, <a href=\"https:\/\/wordpress.org\/news\/2023\/08\/wordpress-6-3-rc3\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress 6.3 a \u00e9t\u00e9 publi\u00e9<\/a> le 8 ao\u00fbt 2023.<\/p>\n\n<p>De nombreuses mises \u00e0 jour passionnantes sont pr\u00e9vues. En voici quelques-unes : <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Changements dans l \u00ab \u00e9diteur de site<\/strong>: Vous pouvez modifier le contenu, les mod\u00e8les et les motifs dans l \u00bb \u00e9diteur de site (qui dispose d\u00e9sormais d&rsquo;un mode \u00ab sans distraction \u00bb).<\/li>\n\n\n\n<li><strong>Nouvelle palette de commandes<\/strong>: Ces raccourcis clavier vous permettent d&rsquo;ex\u00e9cuter rapidement des commandes. Les d\u00e9veloppeurs seront int\u00e9ress\u00e9s par l&rsquo;<a href=\"https:\/\/make.wordpress.org\/core\/2023\/07\/17\/introducing-the-wordpress-command-palette-api\/\" target=\"_blank\" rel=\"noreferrer noopener\">API de la palette de commandes<\/a> qui peut \u00eatre int\u00e9gr\u00e9e \u00e0 leurs plugins. <\/li>\n\n\n\n<li><strong>Meilleure gestion des motifs<\/strong>: Vous pouvez d\u00e9sormais cr\u00e9er et synchroniser des<a href=\"https:\/\/www.bluehost.com\/blog\/what-are-gutenberg-block-patterns-in-wordpress-and-how-to-use-them\/\">blocs de motifs<\/a>.<\/li>\n\n\n\n<li><strong>Mise \u00e0 jour des outils de conception<\/strong>: vous pouvez tirer parti de la nouvelle fonctionnalit\u00e9 des blocs de couverture, suivre les r\u00e9visions de style et personnaliser les l\u00e9gendes sans code.<\/li>\n\n\n\n<li><strong>Nouveaux blocs<\/strong>: D\u00e9couvrez les nouveaux blocs Notes de bas de page et D\u00e9tails.<\/li>\n\n\n\n<li><strong>Aper\u00e7u des th\u00e8mes<\/strong>: Vous pouvez d\u00e9sormais voir \u00e0 quoi ressemblera un th\u00e8me sur votre site web sans avoir \u00e0 l&rsquo;activer.<\/li>\n\n\n\n<li><strong>Une meilleure accessibilit\u00e9<\/strong>: Lionel comprend plus de 50 am\u00e9liorations en mati\u00e8re d&rsquo;accessibilit\u00e9, allant d&rsquo;un meilleur \u00e9tiquetage \u00e0 une navigation et des contr\u00f4les am\u00e9lior\u00e9s.<\/li>\n\n\n\n<li><strong>Des performances plus rapides<\/strong>: L \u00ab \u00e9quipe de WordPress a travaill\u00e9 dur pour am\u00e9liorer les performances c\u00f4t\u00e9 client et c\u00f4t\u00e9 serveur, ce qui a permis d \u00bb<a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/07\/wordpress-6-3-performance-improvements\/\" target=\"_blank\" rel=\"noreferrer noopener\">augmenter la vitesse de 27 % pour les th\u00e8mes en bloc<\/a> et de 18 % pour les th\u00e8mes classiques.<\/li>\n<\/ul>\n\n<p>De plus, la prise en charge de PHP 5 a \u00e9t\u00e9 interrompue, assurez-vous donc de passer \u00e0 la version la plus r\u00e9cente.<\/p>\n\n<p>L&rsquo;initiative communautaire sur les th\u00e8mes a publi\u00e9 <a href=\"https:\/\/wordpress.org\/themes\/blue-note\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blue Note<\/a>, un th\u00e8me inspir\u00e9 du jazz pour accompagner cette version. T\u00e9l\u00e9chargez-le si vous \u00eates \u00e0 la recherche d&rsquo;un th\u00e8me propre, color\u00e9 et beau. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-gutenberg-16-5-auto-inserting-blocks-better-command-palette\"><a><\/a>Gutenberg 16.5 : Insertion automatique de blocs, meilleure Palette de Commandes<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"1152\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands.png\" alt=\"Gutenberg 16.5 et 16.4 ont ajout&#xE9; de nouvelles commandes &#xE0; la palette de commandes.\" class=\"wp-image-46742\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands.png 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-300x173.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-1024x590.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-768x443.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-1536x885.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-36x21.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/Gutenberg-16.5-and-16.4-new-Command-Palett-commands-48x28.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>WordPress a publi\u00e9 ses mises \u00e0 jour bimestrielles de Gutenberg les 9 et 23 ao\u00fbt. Gutenberg 16.4 a ajout\u00e9 les fonctionnalit\u00e9s les plus int\u00e9ressantes, bien que la 16.5 ait \u00e9t\u00e9 remplie de nombreuses am\u00e9liorations utiles. <\/p>\n\n<p>Les principales caract\u00e9ristiques des deux versions sont les suivantes<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Insertion automatique de blocs<\/strong>. Cette fonction exp\u00e9rimentale doit \u00eatre activ\u00e9e manuellement. Elle vous permet d&rsquo;ins\u00e9rer automatiquement des blocs lorsque des param\u00e8tres sp\u00e9cifiques sont remplis. Les cas d&rsquo;utilisation sont tr\u00e8s int\u00e9ressants.   <\/li>\n\n\n\n<li><strong>Nouvelles commandes de la palette de commandes<\/strong>. Elles vous permettent d&rsquo;afficher\/masquer les fils d&rsquo;Ariane des blocs, d&rsquo;activer\/d\u00e9sactiver la liste de contr\u00f4le avant publication et de pr\u00e9visualiser les modifications dans un nouvel onglet. <\/li>\n\n\n\n<li><strong>Composant de barre de progression<\/strong>. Vous pouvez utiliser cette barre de progression simple sur l&rsquo;ensemble de votre site web. <\/li>\n\n\n\n<li><strong>Changements dans les blocs<\/strong>. Des param\u00e8tres suppl\u00e9mentaires ont \u00e9t\u00e9 ajout\u00e9s pour les blocs Footnotes, Details, Post Content et File. <\/li>\n<\/ul>\n\n<p>Il y a des douzaines de petits changements utiles qui offrent une exp\u00e9rience plus fluide. Vous pouvez donc consulter les notes de mise \u00e0 jour pour <a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/10\/whats-new-in-gutenberg-16-4-9-august\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gutenberg 16.4<\/a> et <a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/23\/whats-new-in-gutenberg-16-5-23-august\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gutenberg 16.5<\/a>. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-roadmap-to-wordpress-6-4-what-we-know-so-far\"><a><\/a>Feuille de route vers WordPress 6.4 : Ce que nous savons jusqu&rsquo;\u00e0 pr\u00e9sent<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1600\" height=\"902\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap.png\" alt=\"Il y a beaucoup de choses &#xE0; attendre de WordPress 6.4.\" class=\"wp-image-46743\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap.png 1600w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-1024x577.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-768x433.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-1536x866.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-36x20.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-6.4-roadmap-48x27.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Pr\u00eat pour WordPress 6.4 ? La prochaine mise \u00e0 jour majeure arrivera le 7 novembre 2023, et elle se concentrera sur l&rsquo;am\u00e9lioration de l&rsquo;exp\u00e9rience WordPress. <a href=\"https:\/\/make.wordpress.org\/core\/2023\/03\/24\/phase-3-collaboration\/\" target=\"_blank\" rel=\"noreferrer noopener\">La troisi\u00e8me phase de Gutenberg<\/a> continuera \u00e9galement d&rsquo;\u00eatre examin\u00e9e. <\/p>\n\n<p>Les d\u00e9veloppeurs de WordPress ont des projets passionnants en r\u00e9serve pour la version 6.4 :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Biblioth\u00e8que de polices<\/strong>: Outre la prise en charge de @font-face, la biblioth\u00e8que de polices facilitera grandement l&rsquo;installation et l&rsquo;utilisation des polices.<\/li>\n\n\n\n<li><strong>R\u00e9visions des mod\u00e8les<\/strong>: Tout comme les r\u00e9visions de style ont \u00e9t\u00e9 introduites dans la version 6.3, la version 6.4 les introduira dans les mod\u00e8les.<\/li>\n\n\n\n<li><strong>Nouveaux blocs<\/strong>: Les blocs Table des mati\u00e8res, Marqueur de d\u00e9filement et Temps de lecture combleront certaines lacunes en mati\u00e8re de fonctionnalit\u00e9. Un bloc Boucle de requ\u00eate est \u00e9galement envisag\u00e9. <\/li>\n\n\n\n<li><strong>Blocs d&rsquo;insertion automatique<\/strong>: Une version b\u00eata de cette fonctionnalit\u00e9 est d\u00e9j\u00e0 disponible dans Gutenberg 16.4.<\/li>\n\n\n\n<li><strong>Meilleure exp\u00e9rience d&rsquo;\u00e9criture et d&rsquo;\u00e9dition<\/strong>: Diverses fonctionnalit\u00e9s visant \u00e0 am\u00e9liorer ce point dans l&rsquo;\u00e9diteur Gutenberg de WordPress sont pr\u00e9vues.<\/li>\n\n\n\n<li><strong>Styles, mod\u00e8les et outils de conception<\/strong>: WordPress est un outil formidable, mais il peut toujours \u00eatre am\u00e9lior\u00e9. Les d\u00e9veloppeurs ont entrepris d&rsquo;ajouter des dizaines de perfectionnements indispensables aux fonctionnalit\u00e9s existantes. <\/li>\n\n\n\n<li><strong>Nouveau th\u00e8me par d\u00e9faut<\/strong>: <a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/24\/introducing-twenty-twenty-four\/\" target=\"_blank\" rel=\"noreferrer noopener\">Twenty Twenty-Four<\/a> sera publi\u00e9 en m\u00eame temps que la mise \u00e0 jour 6.4.<\/li>\n<\/ul>\n\n<p>Ce n&rsquo;est pas tout, alors consultez la <a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/22\/roadmap-to-6-4\/\" target=\"_blank\" rel=\"noreferrer noopener\">feuille de route<\/a> et le <a href=\"https:\/\/make.wordpress.org\/core\/2023\/06\/05\/wordpress-6-4-development-cycle\/\" target=\"_blank\" rel=\"noreferrer noopener\">cycle de d\u00e9veloppement de<\/a> WordPress 6.4 &#8211; et pr\u00e9parez-vous pour WordPress 6.4 Beta 1 le 26 septembre 2023.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-new-design-for-the-wordpress-admin\"><a><\/a>Un nouveau design pour l&rsquo;administration de WordPress ?<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"1363\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design.jpg\" alt=\"L'administration de WordPress va faire l'objet d'une mise &#xE0; jour longtemps diff&#xE9;r&#xE9;e.\" class=\"wp-image-46744\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design.jpg 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-300x205.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-1024x698.jpg 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-768x524.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-1536x1047.jpg 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-24x16.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-36x25.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/new-WordPress-admin-design-48x33.jpg 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Ce n&rsquo;est un secret pour personne que l&rsquo;<a href=\"https:\/\/bluehost.com\/fr\/blog\/tableau-de-bord-dadministration-wordpress-une-procedure-pas-a-pas-complete\/\">administration de WordPress<\/a> est un peu d\u00e9pass\u00e9e. Elle est essentiellement la m\u00eame depuis les 10 derni\u00e8res ann\u00e9es. <\/p>\n\n<p>Les d\u00e9veloppeurs et concepteurs de WordPress se penchent sur ce probl\u00e8me depuis 2022. En ao\u00fbt 2023, ils ont finalement <a href=\"https:\/\/make.wordpress.org\/design\/2023\/08\/10\/admin-design-kickoff\/\" target=\"_blank\" rel=\"noreferrer noopener\">pr\u00e9sent\u00e9 quelques id\u00e9es de conception potentielles<\/a>. <\/p>\n\n<p>Les aper\u00e7us sont prometteurs et beaucoup plus modernes, mais WordPress souhaite \u00e9galement recevoir des commentaires sur la conception structurelle sous-jacente.<\/p>\n\n<p>De nombreux utilisateurs ont d\u00e9j\u00e0 fait part de leurs compliments et de leurs inqui\u00e9tudes concernant le nouveau look de l&rsquo;administration de WordPress, et vous pouvez faire part de vos r\u00e9flexions.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-developer-updates-for-august-patterns-image-widths-and-more\"><a><\/a>Mises \u00e0 jour des d\u00e9veloppeurs pour le mois d&rsquo;ao\u00fbt : Motifs, largeur des images et plus encore<\/h2>\n\n<p>La derni\u00e8re version de WordPress s&rsquo;accompagne de nombreux outils et changements passionnants que les d\u00e9veloppeurs peuvent exp\u00e9rimenter. Voici quelques exemples des fonctionnalit\u00e9s de WordPress 6.3 : <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Orientations verticales du texte<\/strong>: D\u00e9sormais, vous pouvez facilement ajouter une touche int\u00e9ressante \u00e0 vos th\u00e8mes ou am\u00e9liorer la prise en charge des langues verticales.<\/li>\n\n\n\n<li><strong>Mises \u00e0 jour des motifs<\/strong>: la biblioth\u00e8que s&rsquo;appelle d\u00e9sormais \u00ab Motifs \u00bb et les blocs r\u00e9utilisables sont d\u00e9sormais des \u00ab motifs synchronis\u00e9s \u00bb. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 remani\u00e9e, alors regardez bien avant de vous y replonger. <\/li>\n\n\n\n<li><strong>La fonction de mode de d\u00e9veloppement a \u00e9t\u00e9 renomm\u00e9e<\/strong>: La fonction s&rsquo;appelle d\u00e9sormais \u00ab wp_is_development_mode() \u00bb et non plus \u00ab wp_in_development_mode() \u00bb.<\/li>\n\n\n\n<li><strong>Changements de conception susceptibles d&rsquo;entra\u00eener une rupture<\/strong>: Si vous utilisez des images de grande largeur dans le bloc Image, celles-ci ont d\u00e9sormais une largeur fixe de 100 %. Le s\u00e9lecteur de style global du bloc Avatar cible d\u00e9sormais l&rsquo;enveloppe et non l&rsquo;\u00e9l\u00e9ment &lt;img&gt;. Assurez-vous de v\u00e9rifier vos th\u00e8mes.  <\/li>\n\n\n\n<li><strong>Le processeur HTML<\/strong>: Cette API minimale est en cours de d\u00e9veloppement et pourrait \u00eatre publi\u00e9e avec WordPress 6.4.<\/li>\n<\/ul>\n\n<p>Lisez la liste compl\u00e8te des changements dans le <a href=\"https:\/\/developer.wordpress.org\/news\/2023\/08\/whats-new-for-developers-august-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">tour d&rsquo;horizon des d\u00e9veloppeurs WordPress<\/a> pour ao\u00fbt 2023.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wordpress-volunteers-struggle-to-keep-up\"><a><\/a>Les b\u00e9n\u00e9voles de WordPress ont du mal \u00e0 suivre<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1305\" height=\"669\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers.png\" alt=\"Des milliers de b&#xE9;n&#xE9;voles aident l'&#xE9;quipe de Make WordPress.\" class=\"wp-image-46745\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers.png 1305w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-300x154.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-1024x525.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-768x394.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-36x18.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-volunteers-48x25.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>En tant que programme libre et gratuit, WordPress s&rsquo;appuie sur le travail de milliers de passionn\u00e9s talentueux pour rester op\u00e9rationnel.<\/p>\n\n<p>L&rsquo;\u00e9quipe de Make WordPress compte des dizaines de branches, des d\u00e9veloppeurs du noyau aux concepteurs, organisateurs de communaut\u00e9s, sp\u00e9cialistes du marketing et testeurs.<\/p>\n\n<p>Malheureusement, alors que de nombreuses personnes travaillent ensemble pour assurer la prosp\u00e9rit\u00e9 de WordPress, certaines \u00e9quipes ont d\u00e9sesp\u00e9r\u00e9ment besoin de plus de volontaires alors que <a href=\"https:\/\/w3techs.com\/technologies\/details\/cm-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress prend peu \u00e0 peu le contr\u00f4le de l&rsquo;internet.<\/a><\/p>\n\n<p>L&rsquo;une d&rsquo;entre elles est l \u00ab \u00e9quipe charg\u00e9e de l \u00bb \u00e9valuation des plugins, qui, malgr\u00e9 tous ses efforts, a un <a href=\"https:\/\/make.wordpress.org\/updates\/2023\/08\/21\/plugin-review-team-21-august-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">arri\u00e9r\u00e9 de plus de 1 900 plugins<\/a>.<\/p>\n\n<p>L&rsquo;\u00e9quipe s&rsquo;est r\u00e9cemment enrichie de six nouveaux membres et esp\u00e8re am\u00e9liorer la situation apr\u00e8s avoir re\u00e7u plus de 20 candidatures. Si vous souhaitez apporter votre contribution, vous pouvez <a href=\"https:\/\/make.wordpress.org\/plugins\/handbook\/apply\/\" target=\"_blank\" rel=\"noreferrer noopener\">demander \u00e0 rejoindre l&rsquo;\u00e9quipe charg\u00e9e de l&rsquo;\u00e9valuation des plugins<\/a> et contribuer \u00e0 r\u00e9duire le nombre de dossiers en attente. <\/p>\n\n<p>Un autre domaine dans lequel les b\u00e9n\u00e9voles de WordPress ont besoin d&rsquo;aide est le maintien des normes de codage de WordPress. Malgr\u00e9 l&rsquo;importance de les maintenir \u00e0 jour, les normes de codage de WordPress sont maintenues par une petite poign\u00e9e de b\u00e9n\u00e9voles. <\/p>\n\n<p>Bien que <a href=\"https:\/\/make.wordpress.org\/core\/2023\/08\/21\/wordpresscs-3-0-0-is-now-available\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPressCS 3.0.0<\/a> ait \u00e9t\u00e9 publi\u00e9 avec succ\u00e8s en ao\u00fbt, la situation pourrait \u00eatre plus durable. En outre, la maintenance future sera interrompue sans financement de la part des entreprises et des agences utilisatrices de WordPressCS. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wordpress-com-offers-100-year-domain\"><a><\/a>WordPress.com propose un domaine de 100 ans<\/h2>\n\n<p>WordPress.com a r\u00e9cemment d\u00e9voil\u00e9 son <a href=\"https:\/\/wordpress.com\/blog\/2023\/08\/25\/introducing-the-100-year-plan\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab\u00a0100-Year Plan\u00a0\u00bb<\/a>, qui pr\u00e9voit l&rsquo;<a href=\"https:\/\/www.bluehost.com\/domains\">enregistrement d&rsquo;un domaine<\/a> pour une dur\u00e9e d&rsquo;un si\u00e8cle moyennant une redevance unique. Il a \u00e9galement mis en place des protocoles de propri\u00e9t\u00e9 sp\u00e9ciaux si vous souhaitez transf\u00e9rer le domaine \u00e0 quelqu&rsquo;un d&rsquo;autre, comme un enfant. <\/p>\n\n<p>Ce n&rsquo;est pas la premi\u00e8re fois qu&rsquo;un enregistrement de domaine \u00e0 dur\u00e9e ind\u00e9termin\u00e9e ou \u00e0 vie est propos\u00e9, mais ce n&rsquo;est certainement pas une option standard.<\/p>\n\n<p>Bien entendu, cela soul\u00e8ve des questions int\u00e9ressantes sur ce qu&rsquo;il adviendrait de votre domaine si WordPress.com \u00e9tait dissous ou rachet\u00e9 au cours du si\u00e8cle prochain.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-10-worldwide-wordcamp-events-coming-up\"><a><\/a>10 \u00e9v\u00e9nements WordCamp mondiaux \u00e0 venir<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US.png\" alt=\"WordPress WordCamp US a r&#xE9;uni des passionn&#xE9;s de WordPress.\" class=\"wp-image-46746\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US.png 1920w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-1024x576.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-768x432.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-1536x864.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-36x20.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/WordPress-WordCamp-US-48x27.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Le mois d&rsquo;ao\u00fbt a \u00e9t\u00e9 une p\u00e9riode passionnante pour les passionn\u00e9s de WordPress, avec la tenue du <a href=\"https:\/\/bluehost.com\/fr\/blog\/quest-ce-que-wordcamp-et-pourquoi-est-ce-important-pour-la-communaute-wordpress\/\">WordCamp<\/a> US et du WordCamp Community Summit.<\/p>\n\n<p>En septembre, dix autres WordCamp auront lieu dans le monde entier, notamment au N\u00e9pal, en Malaisie, en Finlande, en Espagne, au Canada et \u00e0 New York.<\/p>\n\n<p>Consultez le <a href=\"https:\/\/central.wordcamp.org\/schedule\/\" target=\"_blank\" rel=\"noreferrer noopener\">calendrier des WordCamp<\/a> et voyez s&rsquo;il y en a un dans votre coin de pays.<\/p>\n\n<p>Si vous souhaitez vous impliquer davantage dans un \u00e9v\u00e9nement, WordCamp Asia a lanc\u00e9 un <a href=\"https:\/\/asia.wordcamp.org\/2024\/call-for-speakers\/\" target=\"_blank\" rel=\"noreferrer noopener\">appel \u00e0 orateurs<\/a>. Vous avez jusqu&rsquo;au 30 septembre 2023 pour postuler. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-stay-up-to-date\"><a><\/a>Rester inform\u00e9<\/h2>\n\n<p>Suivez Bluehost pour conna\u00eetre les <a href=\"https:\/\/bluehost.com\/fr\/blog\/category\/nouvelles\/\">derni\u00e8res nouvelles de la communaut\u00e9 WordPress<\/a>.<\/p>\n\n<p>Si vous cherchez un h\u00e9bergeur WordPress abordable, fiable et puissant, consultez les <a href=\"https:\/\/www.bluehost.com\/wordpress\/wordpress-hosting\">plans d&rsquo;h\u00e9bergement WordPress<\/a> de Bluehost.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tant attendue WordPress 6.3 est enfin disponible, ce qui est une excellente nouvelle pour les fans de WordPress. Mais ce n&rsquo;est pas tout ce que le mois d&rsquo;ao\u00fbt nous a apport\u00e9. Gutenberg 16.5 est \u00e9galement sorti, ainsi que la feuille de route officielle de la prochaine version majeure de WordPress. Cependant, les nouvelles ne [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":213954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Ao\u00fbt 2023 Mises \u00e0 jour WordPress | Bluehost","_yoast_wpseo_metadesc":"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.","inline_featured_image":false,"footnotes":""},"categories":[3165,2028],"tags":[3507,3508,3530,3520],"ppma_author":[599],"class_list":["post-213952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mis-a-jour-des-produits","category-nouvelles","tag-cms","tag-comparaison","tag-conseils-et-astuces","tag-guides-pratiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ao\u00fbt 2023 Mises \u00e0 jour WordPress | Bluehost<\/title>\n<meta name=\"description\" content=\"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213952\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordPress News Roundup - 6.3 Full Release + 7 More Updates | August 2023\" \/>\n<meta property=\"og:description\" content=\"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-02T14:47:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T10:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Minal Agarwal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/minalagarwal\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Minal Agarwal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\"},\"author\":{\"name\":\"Minal Agarwal\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\"},\"headline\":\"WordPress News Roundup &#8211; 6.3 Full Release + 7 More Updates | August 2023\",\"datePublished\":\"2023-09-02T14:47:38+00:00\",\"dateModified\":\"2025-06-02T10:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\"},\"wordCount\":1813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png\",\"keywords\":[\"CMS\",\"Comparaison\",\"Conseils et astuces\",\"Guides pratiques\"],\"articleSection\":[\"Mis \u00e0 jour des produits\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\",\"name\":\"Ao\u00fbt 2023 Mises \u00e0 jour WordPress | Bluehost\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png\",\"datePublished\":\"2023-09-02T14:47:38+00:00\",\"dateModified\":\"2025-06-02T10:06:49+00:00\",\"description\":\"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png\",\"width\":1536,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/bluehost.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\/\/www.bluehost.com\/blog\/fr\/category\/nouvelles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WordPress News Roundup &#8211; 6.3 Full Release + 7 More Updates | August 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\",\"name\":\"Minal Agarwal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"caption\":\"Minal Agarwal\"},\"description\":\"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal\"],\"knowsAbout\":[\"WordPress\"],\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/author\/minal-agarwal\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ao\u00fbt 2023 Mises \u00e0 jour WordPress | Bluehost","description":"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213952\/","og_locale":"fr_FR","og_type":"article","og_title":"WordPress News Roundup - 6.3 Full Release + 7 More Updates | August 2023","og_description":"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.","og_url":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2023-09-02T14:47:38+00:00","article_modified_time":"2025-06-02T10:06:49+00:00","og_image":[{"width":1536,"height":864,"url":"https:\/\/bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png","type":"image\/png"}],"author":"Minal Agarwal","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/minalagarwal","twitter_site":"@bluehost","twitter_misc":{"\u00c9crit par":"Minal Agarwal","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/"},"author":{"name":"Minal Agarwal","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3"},"headline":"WordPress News Roundup &#8211; 6.3 Full Release + 7 More Updates | August 2023","datePublished":"2023-09-02T14:47:38+00:00","dateModified":"2025-06-02T10:06:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/"},"wordCount":1813,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png","keywords":["CMS","Comparaison","Conseils et astuces","Guides pratiques"],"articleSection":["Mis \u00e0 jour des produits","Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/","url":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/","name":"Ao\u00fbt 2023 Mises \u00e0 jour WordPress | Bluehost","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png","datePublished":"2023-09-02T14:47:38+00:00","dateModified":"2025-06-02T10:06:49+00:00","description":"Rattrapez toutes les derni\u00e8res nouvelles et mises \u00e0 jour les plus excitantes du monde WordPress en ao\u00fbt 2023, de WordPress 6.3 \u00e0 Gutenberg 16.5 en passant par les \u00e9v\u00e9nements.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/09\/August-2023-WordPress-Updates.png","width":1536,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/fr\/wordpress-news-roundup-6-3-full-release-7-more-updates-august-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/bluehost.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/www.bluehost.com\/blog\/fr\/category\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"WordPress News Roundup &#8211; 6.3 Full Release + 7 More Updates | August 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#website","url":"https:\/\/www.bluehost.com\/blog\/fr\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3","name":"Minal Agarwal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478","url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","caption":"Minal Agarwal"},"description":"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal"],"knowsAbout":["WordPress"],"url":"https:\/\/www.bluehost.com\/blog\/fr\/author\/minal-agarwal\/"}]}},"authors":[{"term_id":599,"user_id":74,"is_guest":0,"slug":"minal-agarwal","display_name":"Minal Agarwal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=213952"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/media\/213954"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=213952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=213952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=213952"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/ppma_author?post=213952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}