{"id":213980,"date":"2023-09-01T10:40:00","date_gmt":"2023-09-01T10:40:00","guid":{"rendered":"https:\/\/www.bluehost.com\/blog\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/"},"modified":"2025-06-02T10:07:09","modified_gmt":"2025-06-02T10:07:09","slug":"utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial","status":"publish","type":"post","link":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/","title":{"rendered":"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial"},"content":{"rendered":"\n<p>L \u00ab <a href=\"https:\/\/wordpress.org\/gutenberg\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9diteur de blocs<\/a> <a href=\"https:\/\/wordpress.org\/gutenberg\/\">Gutenberg <\/a>, l \u00bb \u00e9diteur de contenu de WordPress, compte plus de <a href=\"https:\/\/gutenstats.blog\/\" target=\"_blank\" rel=\"noreferrer noopener\">81 millions d&rsquo;installations actives<\/a>. En raison de la nature dominante du march\u00e9 de WordPress et de la nature intuitive de la conception de cet \u00e9diteur, il n&rsquo;est pas surprenant que ce syst\u00e8me soit si populaire. <\/p>\n\n<p>Gutenberg est un constructeur de pages et un \u00e9diteur de contenu accessible par glisser-d\u00e9poser. Il offre de nombreuses fonctionnalit\u00e9s, ainsi que des approches vari\u00e9es que vous pouvez utiliser pour cr\u00e9er le site web curat\u00e9 de vos r\u00eaves. <\/p>\n\n<p>Cet \u00e9diteur est construit sur <a href=\"https:\/\/wordpress.com\/support\/wordpress-editor\/blocks\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>blocs Gutenberg<\/strong><\/a>les diverses unit\u00e9s de contenu qui composent les pages et la mise en page d&rsquo;un site web.<\/p>\n\n<p>Vous pouvez obtenir ces blocs \u00e0 partir de la <a href=\"https:\/\/developer.wordpress.org\/block-editor\/reference-guides\/packages\/packages-block-library\/\" target=\"_blank\" rel=\"noreferrer noopener\">biblioth\u00e8que de blocs de WordPress<\/a>. Cette biblioth\u00e8que est tr\u00e8s compl\u00e8te, mais elle ne contient pas <em>toujours<\/em> le bloc exact dont vous avez besoin pour votre site web. <\/p>\n\n<p>Ainsi, si vous \u00eates un entrepreneur qui souhaite des fonctionnalit\u00e9s avanc\u00e9es pour son site web ou des \u00e9l\u00e9ments sp\u00e9cialis\u00e9s qui ne sont pas encore propos\u00e9s par Gutenberg, vous pourriez \u00eatre int\u00e9ress\u00e9 par l&rsquo;utilisation de blocs personnalis\u00e9s Gutenberg sur votre site web WordPress.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-gutenberg-wordpress-core-content-editor\">Gutenberg : L&rsquo;\u00e9diteur de contenu de base de WordPress<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"1094\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor.png\" alt=\"L'&#xE9;diteur de contenu WordPress Gutenberg.\" class=\"wp-image-46218\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor.png 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-300x164.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-1024x560.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-768x420.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-1536x841.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-24x13.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-36x20.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-content-editor-48x26.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>L \u00ab \u00e9diteur Gutenberg est au c\u0153ur du cadre d \u00bb \u00e9dition de contenu de WordPress. Sa structure bas\u00e9e sur des blocs facilite la <a href=\"https:\/\/www.bluehost.com\/blog\/how-to-create-a-website-guide\/\">construction d&rsquo;un <\/a><a href=\"https:\/\/www.bluehost.com\/blog\/how-to-create-a-website-guide\/\"> site web<\/a><a href=\"https:\/\/www.bluehost.com\/blog\/how-to-create-a-website-guide\/\">WordPress<\/a> et de toutes ses pages &#8211; m\u00eame pour les d\u00e9butants complets. <\/p>\n\n<p>Avec cet \u00e9diteur, vous pouvez cr\u00e9er un contenu riche en m\u00e9dias dans WordPress en choisissant les nouveaux blocs dont vous avez besoin. Vous pouvez ensuite les dimensionner comme vous le souhaitez et ajouter les \u00e9l\u00e9ments sp\u00e9cifiques que vous voulez voir appara\u00eetre sur chaque page. <\/p>\n\n<h3 class=\"wp-block-heading\">Que sont les blocs Gutenberg ?<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"689\" height=\"575\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks.png\" alt=\"Les blocs Gutenberg sont les &#xE9;l&#xE9;ments qui composent une page ou un article.\" class=\"wp-image-46219\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks.png 689w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks-300x250.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks-24x20.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks-36x30.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-blocks-48x40.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dans Gutenberg, chaque page ou article est constitu\u00e9 d&rsquo;une collection d&rsquo;\u00e9l\u00e9ments autonomes.<\/p><\/blockquote><\/figure>\n\n<p>Vous utilisez ces \u00e9l\u00e9ments &#8211; ou blocs &#8211; pour construire des pages, des articles et tout le reste de votre site web WordPress.<\/p>\n\n<p>Le bloc <a href=\"https:\/\/gutenstats.blog\/\" target=\"_blank\" rel=\"noreferrer noopener\">le plus populaire<\/a> est le bloc de paragraphes, suivi par les blocs d&rsquo;images et d&rsquo;en-t\u00eates. Les titres, le texte, les s\u00e9parateurs, les widgets et les vid\u00e9os sont d&rsquo;autres exemples de types de blocs. <\/p>\n\n<p>Comme nous l&rsquo;avons mentionn\u00e9 pr\u00e9c\u00e9demment, vous pouvez acc\u00e9der aux blocs WP via la biblioth\u00e8que de blocs. Vous pouvez la trouver en cliquant sur le <strong>+ en <\/strong>haut \u00e0 gauche de votre barre d&rsquo;outils WordPress lorsque vous \u00e9ditez une page ou un article. <\/p>\n\n<p>Mais que faire si la biblioth\u00e8que de WordPress ne propose pas le type de bloc que vous recherchez ? Ou tout autre bloc que vous pourriez am\u00e9liorer pour l&rsquo;adapter \u00e0 vos besoins ? <\/p>\n\n<p>C&rsquo;est l\u00e0 qu&rsquo;interviennent les blocs personnalis\u00e9s.<\/p>\n\n<h3 class=\"wp-block-heading\"><a><\/a>Que sont les blocs personnalis\u00e9s de Gutenberg ?<\/h3>\n\n<p>Gutenberg permet \u00e0 quiconque de cr\u00e9er des ressources gratuites. Ainsi, si vous avez de l&rsquo;exp\u00e9rience en codage et en d\u00e9veloppement web, vous pouvez construire des blocs <em>personnalis\u00e9s<\/em> lors de la cr\u00e9ation de votre site web. <\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les blocs personnalis\u00e9s offrent encore plus de flexibilit\u00e9 et de fonctionnalit\u00e9s sp\u00e9cifiques que les blocs par d\u00e9faut.<\/p><\/blockquote><\/figure>\n\n<p>Les utilisateurs construisent des blocs personnalis\u00e9s pour cr\u00e9er des \u00e9l\u00e9ments de page uniques.<\/p>\n\n<p>Les blocs personnalis\u00e9s de Gutenberg offrent de nombreux avantages, notamment :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vous pouvez concevoir des \u00e9l\u00e9ments WordPress visuellement attrayants, riches en m\u00e9dias et adapt\u00e9s aux besoins de <em>votre<\/em> entreprise.<\/li>\n\n\n\n<li>Ils ajoutent des fonctionnalit\u00e9s uniques et avanc\u00e9es \u00e0 votre site web.<\/li>\n\n\n\n<li>Ils am\u00e9liorent l&rsquo;aspect esth\u00e9tique de vos pages et aident votre entreprise \u00e0 se d\u00e9marquer.<\/li>\n\n\n\n<li>Vous ne devez coder les blocs qu&rsquo;une seule fois. Ensuite, vous pouvez les utiliser sur l&rsquo;ensemble de vos sites web et pages. <\/li>\n<\/ul>\n\n<p>Cependant, les blocs personnalis\u00e9s posent certains probl\u00e8mes. Tout d&rsquo;abord, leur cr\u00e9ation n\u00e9cessite des connaissances techniques approfondies. D&rsquo;autre part, vous aurez besoin d&rsquo;une expertise sp\u00e9cifique en mati\u00e8re de codage et d&rsquo;outils de d\u00e9veloppement.  <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Comment obtenir des blocs Gutenberg personnalis\u00e9s pour WordPress ?<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks.png\" alt=\"Comment obtenir des blocs Gutenberg personnalis&#xE9;s pour WordPress.\" class=\"wp-image-46220\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks.png 1920w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-1024x576.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-768x432.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-1536x864.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-36x20.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Custom-gutenberg-blocks-48x27.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<p>Pour obtenir des blocs personnalis\u00e9s Gutenberg, vous devez soit les construire vous-m\u00eame, soit les acheter.<\/p>\n\n<p>La cr\u00e9ation de blocs personnalis\u00e9s n&rsquo;est pas \u00e0 la port\u00e9e de tout le monde, mais ce n&rsquo;est pas un probl\u00e8me. Vous pouvez acheter des blocs Gutenberg personnalis\u00e9s au lieu de les construire vous-m\u00eame. Pour ce faire, trouvez un <a href=\"https:\/\/www.bluehost.com\/about\">d\u00e9veloppeur de premier ordre<\/a> en qui vous avez confiance, puis travaillez avec lui pour cr\u00e9er vos blocs id\u00e9aux.  <\/p>\n\n<p>Si vous avez l&rsquo;intention de cr\u00e9er ces blocs vous-m\u00eame, vous devez tenir compte de certains \u00e9l\u00e9ments avant de commencer.<\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Ce qu&rsquo;il faut prendre en compte avant de cr\u00e9er des blocs personnalis\u00e9s<\/h2>\n\n<p>La cr\u00e9ation d&rsquo;un bloc personnalis\u00e9 Gutenberg prend du temps et de l&rsquo;\u00e9nergie. Avant de commencer le processus, vous devez vous assurer d&rsquo;avoir \u00e9puis\u00e9 toutes vos autres options. <\/p>\n\n<p>Vous pouvez v\u00e9rifier qu&rsquo;il n&rsquo;existe pas d&rsquo;autres approches appropri\u00e9es en examinant attentivement la biblioth\u00e8que des blocs par d\u00e9faut de Gutenberg. Assurez-vous qu&rsquo;il n&rsquo;y a pas de blocs existants qui fournissent les fonctions de base ou les sp\u00e9cifications de style dont vous avez besoin. <\/p>\n\n<p>Et si vous avez d\u00e9termin\u00e9 que vous <em>avez<\/em> besoin d&rsquo;un bloc personnalis\u00e9, d\u00e9finissez les sp\u00e9cifications essentielles de votre bloc<em> avant de <\/em>commencer la construction. Pensez aux \u00e9l\u00e9ments esth\u00e9tiques, aux param\u00e8tres par d\u00e9faut et aux fonctionnalit\u00e9s de base. Pensez \u00e9galement aux sp\u00e9cifications de la barre d&rsquo;outils et \u00e0 d&rsquo;autres caract\u00e9ristiques stylistiques et fonctionnelles essentielles.  <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Ce dont vous avez besoin pour construire des blocs personnalis\u00e9s Gutenberg<\/h2>\n\n<p>Une fois que vous avez d\u00e9termin\u00e9 les aspects les plus essentiels de votre bloc, vous devez satisfaire \u00e0 quelques autres exigences cl\u00e9s avant d&rsquo;entamer le processus.<\/p>\n\n<p>Un site web WordPress actif est essentiel. Vous devrez \u00e9galement avoir au moins une certaine exp\u00e9rience de JavaScript et des outils de construction JavaScript, tels que <a href=\"https:\/\/nodejs.org\/en\" target=\"_blank\" rel=\"noreferrer noopener\">Node.js<\/a>. <\/p>\n\n<p>Vous aurez \u00e9galement besoin de connaissances interm\u00e9diaires en HTML, CSS et PHP pour cr\u00e9er vos propres blocs personnalis\u00e9s.<\/p>\n\n<p>Si vous n \u00ab \u00eates pas tr\u00e8s exp\u00e9riment\u00e9 dans ce domaine, ne vous inqui\u00e9tez pas. Vous pouvez gagner du temps et de l \u00bb \u00e9nergie en faisant appel \u00e0 des <a href=\"https:\/\/www.bluehost.com\/solutions\/full-service\">experts en conception de sites web<\/a> pour vous aider \u00e0 construire des blocs. <\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Comment cr\u00e9er des blocs Gutenberg personnalis\u00e9s dans WordPress ?<\/h2>\n\n<p>Il existe deux approches accessibles pour construire des blocs personnalis\u00e9s Gutenberg. Vous pouvez soit installer un plugin convivial qui simplifie le processus, soit les construire \u00e0 partir de z\u00e9ro en utilisant du code HTML\/CSS ou PHP. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-1024x576.png\" alt=\"Comment cr&#xE9;er des blocs Gutenberg personnalis&#xE9;s dans WordPress ?\" class=\"wp-image-46221\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-1024x576.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-300x169.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-768x432.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-24x14.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-36x20.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-gutenberg-blocks-48x27.png 48w\" sizes=\"100vw\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\">Cr\u00e9er des blocs personnalis\u00e9s avec un plugin<\/h3>\n\n<p>Il existe un certain nombre de <a href=\"https:\/\/wordpress.org\/plugins\/genesis-custom-blocks\/\" target=\"_blank\" rel=\"noreferrer noopener\">plugins WordPress<\/a> de construction de blocs qui rationalisent le processus de cr\u00e9ation de blocs personnalis\u00e9s Gutenberg pour votre site WordPress. Nous recommandons d&rsquo;utiliser <a href=\"https:\/\/wordpress.org\/plugins\/genesis-custom-blocks\/\" target=\"_blank\" rel=\"noreferrer noopener\">Genesis Custom Blocks<\/a>. <\/p>\n\n<p>Pour cr\u00e9er votre premier bloc avec ce plugin :<\/p>\n\n<p><strong>1. Installer les blocs personnalis\u00e9s de Genesis<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"988\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks.png\" alt=\"Installez le plugin WordPress Genesis Custom Blocks.\" class=\"wp-image-46222\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks.png 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-300x148.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-1024x506.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-768x380.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-1536x759.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-36x18.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Genesis-custom-blocks-48x24.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Tout d&rsquo;abord, naviguez vers <strong>Plugins &gt; Add New <\/strong>dans la barre lat\u00e9rale gauche de votre tableau de bord d&rsquo;administration et recherchez Genesis dans le <a href=\"https:\/\/wordpress.org\/plugins\/\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9pertoire des plugins WordPress<\/a>. Installez-le et cliquez sur le bouton <strong>Activer <\/strong>. <\/p>\n\n<p><strong>2. Cr\u00e9er un nouveau bloc<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"646\" height=\"312\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block.png\" alt=\"Allez dans Blocs personnalis&#xE9;s &amp;gt; Ajouter un nouveau bloc dans votre tableau de bord WordPress.\" class=\"wp-image-46223\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block.png 646w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block-300x145.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block-36x17.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-new-block-48x23.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Ensuite, naviguez vers <strong>Custom Blocks (blocs personnalis\u00e9s) &gt; Add New (ajouter un nouveau <\/strong>bloc) pour cr\u00e9er un bloc.<\/p>\n\n<p><strong>3. Configurer les sp\u00e9cificit\u00e9s du bloc<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"995\" height=\"467\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring.jpg\" alt=\"Configuration du bloc.\" class=\"wp-image-46224\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring.jpg 995w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring-300x141.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring-768x360.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring-24x11.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring-36x17.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Block-configuring-48x23.jpg 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Vous pouvez maintenant s\u00e9lectionner un nom de bloc, puis configurer et personnaliser ses propri\u00e9t\u00e9s. <a href=\"https:\/\/www.bluehost.com\/blog\/website-seo-basics-how-to-optimize-your-content\/\">Pour faciliter l&rsquo;optimisation des moteurs de recherche<\/a> (SEO), ajoutez des <a href=\"https:\/\/www.bluehost.com\/blog\/find-best-keywords-get-found\/\">mots-cl\u00e9s pertinents<\/a>.<\/p>\n\n<p>Ajoutez ensuite des champs &#8211; tels que des nombres, des images et des cases \u00e0 cocher &#8211; en appuyant sur le <strong> bouton +. <\/strong>Vous devrez saisir d&rsquo;autres sp\u00e9cifications, telles que <strong>l \u00ab \u00e9tiquette du champ<\/strong>, l \u00bb<strong>emplacement du champ<\/strong> et le <strong>texte d&rsquo;aide<\/strong>. Vous pouvez \u00e9galement r\u00e9organiser, modifier et supprimer des champs.  <\/p>\n\n<p><strong>4. Cr\u00e9ez votre mod\u00e8le.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1076\" height=\"470\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Template-building.jpg\" alt=\"Construire un mod&#xE8;le.\" class=\"wp-image-46225\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building.jpg 1076w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-300x131.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-1024x447.jpg 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-768x335.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-24x10.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-36x16.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Template-building-48x21.jpg 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Ensuite, vous pouvez construire votre mod\u00e8le avec HTML et CSS ou PHP, en fonction de votre bloc de sortie.<\/p>\n\n<p>Si votre bloc est configur\u00e9 pour HTML et CSS, vous pouvez utiliser l&rsquo;<strong>\u00e9diteur de mod\u00e8le<\/strong> du plugin, qui se trouve dans la barre sup\u00e9rieure. Vous pouvez y personnaliser votre bloc via les onglets <strong>Markup (<\/strong>HTML) et <strong>CSS <\/strong>. <\/p>\n\n<p>Et si vous souhaitez ajouter du PHP, vous devrez utiliser un \u00e9diteur de texte simple pour cr\u00e9er manuellement les fichiers <strong>block<\/strong><strong>.php<\/strong> et <strong>block.css<\/strong>.<\/p>\n\n<p><strong>5. Sauvegardez et confirmez votre bloc<\/strong><\/p>\n\n<p>Veillez \u00e0 enregistrer votre bloc en cliquant sur <strong>Publier<\/strong> en haut \u00e0 droite.<\/p>\n\n<p><strong>6. Ajoutez votre bloc \u00e0 votre site web<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1404\" height=\"592\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page.jpg\" alt=\"Ajout du bloc &#xE0; une page.\" class=\"wp-image-46226\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page.jpg 1404w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-300x126.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-1024x432.jpg 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-768x324.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-24x10.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-36x15.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Add-block-page-48x20.jpg 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Enfin, vous pouvez ajouter le bloc \u00e0 votre site web. Ouvrez ou cr\u00e9ez un article ou une page, puis appuyez sur le <strong>+ dans la <\/strong>barre lat\u00e9rale gauche de votre tableau de bord pour trouver et int\u00e9grer votre bloc. <\/p>\n\n<p>Ensuite, personnalisez le contenu de la page \u00e0 votre guise avec d&rsquo;autres blocs, des<a href=\"https:\/\/www.bluehost.com\/blog\/what-is-wordpress-shortcode\/\">shortcodes<\/a> <a href=\"https:\/\/www.bluehost.com\/blog\/what-is-wordpress-shortcode\/\">WordPress<\/a><a href=\"https:\/\/www.bluehost.com\/blog\/what-is-wordpress-shortcode\/\"> <\/a> utiles et d&rsquo;autres approches accessibles qui <a href=\"https:\/\/www.bluehost.com\/blog\/ux-matters-how-to-create-a-dynamic-user-experience-faqs\/\">optimisent l&rsquo;exp\u00e9rience utilisateur<\/a> (UX) et les <a href=\"https:\/\/www.bluehost.com\/blog\/10-wordpress-setting-changes-to-optimize-your-sites-performance\/\">performances du site web<\/a>.<\/p>\n\n<h3 class=\"wp-block-heading\"><a><\/a>Cr\u00e9ation manuelle de blocs personnalis\u00e9s<\/h3>\n\n<p>Vous pouvez \u00e9galement coder des blocs personnalis\u00e9s Gutenberg \u00e0 partir de z\u00e9ro en suivant ce processus \u00e9tape par \u00e9tape :<\/p>\n\n<p><strong>1. Configurer l&rsquo;environnement de d\u00e9veloppement de WordPress<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1999\" height=\"1030\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment.png\" alt=\"Vous devrez inclure Node.js dans votre environnement de d&#xE9;veloppement WordPress.\" class=\"wp-image-46227\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment.png 1999w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-300x155.png 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-1024x528.png 1024w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-768x396.png 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-1536x791.png 1536w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-24x12.png 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-36x19.png 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Wordpress-developer-environment-48x25.png 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Avant tout, installez <a href=\"https:\/\/nodejs.org\/en\/download\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Node.js<\/strong><\/a> et le <a href=\"https:\/\/www.npmjs.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">gestionnaire de paquets Node<\/a> (npm). Il s&rsquo;agit d&rsquo;outils de construction JavaScript qui vous permettent de d\u00e9finir des fonctions de bloc de base. Vous pouvez t\u00e9l\u00e9charger <strong>Node.js<\/strong> via le programme d&rsquo;installation en ligne, puis vous assurer que le <strong>npm<\/strong> est activ\u00e9 en entrant la commande <strong>npm-v <\/strong>dans votre \u00e9diteur de code.  <\/p>\n\n<p>Ensuite, vous devrez installer <a href=\"https:\/\/www.docker.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Docker<\/a>, une condition pr\u00e9alable \u00e0 l&rsquo;utilisation de l&rsquo;outil de d\u00e9veloppement de WordPress. Le site web de Docker propose une installation simple en un clic. <\/p>\n\n<p>Ensuite, vous <a href=\"https:\/\/developer.wordpress.org\/themes\/getting-started\/setting-up-a-development-environment\/\" target=\"_blank\" rel=\"noreferrer noopener\">configurerez votre environnement de d\u00e9veloppement<\/a> et <a href=\"https:\/\/www.bluehost.com\/help\/article\/wordpress-how-to-create-a-staging-site\">activerez votre site de mise \u00e0 l&rsquo;essai<\/a>. Vous pouvez configurer l&rsquo;environnement de d\u00e9veloppement \u00e0 l&rsquo;aide de l&rsquo;outil par d\u00e9faut de WordPress. Installez-le globalement en entrant la commande <strong>npm -g install @wordpress\/env<\/strong>.  <\/p>\n\n<p><strong>2. Configurez votre fichier de plugin de base (starter)<\/strong><\/p>\n\n<p>Avant de pouvoir cr\u00e9er votre bloc personnalis\u00e9 Gutenberg, vous devez cr\u00e9er un plugin de bloc de base pour r\u00e9f\u00e9rence. Heureusement, il existe quelques approches qui vous permettent d&rsquo;\u00e9viter de compl\u00e9ter manuellement cette \u00e9tape. <\/p>\n\n<p>Ex\u00e9cutez la commande <strong>\/wp-content\/plugins\/ <\/strong>pour naviguer dans votre r\u00e9pertoire de plugins.<\/p>\n\n<p>Vous pouvez alors ex\u00e9cuter la commande <strong>npx @wordpress\/create-block<\/strong>, qui vous permet d&rsquo;acc\u00e9der facilement \u00e0 vos fichiers PHP et JS et de les \u00e9diter.<\/p>\n\n<p>Veillez \u00e0 ajouter \u00e0 la commande le nom que vous souhaitez donner \u00e0 votre bloc de d\u00e9part. Vous pouvez utiliser quelque chose de simple, comme <strong>mon-nouveau-bloc<\/strong>, ou faire preuve de cr\u00e9ativit\u00e9. <\/p>\n\n<p>L&rsquo;autre option consiste \u00e0 installer l&rsquo;outil <a href=\"https:\/\/www.npmjs.com\/package\/create-guten-block\" target=\"_blank\" rel=\"noreferrer noopener\">create-guten-block<\/a> et \u00e0 ex\u00e9cuter la commande <strong>npx create-guten-block<\/strong> avec le nom de votre bloc de d\u00e9part.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"888\" height=\"818\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block.jpg\" alt=\"Vous pouvez utiliser l'outil create-guten-block pour cr&#xE9;er votre fichier de plugin de d&#xE9;marrage.\" class=\"wp-image-46228\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block.jpg 888w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block-300x276.jpg 300w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block-768x707.jpg 768w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block-24x22.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block-36x33.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Create-guten-block-48x44.jpg 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Ces processus cr\u00e9eront un point de d\u00e9part.<\/p>\n\n<p><strong>3. Configurer block.json<\/strong><\/p>\n\n<p>Vous devez ajouter un <a href=\"https:\/\/developer.wordpress.org\/block-editor\/reference-guides\/block-api\/block-metadata\/\" target=\"_blank\" rel=\"noreferrer noopener\">fichier block.json<\/a> \u00e0 votre nouveau r\u00e9pertoire, puis le configurer en saisissant des m\u00e9tadonn\u00e9es et des s\u00e9lections pour divers param\u00e8tres. Les exemples de param\u00e8tres incluent les attributs du bloc et d&rsquo;autres sp\u00e9cifications ajustables, comme la<strong>version<\/strong>, le <strong>titre<\/strong> et la <strong>cat\u00e9gorie de l<\/strong>&lsquo;interface de planification des applications<strong>(API)<\/strong>. <\/p>\n\n<p>Voici un exemple de ce \u00e0 quoi pourrait ressembler une partie du code block.json :<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"583\" height=\"655\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file.jpg\" alt=\"Vous devez configurer les param&#xE8;tres de votre fichier block.json, y compris la version de l'API.\" class=\"wp-image-46229\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file.jpg 583w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file-267x300.jpg 267w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file-21x24.jpg 21w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file-32x36.jpg 32w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Blockjson-file-43x48.jpg 43w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p>Le fichier <strong>block.json<\/strong> permet \u00e0 votre plugin de bloc de base d&rsquo;appara\u00eetre dans le r\u00e9pertoire des plugins, facilite l&rsquo;enregistrement de votre bloc par la suite et contribue \u00e0 la performance de votre site web.<\/p>\n\n<p><strong>4. Configurer d&rsquo;autres sp\u00e9cifications<\/strong><\/p>\n\n<p>Ensuite, vous d\u00e9terminerez et mettrez en file d&rsquo;attente les sp\u00e9cificit\u00e9s concernant :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Styles.<\/li>\n\n\n\n<li>D\u00e9pendances et fichiers d&rsquo;actifs.<\/li>\n\n\n\n<li>Attributs.<\/li>\n\n\n\n<li>Scripts.<\/li>\n\n\n\n<li>\u00c9tiquettes et mots-cl\u00e9s.<\/li>\n<\/ul>\n\n<p>Vous pouvez acc\u00e9der au <a href=\"https:\/\/docs.npmjs.com\/cli\/v7\/configuring-npm\/package-json\" target=\"_blank\" rel=\"noreferrer noopener\">fichier<strong>package.json<\/strong><\/a> pour configurer vos propri\u00e9t\u00e9s, styles et scripts JavaScript. Dans le <strong>fichier block.json<\/strong>, vous pouvez d\u00e9finir des attributs \u00e0 l&rsquo;aide de la fonction <strong>setAttributes <\/strong>. Vous pouvez \u00e9galement modifier les param\u00e8tres des blocs \u00e0 l&rsquo;aide d&rsquo;\u00e9tiquettes et de mots-cl\u00e9s.  <\/p>\n\n<p>Vous pouvez ajouter d&rsquo;autres sp\u00e9cifications frontales et dorsales et modifier diverses fonctions. Par exemple, vous devez cr\u00e9er un fichier d&rsquo;actifs pour ajouter des <a href=\"https:\/\/www.sonatype.com\/launchpad\/what-are-software-dependencies\" target=\"_blank\" rel=\"noreferrer noopener\">d\u00e9pendances<\/a>. Vous pouvez le faire en entrant la commande <strong>npm run build <\/strong>pour votre fichier JavaScript XML (JSX) ou le code PHP suivant :  <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"266\" height=\"229\" src=\"https:\/\/bluehost.com\/fr\/blog\/wp-content\/uploads\/2018\/11\/Php-code.jpg\" alt=\"Code PHP pour cr&#xE9;er un fichier de ressources pour vos d&#xE9;pendances.\" class=\"wp-image-46230\" srcset=\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Php-code.jpg 266w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Php-code-24x21.jpg 24w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Php-code-36x31.jpg 36w, https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Php-code-48x41.jpg 48w\" sizes=\"100vw\" \/><figcaption class=\"wp-element-caption\"><em>Capture d&rsquo;\u00e9cran<\/em><\/figcaption><\/figure>\n\n<p><strong>5. Enregistrez votre bloc<\/strong><\/p>\n\n<p>Une fois que vous avez cr\u00e9\u00e9 votre plugin de bloc, utilisez la fonction <strong>register_block_type<\/strong>. Cette technique d&rsquo;enregistrement des blocs extrait automatiquement les m\u00e9tadonn\u00e9es pr\u00e9c\u00e9demment d\u00e9termin\u00e9es du fichier <strong>block.json<\/strong>. <\/p>\n\n<p><strong>6. Sauvegardez et confirmez vos travaux de blocage<\/strong><\/p>\n\n<p>La derni\u00e8re \u00e9tape consiste \u00e0 enregistrer tous les fichiers et \u00e0 tester votre nouveau bloc.<\/p>\n\n<p>Vous pouvez confirmer sa fonctionnalit\u00e9 en ajoutant votre nouveau bloc personnalis\u00e9 Gutenberg \u00e0 votre site web. Si vous l&rsquo;ins\u00e9rez et qu&rsquo;il affiche le message \u00ab Hello World \u00bb, c&rsquo;est le signe que vous avez termin\u00e9 le processus correctement. <\/p>\n\n<p>Si vous souhaitez utiliser le m\u00eame bloc dans plusieurs mises en page ou sites web \u00e0 l&rsquo;avenir, essayez de l&rsquo;utiliser dans un <a href=\"https:\/\/www.bluehost.com\/blog\/what-are-gutenberg-block-patterns-in-wordpress-and-how-to-use-them\/\">mod\u00e8le de bloc Gutenberg<\/a>.<\/p>\n\n<p>Consultez la <a href=\"https:\/\/learn.wordpress.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">page \u00ab Apprendre \u00bb de WordPress<\/a> pour plus de d\u00e9tails et de <a href=\"https:\/\/learn.wordpress.org\/tutorials\/\" target=\"_blank\" rel=\"noreferrer noopener\">tutoriels<\/a> sur la mani\u00e8re de configurer votre site web.<\/p>\n\n<h2 class=\"wp-block-heading\"><a><\/a>Derni\u00e8res r\u00e9flexions : Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg &#8211; un guide Bluehost<\/h2>\n\n<p>Faire des blocs personnalis\u00e9s Gutenberg pour WordPress est une solution utile si vous avez besoin d&rsquo;\u00e9l\u00e9ments de site web qui ne sont pas propos\u00e9s par les blocs par d\u00e9faut.<\/p>\n\n<p>Vous cr\u00e9ez vos propres blocs Gutenberg \u00e0 l&rsquo;aide d&rsquo;un plugin ou par codage manuel. Cependant, l&rsquo;un ou l&rsquo;autre processus n\u00e9cessite une certaine expertise technique. <\/p>\n\n<p>Si vous ne souhaitez pas cr\u00e9er vous-m\u00eame des blocs personnalis\u00e9s, essayez les <a href=\"https:\/\/www.bluehost.com\/solutions\/website-design\">services de conception de sites Web de Bluehost<\/a>. Notre \u00e9quipe d&rsquo;experts d\u00e9vou\u00e9s est l\u00e0 pour vous aider \u00e0 personnaliser et \u00e0 cultiver le site Web parfait. <\/p>\n\n<p>Si vous souhaitez concevoir vous-m\u00eame votre site web, mais que vous avez besoin de conseils d&rsquo;experts en mati\u00e8re d&rsquo;\u00e9dition de site, nous proposons \u00e9galement la <a href=\"https:\/\/www.bluehost.com\/pro-design-live\">conception Pro avec une assistance en direct.<\/a> Nos experts peuvent vous aider \u00e0 choisir et \u00e0 personnaliser les th\u00e8mes et les plugins parfaits et \u00e0 optimiser votre site web. <\/p>\n\n<p>Ensuite, une fois que votre site web est pr\u00eat \u00e0 \u00eatre mis en ligne, <a href=\"https:\/\/www.bluehost.com\/contact\">contactez-nous chez Bluehost<\/a> pour obtenir des<a href=\"https:\/\/www.bluehost.com\/wordpress\/wordpress-hosting\"> services d&rsquo;h\u00e9bergement<\/a> <a href=\"https:\/\/www.bluehost.com\/wordpress\/wordpress-hosting\">WordPress<\/a> rapides, de haute qualit\u00e9 et tr\u00e8s performants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L \u00ab \u00e9diteur de blocs Gutenberg , l \u00bb \u00e9diteur de contenu de WordPress, compte plus de 81 millions d&rsquo;installations actives. En raison de la nature dominante du march\u00e9 de WordPress et de la nature intuitive de la conception de cet \u00e9diteur, il n&rsquo;est pas surprenant que ce syst\u00e8me soit si populaire. Gutenberg est un [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":213982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg | Guide Bluehost","_yoast_wpseo_metadesc":"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.","inline_featured_image":false,"footnotes":""},"categories":[3151,1969],"tags":[3520],"ppma_author":[599],"class_list":["post-213980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement","category-wordpress","tag-guides-pratiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg | Guide Bluehost<\/title>\n<meta name=\"description\" content=\"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213980\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluehost Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluehost\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T10:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T10:07:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Minal Agarwal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/minalagarwal\" \/>\n<meta name=\"twitter:site\" content=\"@bluehost\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Minal Agarwal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\"},\"author\":{\"name\":\"Minal Agarwal\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\"},\"headline\":\"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial\",\"datePublished\":\"2023-09-01T10:40:00+00:00\",\"dateModified\":\"2025-06-02T10:07:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\"},\"wordCount\":2544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png\",\"keywords\":[\"Guides pratiques\"],\"articleSection\":[\"D\u00e9veloppement\",\"WordPress\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\",\"name\":\"Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg | Guide Bluehost\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png\",\"datePublished\":\"2023-09-01T10:40:00+00:00\",\"dateModified\":\"2025-06-02T10:07:09+00:00\",\"description\":\"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/bluehost.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sites web\",\"item\":\"https:\/\/www.bluehost.com\/blog\/fr\/category\/sites-web\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#website\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/\",\"name\":\"Bluehost\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluehost.com\/blog\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#organization\",\"name\":\"Bluehost\",\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"contentUrl\":\"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg\",\"width\":136,\"height\":24,\"caption\":\"Bluehost\"},\"image\":{\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bluehost\/\",\"https:\/\/x.com\/bluehost\",\"https:\/\/www.linkedin.com\/company\/bluehost-com\/\",\"https:\/\/www.youtube.com\/user\/bluehost\",\"https:\/\/en.wikipedia.org\/wiki\/Bluehost\"],\"description\":\"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \\u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.\",\"telephone\":\"+1-888-401-4678\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3\",\"name\":\"Minal Agarwal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g\",\"caption\":\"Minal Agarwal\"},\"description\":\"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal\"],\"knowsAbout\":[\"WordPress\"],\"url\":\"https:\/\/www.bluehost.com\/blog\/fr\/author\/minal-agarwal\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg | Guide Bluehost","description":"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213980\/","og_locale":"fr_FR","og_type":"article","og_title":"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial","og_description":"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.","og_url":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/","og_site_name":"Bluehost Blog","article_publisher":"https:\/\/www.facebook.com\/bluehost\/","article_published_time":"2023-09-01T10:40:00+00:00","article_modified_time":"2025-06-02T10:07:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png","type":"image\/png"}],"author":"Minal Agarwal","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/minalagarwal","twitter_site":"@bluehost","twitter_misc":{"\u00c9crit par":"Minal Agarwal","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#article","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/"},"author":{"name":"Minal Agarwal","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3"},"headline":"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial","datePublished":"2023-09-01T10:40:00+00:00","dateModified":"2025-06-02T10:07:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/"},"wordCount":2544,"commentCount":0,"publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png","keywords":["Guides pratiques"],"articleSection":["D\u00e9veloppement","WordPress"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/","url":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/","name":"Comment cr\u00e9er des blocs personnalis\u00e9s Gutenberg | Guide Bluehost","isPartOf":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png","datePublished":"2023-09-01T10:40:00+00:00","dateModified":"2025-06-02T10:07:09+00:00","description":"Vous souhaitez cr\u00e9er des blocs personnalis\u00e9s Gutenberg pour votre site web WordPress ? D\u00e9couvrez diff\u00e9rentes approches pour construire et obtenir des blocs personnalis\u00e9s dans ce guide.","breadcrumb":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#primaryimage","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2018\/11\/Gutenberg-Custom-blocks.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluehost.com\/blog\/fr\/utiliser-les-blocs-personnalises-de-gutenberg-pour-la-creation-de-contenu-wordpress-un-guide-convivial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/bluehost.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sites web","item":"https:\/\/www.bluehost.com\/blog\/fr\/category\/sites-web\/"},{"@type":"ListItem","position":3,"name":"Utiliser les blocs personnalis\u00e9s de Gutenberg pour la cr\u00e9ation de contenu WordPress : Un guide convivial"}]},{"@type":"WebSite","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#website","url":"https:\/\/www.bluehost.com\/blog\/fr\/","name":"Bluehost","description":"","publisher":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluehost.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#organization","name":"Bluehost","url":"https:\/\/www.bluehost.com\/blog\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","contentUrl":"https:\/\/www.bluehost.com\/blog\/wp-content\/uploads\/2023\/08\/bluehost-logo.svg","width":136,"height":24,"caption":"Bluehost"},"image":{"@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluehost\/","https:\/\/x.com\/bluehost","https:\/\/www.linkedin.com\/company\/bluehost-com\/","https:\/\/www.youtube.com\/user\/bluehost","https:\/\/en.wikipedia.org\/wiki\/Bluehost"],"description":"Bluehost is a leading web hosting provider empowering millions of websites worldwide. \u2028Discover how Bluehost's expertise, reliability, and innovation can help you achieve your online goals.","telephone":"+1-888-401-4678"},{"@type":"Person","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/e9ccb012781e05c929d20c7b89f8bbe3","name":"Minal Agarwal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bluehost.com\/blog\/fr\/#\/schema\/person\/image\/c8d40b28171fda3585c635bc9672f478","url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","caption":"Minal Agarwal"},"description":"Minal is the Director of Brand Marketing at Bluehost. With over 15 years of business experience in the technology industry, she strives to create solutions and content that fulfill a customer's needs. She is a dog mom and a stickler for calendaring.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/minalagarwal"],"knowsAbout":["WordPress"],"url":"https:\/\/www.bluehost.com\/blog\/fr\/author\/minal-agarwal\/"}]}},"authors":[{"term_id":599,"user_id":74,"is_guest":0,"slug":"minal-agarwal","display_name":"Minal Agarwal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/042b2a6396c1ee0366c5c9560120123c4f0235ad09355e28ecc11f17cf341b97?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":"","10":"","11":"","12":"","13":"","14":"","15":""}],"_links":{"self":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=213980"}],"version-history":[{"count":0,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/213980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/media\/213982"}],"wp:attachment":[{"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=213980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=213980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=213980"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.bluehost.com\/blog\/fr\/wp-json\/wp\/v2\/ppma_author?post=213980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}